{"id":970,"date":"2023-10-16T13:47:37","date_gmt":"2023-10-16T13:47:37","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=970"},"modified":"2023-10-16T13:47:39","modified_gmt":"2023-10-16T13:47:39","slug":"apucarana-futsal-vence-o-medianeira-por-5-a-3-no-lagoao","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/10\/16\/apucarana-futsal-vence-o-medianeira-por-5-a-3-no-lagoao\/","title":{"rendered":"Apucarana Futsal vence o Medianeira por 5 a 3 no Lago\u00e3o"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O jogo, v\u00e1lido pelas quartas de final do Campeonato Paranaense de Futsal S\u00e9rie Prata, foi o primeiro de dois jogos que definem a pr\u00f3xima fase<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"529\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Apucarana-Futsal-vence-o-Medianeira-por-5-a-3-no-L-00801471-0-202310151943-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-971\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Apucarana-Futsal-vence-o-Medianeira-por-5-a-3-no-L-00801471-0-202310151943-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Apucarana-Futsal-vence-o-Medianeira-por-5-a-3-no-L-00801471-0-202310151943-ScaleDownProportional-600x356.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Apucarana-Futsal-vence-o-Medianeira-por-5-a-3-no-L-00801471-0-202310151943-ScaleDownProportional-300x178.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Apucarana-Futsal-vence-o-Medianeira-por-5-a-3-no-L-00801471-0-202310151943-ScaleDownProportional-768x456.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>O\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/apucarana-futsal?d=1\">Apucarana Futsal<\/a>\u00a0venceu o Medianeira com um placar de 5 a 3, na noite deste s\u00e1bado (14), no Gin\u00e1sio de Esportes Lago\u00e3o, em Apucarana (PR).<\/p>\n\n\n\n<p>O jogo, v\u00e1lido pelas quartas de final do Campeonato Paranaense de Futal S\u00e9rie Prata, foi o primeiro de dois jogos que definem a pr\u00f3xima fase.<\/p>\n\n\n\n<p>O t\u00e9cnico Luizinho, do Apucarana Futsal, comemorou o resultado do Apucarana em mais um jogo em casa.<\/p>\n\n\n\n<p>&#8220;Muito feliz em ver nosso time aguerrido, a entrega de todos para sair na frente nesta disputa diante da melhor equipe do campeonato. N\u00e3o sou eu quem fala, s\u00e3o os n\u00fameros. Estamos vivos, vamos honrar o Apucarana em busca da vaga na semifinal e depois pela busca do acesso. Agora \u00e9 descansar, comemorar e, a partir de segunda, nos preparar para encar\u00e1-los na casa deles, o que \u00e9 muito dif\u00edcil&#8221;, disse.<\/p>\n\n\n\n<p>Os gols foram marcados pelos jogadores Deninho, Beb\u00ea e Biruzinho. Com o resultado, a equipe de Apucarana vai para o pr\u00f3ximo jogo com a vantagem do empate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jogo, v\u00e1lido pelas quartas de final do Campeonato Paranaense de Futsal S\u00e9rie Prata, foi o primeiro de dois jogos que definem a pr\u00f3xima fase O\u00a0Apucarana Futsal\u00a0venceu o Medianeira com um placar de 5 a 3, na noite deste s\u00e1bado (14), no Gin\u00e1sio de Esportes Lago\u00e3o, em Apucarana (PR). O jogo, v\u00e1lido pelas quartas de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-970","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}