{"id":94,"date":"2023-08-22T13:04:00","date_gmt":"2023-08-22T13:04:00","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=94"},"modified":"2023-08-22T13:04:03","modified_gmt":"2023-08-22T13:04:03","slug":"mulher-e-seguida-e-roubada-apos-sair-de-supermercado-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/08\/22\/mulher-e-seguida-e-roubada-apos-sair-de-supermercado-em-apucarana\/","title":{"rendered":"Mulher \u00e9 seguida e roubada ap\u00f3s sair de supermercado em Apucarana"},"content":{"rendered":"\n<p>Dois homens encapuzados ficaram observando a v\u00edtima e, na sequ\u00eancia, a abordaram com uma arma<\/p>\n\n\n\n<p>Uma moradora de\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\">Apucarana<\/a>, no Norte do Paran\u00e1, foi alvo de criminosos ao sair de um supermercado na noite desta segunda-feira (21). De acordo com o boletim de ocorr\u00eancia da Pol\u00edcia Militar (PM), a mulher foi seguida e, na sequ\u00eancia, roubada.<\/p>\n\n\n\n<p>A ocorr\u00eancia foi registrada por volta das 19h30, em um supermercado localizado no bairro Jardim Catua\u00ed. Segundo relato da v\u00edtima, ainda dentro do estabelecimento ela percebeu que dois homens estavam pr\u00f3ximos dela de uma &#8220;maneira estranha&#8221;.<\/p>\n\n\n\n<p>A mulher foi seguida e, quando estava na Rua Nova Ucr\u00e2nia, foi abordada pela dupla, sendo que um deles estava armado. Os bandidos a surpreenderam pelas costas e anunciaram o assalto.<\/p>\n\n\n\n<p>Um aparelho celular da marca Samsung, modelo A3 de cor preta foi levado. Os homens fugiram, e a v\u00edtima n\u00e3o conseguiu repassar as caracter\u00edsticas dos suspeitos porque eles estavam com capuz. Ela foi orientada pelos PMs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"509\" height=\"339\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/A-dupla-fugiu-e-nao-foi-encontrada-00785917-0-202308220933-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-95\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/A-dupla-fugiu-e-nao-foi-encontrada-00785917-0-202308220933-ScaleDownProportional.webp 509w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/A-dupla-fugiu-e-nao-foi-encontrada-00785917-0-202308220933-ScaleDownProportional-300x200.webp 300w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dois homens encapuzados ficaram observando a v\u00edtima e, na sequ\u00eancia, a abordaram com uma arma Uma moradora de\u00a0Apucarana, no Norte do Paran\u00e1, foi alvo de criminosos ao sair de um supermercado na noite desta segunda-feira (21). De acordo com o boletim de ocorr\u00eancia da Pol\u00edcia Militar (PM), a mulher foi seguida e, na sequ\u00eancia, roubada. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-94","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/94\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=94"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}