{"id":9064,"date":"2026-04-27T00:06:18","date_gmt":"2026-04-26T21:06:18","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=9064"},"modified":"2026-04-28T00:07:05","modified_gmt":"2026-04-27T21:07:05","slug":"apucarana-conquista-19-podios-em-torneio-estadual-de-atletismo","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2026\/04\/27\/apucarana-conquista-19-podios-em-torneio-estadual-de-atletismo\/","title":{"rendered":"Apucarana conquista 19 p\u00f3dios em torneio estadual de atletismo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"405\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png\" alt=\"\" class=\"wp-image-9067\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png 720w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-300x169.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-400x225.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-700x394.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-600x338.png 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>A equipe de atletismo da Prefeitura de Apucarana foi um dos destaques do Torneio da Federa\u00e7\u00e3o de Atletismo do Paran\u00e1 (FAP) realizado neste final de semana na pista da Universidade Estadual de Londrina (UEL). Disputado nas categorias sub 16, sub 14 e Sub 12, os jovens talentos apucaranenses sob treinamento do professor de educa\u00e7\u00e3o f\u00edsica e coordenador municipal de Atletismo, Jos\u00e9 Marcelino da Silva (Grillo), conquistaram oito primeiros lugares, sete segundos lugares e quatro terceiras coloca\u00e7\u00f5es.<\/p>\n\n\n\n<p>O atleta Sub 12, Nathan Augusto Almeida Gerin, foi o principal destaque da competi\u00e7\u00e3o ao bater dois recordes paranaenses nas provas do 60 metros rasos e 600 metros rasos. O&nbsp;prefeito Rodolfo Mota salienta que a competi\u00e7\u00e3o reuniu atletas de todo o Paran\u00e1, incluindo a equipe local IPEC Londrina. Para ele, o desempenho da equipe confirma a for\u00e7a do trabalho de base no munic\u00edpio. \u201cEsses resultados nos enchem de orgulho e mostram que Apucarana est\u00e1 no caminho certo, investindo em nossos jovens, oferecendo estrutura e incentivando talentos. Ver nossos atletas subindo ao p\u00f3dio em uma competi\u00e7\u00e3o de alto n\u00edvel \u00e9 a prova de que trabalho s\u00e9rio gera conquistas. Parabenizo cada atleta, o professor Grillo e todas as fam\u00edlias que acreditam no esporte como instrumento de disciplina, cidadania e futuro\u201d, disse o prefeito.<\/p>\n\n\n\n<p>O t\u00e9cnico e coordenador municipal de Atletismo, Jos\u00e9 Marcelino da Silva, tamb\u00e9m avaliou de forma positiva os resultados conquistados pela equipe. \u201cParticipamos das categorias de base da competi\u00e7\u00e3o e, gra\u00e7as a Deus, fomos muito bem em um torneio de n\u00edvel estadual. Tivemos a presen\u00e7a de equipes de diversas cidades do Paran\u00e1, como Londrina, Maring\u00e1, Guarapuava, Foz do Igua\u00e7u, Camb\u00e9, Ibipor\u00e3, Palmas, Medianeira, Rol\u00e2ndia, Mandaguari, Campo Mour\u00e3o, Paranava\u00ed e Nova Esperan\u00e7a. Isso valoriza ainda mais o desempenho dos nossos atletas, que representaram muito bem Apucarana\u201d, observou Grillo.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Esportes, Bruno Marchi, ressaltou que os resultados confirmam a qualidade do trabalho desenvolvido com as categorias de base no munic\u00edpio. \u201cApucarana teve uma participa\u00e7\u00e3o extraordin\u00e1ria. Tivemos atletas se destacando nas corridas, nos saltos e em diferentes faixas et\u00e1rias, o que demonstra a for\u00e7a e a renova\u00e7\u00e3o do nosso atletismo. Esses resultados s\u00e3o fruto de treinamento s\u00e9rio, dedica\u00e7\u00e3o dos atletas, apoio das fam\u00edlias e do trabalho comprometido do professor Grillo. Seguiremos investindo no esporte, porque sabemos que ele transforma vidas e revela talentos para o futuro\u201d, concluiu o secret\u00e1rio.<\/p>\n\n\n\n<p><strong><u>Confira o resultado dos atletas de Apucarana<\/u><\/strong><\/p>\n\n\n\n<p><strong>1\u00b0 Lugar<\/strong><\/p>\n\n\n\n<p>\u2013 Sub16. Ana Clara Pavesi: Salto em altura.<br>\u2013 Sub16. Ana Clara Pavesi: Salto em dist\u00e2ncia.<br>\u2013 Sub16. Kethellyn Vit\u00f3ria de Lima: 2.000 metros.<br>\u2013 Sub16. Adryan Gomes: Salto em Altura.<br>\u2013 Sub14. Allana Sloboda Rodrigues: 800 metros.<br>\u2013 Sub12. Nathan Augusto Almeida Gerin: 60 metros.<br>\u2013 Sub12. Nathan Augusto Almeida Gerin: 600 metros.<br>\u2013 Sub14. Ana Clara Pavesi: Salto em dist\u00e2ncia.<\/p>\n\n\n\n<p><strong>2\u00b0 Lugar<\/strong><\/p>\n\n\n\n<p>\u2013 Sub16: Miguel Pires: Salto em dist\u00e2ncia.<br>\u2013 Sub16. Maur\u00edcio Isaac: Salto em altura.<br>\u2013 Sub12. Leonardo Gon\u00e7alves: 60 metros.<br>\u2013 Sub12. Leonardo Gon\u00e7alves: 600 metros.<br>\u2013 Sub12. Al\u00edcia Sloboda Rodrigues: 60 metros.<br>\u2013 Sub16. Kethellyn Vit\u00f3ria de Lima: 1.000 metros.<br>\u2013 Sub14. Allana Sloboda Rodrigues: 150 metros.<\/p>\n\n\n\n<p><strong>3\u00b0 Lugar<\/strong><\/p>\n\n\n\n<p>\u2013 Sub16. Pedro Henrique Rodrigues Bosso: Salto em altura.<br>\u2013 Sub12. Yan Guilherme Freitas F\u00e9lix: Salto em dist\u00e2ncia.<br>\u2013 Sub12. Francisco de Assun\u00e7\u00e3o Nedoptalski: 600 metros.<br>\u2013 Sub16. Miguel Pires: 75 metros.<\/p>\n\n\n\n<p>Tamb\u00e9m representaram a equipe de Apucarana os atletas: Vit\u00f3ria Proen\u00e7a; Jo\u00e3o Vitor Bernardo; Pedro Torres; Emilly da Silva; Isadora Bezerra; Annalu de Moraes; Lorena Chagas; Luiz Gustavo Fernandes; Jos\u00e9 Miguel Vilsinski; Gabriel Magro; Arthur Felix; Cau\u00e3 Motta; Caio dos Santos; Gabrielly Arruda; Alice Nikitiniere; Kimberly Vilas Boas; e Nathaly da Silva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe de atletismo da Prefeitura de Apucarana foi um dos destaques do Torneio da Federa\u00e7\u00e3o de Atletismo do Paran\u00e1 (FAP) realizado neste final de semana na pista da Universidade Estadual de Londrina (UEL). Disputado nas categorias sub 16, sub 14 e Sub 12, os jovens talentos apucaranenses sob treinamento do professor de educa\u00e7\u00e3o f\u00edsica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-300x169.png",300,169,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-400x405.png",400,405,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-400x225.png",400,225,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-700x405.png",700,405,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-700x405.png",700,405,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-700x394.png",700,394,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54.png",720,405,false],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-600x338.png",600,338,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/04\/image-54-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/9064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=9064"}],"version-history":[{"count":1,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/9064\/revisions"}],"predecessor-version":[{"id":9068,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/9064\/revisions\/9068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/9067"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=9064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=9064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=9064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}