{"id":886,"date":"2023-10-09T15:15:00","date_gmt":"2023-10-09T15:15:00","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=886"},"modified":"2023-10-09T15:15:00","modified_gmt":"2023-10-09T15:15:00","slug":"trio-e-preso-com-caminhonete-furtada-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/10\/09\/trio-e-preso-com-caminhonete-furtada-em-apucarana\/","title":{"rendered":"Trio \u00e9 preso com caminhonete furtada em Apucarana"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Um dos suspeitos \u00e9 uma mulher, que ganhou R$ 200 para levar os outros dois criminosos at\u00e9 o local do crime<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"501\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/O-crime-aconteceu-no-Nucleo-Habitacional-das-Indus-00799765-0-202310091011-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-887\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/O-crime-aconteceu-no-Nucleo-Habitacional-das-Indus-00799765-0-202310091011-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/O-crime-aconteceu-no-Nucleo-Habitacional-das-Indus-00799765-0-202310091011-ScaleDownProportional-600x337.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/O-crime-aconteceu-no-Nucleo-Habitacional-das-Indus-00799765-0-202310091011-ScaleDownProportional-300x169.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/O-crime-aconteceu-no-Nucleo-Habitacional-das-Indus-00799765-0-202310091011-ScaleDownProportional-768x432.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>Tr\u00eas pessoas foram presas pela Pol\u00edcia Militar (PM) por furto qualificado de uma Caminhonete F-4000 na madrugada desta segunda-feira (9) na Rua Mangan\u00eas, no N\u00facleo Habitacional das Ind\u00fastrias, regi\u00e3o Norte, em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\">Apucarana<\/a>. O crime aconteceu na Rua Maria Neves de Souza, no mesmo bairro.<\/p>\n\n\n\n<p>Durante o patrulhamento, na Rua Mangan\u00eas, a equipe abordou um ve\u00edculo Chevrolet Vectra, que estava estacionado na rua em atitude suspeita. No carro, estava uma mulher, que explicou \u00e0 PM que o ve\u00edculo ficou sem combust\u00edvel e que seu pai teria ido at\u00e9 o Distrito de Aricanduva para comprar gasolina.<\/p>\n\n\n\n<p>No entanto, diante da demora do pai da abordada em voltar com o combust\u00edvel, a equipe tentou ligar o Vectra, que funcionou normalmente. Diante disso, a mulher contou que, na verdade, o carro havia aquecido e parado naquele local. Ela ent\u00e3o teria decidido esperar que o carro esfriasse. Nesse momento, aproximou-se uma&nbsp;<a href=\"https:\/\/tnonline.uol.com.br\/tags\/caminhonete\">Caminhonete<\/a>&nbsp;F-4000 de cor azul, ocupada por dois homens.<\/p>\n\n\n\n<p>A PM realizou a abordagem e, durante a busca pessoal, ambos informaram que haviam acabado de furtar o ve\u00edculo com uma chave micha, que se encontrava na igni\u00e7\u00e3o. Na sequ\u00eancia, uma pessoa chegou no local e informou que a caminhonete era sua e que havia sido furtada momentos antes, na Rua Maria Neves de Souza.<\/p>\n\n\n\n<p>De acordo com o boletim de ocorr\u00eancia, a motorista de Vectra estava envolvida no furto da caminhonete. A mulher informou que os criminosos haviam prometido o pagamento de R$200 para que ela os levasse do Bairro Vila Regina at\u00e9 aquele local para a pr\u00e1tica do crime. Durante a abordagem, o celular da mulher come\u00e7ou a tocar e, pela tela bloqueada, os PMs perceberam que a pessoa que estava ligando se passava pelo pai da motorista<\/p>\n\n\n\n<p>Os tr\u00eas envolvidos foram encaminhados para a delegacia. A caminhonete foi liberada pelo delegado para que a v\u00edtima a apresentasse posteriormente. O Vectra foi encaminhado ao p\u00e1tio do Detran devido a pend\u00eancias administrativas. Foram apreendidos dois telefones celulares e uma chave micha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos suspeitos \u00e9 uma mulher, que ganhou R$ 200 para levar os outros dois criminosos at\u00e9 o local do crime Tr\u00eas pessoas foram presas pela Pol\u00edcia Militar (PM) por furto qualificado de uma Caminhonete F-4000 na madrugada desta segunda-feira (9) na Rua Mangan\u00eas, no N\u00facleo Habitacional das Ind\u00fastrias, regi\u00e3o Norte, em\u00a0Apucarana. O crime aconteceu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-886","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/886\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}