{"id":8744,"date":"2026-03-23T16:52:23","date_gmt":"2026-03-23T13:52:23","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8744"},"modified":"2026-03-23T16:52:54","modified_gmt":"2026-03-23T13:52:54","slug":"articulada-por-tiao-medeiros-ponte-historica-entre-japura-e-sao-carlos-do-ivai-tem-pedra-fundamental-lancada","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2026\/03\/23\/articulada-por-tiao-medeiros-ponte-historica-entre-japura-e-sao-carlos-do-ivai-tem-pedra-fundamental-lancada\/","title":{"rendered":"Articulada por Ti\u00e3o Medeiros, ponte hist\u00f3rica entre Japur\u00e1 e S\u00e3o Carlos do Iva\u00ed tem pedra fundamental lan\u00e7ada"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"591\" height=\"1024\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-591x1024.png\" alt=\"\" class=\"wp-image-8747\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-591x1024.png 591w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-173x300.png 173w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-768x1330.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-887x1536.png 887w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-400x693.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-700x1212.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-600x1039.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10.png 924w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/><\/figure>\n\n\n\n<p>Foi lan\u00e7ada nesta quinta-feira (05), a pedra fundamental da nova ponte que ligar\u00e1 os munic\u00edpios de Japur\u00e1 e S\u00e3o Carlos do Iva\u00ed, na rodovia PR-498. A obra, considerada hist\u00f3rica para o Noroeste do Estado, contar\u00e1 com investimento de R$ 71,5 milh\u00f5es e substituir\u00e1 a travessia atualmente realizada por balsa sobre o Rio Iva\u00ed.<\/p>\n\n\n\n<p>A nova ponte ter\u00e1 360 metros de comprimento e 13,40 metros de largura, com duas faixas de rolamento de 3,60 metros cada, acostamentos de 2,50 metros, faixas de seguran\u00e7a de 0,20 metros e barreiras de concreto do tipo New Jersey nas laterais. O projeto tamb\u00e9m prev\u00ea a pavimenta\u00e7\u00e3o de trechos variantes da PR-498 nas duas margens do rio, totalizando 1,1 quil\u00f4metro de extens\u00e3o.<\/p>\n\n\n\n<p>Por se tratar de uma contrata\u00e7\u00e3o integrada, a primeira etapa da obra ser\u00e1 dedicada \u00e0 realiza\u00e7\u00e3o de estudos e \u00e0 elabora\u00e7\u00e3o da concep\u00e7\u00e3o do projeto da ponte, com prazo de 180 dias. At\u00e9 completar 360 dias de contrato, dever\u00e3o ser conclu\u00eddos o projeto b\u00e1sico e o projeto executivo de engenharia, que passar\u00e3o por an\u00e1lise do Departamento de Estradas de Rodagem do Paran\u00e1.<\/p>\n\n\n\n<p>A solenidade de lan\u00e7amento da pedra fundamental contou com a presen\u00e7a do governador do Paran\u00e1, Carlos Massa Ratinho Junior, al\u00e9m de prefeitos, lideran\u00e7as regionais, empres\u00e1rios e diversas autoridades.<\/p>\n\n\n\n<p>O deputado federal Ti\u00e3o Medeiros, que atuou na articula\u00e7\u00e3o e na defesa do projeto, destacou a import\u00e2ncia da uni\u00e3o de esfor\u00e7os para que a obra sa\u00edsse do papel.<\/p>\n\n\n\n<p>\u201cA constru\u00e7\u00e3o dessa ponte \u00e9 resultado de uma mobiliza\u00e7\u00e3o que envolveu lideran\u00e7as, empres\u00e1rios e a comunidade regional. Abra\u00e7amos essa causa porque sab\u00edamos que n\u00e3o se tratava apenas de uma obra de infraestrutura, mas de um projeto fundamental para o desenvolvimento de toda a regi\u00e3o. Hoje damos um passo hist\u00f3rico para aproximar cidades, fortalecer a economia e melhorar a vida de quem vive e trabalha aqui\u201d, afirmou.<\/p>\n\n\n\n<p>Segundo o parlamentar, a nova liga\u00e7\u00e3o sobre o Rio Iva\u00ed representa um avan\u00e7o importante para a mobilidade e para o escoamento da produ\u00e7\u00e3o regional. \u201cDurante muitos anos a travessia foi feita por balsa. Essa ponte vai trazer mais seguran\u00e7a, agilidade e novas oportunidades para o Noroeste do Paran\u00e1\u201d, completou.<\/p>\n\n\n\n<p>A obra \u00e9 considerada estrat\u00e9gica para integrar ainda mais os munic\u00edpios da regi\u00e3o, facilitando o deslocamento da popula\u00e7\u00e3o e impulsionando o desenvolvimento econ\u00f4mico local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi lan\u00e7ada nesta quinta-feira (05), a pedra fundamental da nova ponte que ligar\u00e1 os munic\u00edpios de Japur\u00e1 e S\u00e3o Carlos do Iva\u00ed, na rodovia PR-498. A obra, considerada hist\u00f3rica para o Noroeste do Estado, contar\u00e1 com investimento de R$ 71,5 milh\u00f5es e substituir\u00e1 a travessia atualmente realizada por balsa sobre o Rio Iva\u00ed. A nova [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10.png",924,1600,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-173x300.png",173,300,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-768x1330.png",768,1330,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-591x1024.png",591,1024,true],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-887x1536.png",887,1536,true],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10.png",924,1600,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-400x693.png",400,693,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-700x1212.png",700,1212,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-924x600.png",924,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-924x600.png",924,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-600x1039.png",600,1039,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/03\/image-10-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8744"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8747"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}