{"id":8473,"date":"2026-01-23T08:45:34","date_gmt":"2026-01-23T05:45:34","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8473"},"modified":"2026-01-24T08:47:17","modified_gmt":"2026-01-24T05:47:17","slug":"apucarana-entra-no-clima-de-celebracao-amor-pela-cidade-e-festa-pelos-82-anos","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2026\/01\/23\/apucarana-entra-no-clima-de-celebracao-amor-pela-cidade-e-festa-pelos-82-anos\/","title":{"rendered":"Apucarana entra no clima de celebra\u00e7\u00e3o, amor pela cidade e festa pelos 82 anos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png\" alt=\"\" class=\"wp-image-8476\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Apucarana vive um momento especial no m\u00eas em que celebra seus 82 anos. A programa\u00e7\u00e3o de anivers\u00e1rio re\u00fane an\u00fancios de obras, inaugura\u00e7\u00f5es, festejos e grandes eventos, refor\u00e7ando o sentimento de orgulho, pertencimento e amor pela cidade. O ponto alto das comemora\u00e7\u00f5es ser\u00e1 a grande festa na Pra\u00e7a Rui Barbosa, de 27 a 31 de janeiro, com seis shows nacionais gratuitos, al\u00e9m da realiza\u00e7\u00e3o da maior Prova Pedestre 28 de Janeiro de todos os tempos.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota destaca que diversas equipes est\u00e3o mobilizadas para garantir uma celebra\u00e7\u00e3o \u00e0 altura da hist\u00f3ria do munic\u00edpio. \u201cSer\u00e1 uma festa do tamanho de Apucarana, com a for\u00e7a, a f\u00e9 e o esp\u00edrito empreendedor da nossa gente. Um momento hist\u00f3rico de celebra\u00e7\u00e3o, orgulho e alegria de viver aqui. \u00c9 a festa das fam\u00edlias, desse povo acolhedor e ordeiro. Convido todas as fam\u00edlias apucaranenses para participarem desse grande evento, preparado com muito amor e carinho\u201d, afirmou.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio municipal de Cultura e Turismo, Rodrigo Lievore (Recife), a agenda de shows tem gerado grande expectativa desde o an\u00fancio. A programa\u00e7\u00e3o come\u00e7a no dia 27 de janeiro com a Noite de Cultura e Paz, reunindo o cantor gospel Ton Carfi e a dupla cat\u00f3lica Ramon &amp; Rafael. No dia 28, data do anivers\u00e1rio de Apucarana, o palco recebe a dupla sertaneja Maiara &amp; Maraisa. J\u00e1 no dia 29, ser\u00e1 a vez da banda Os Paralamas do Sucesso; no dia 30, do cantor Mumuzinho; e, no dia 31, da dupla Edson &amp; Hudson. \u201cSer\u00e3o cinco noites inesquec\u00edveis, com seis atra\u00e7\u00f5es nacionais gratuitas, que certamente v\u00e3o atrair um grande p\u00fablico\u201d, destacou.<\/p>\n\n\n\n<p>O clima de comemora\u00e7\u00e3o tamb\u00e9m envolve o esporte. O secret\u00e1rio municipal de Esportes, Bruno Marchi, lembra que Apucarana realiza neste ano a maior edi\u00e7\u00e3o da Prova Pedestre 28 de Janeiro. \u201cA tradicional corrida de rua bateu recorde hist\u00f3rico, com 5.445 inscritos. A expectativa \u00e9 enorme para o dia 31 de janeiro, quando teremos a Vinteoitinha \u00e0s 9 horas, a prova de 5 quil\u00f4metros \u00e0s 19 horas e a de 10 quil\u00f4metros \u00e0s 20h15, com largada e chegada na Pra\u00e7a Rui Barbosa\u201d, informou.<\/p>\n\n\n\n<p><strong>Palco inovador, estrutura moderna e organiza\u00e7\u00e3o do tr\u00e2nsito<\/strong><\/p>\n\n\n\n<p>Pela primeira vez, a Festa de Apucarana contar\u00e1 com o Palco Geo Space, estrutura moderna utilizada nos maiores eventos do pa\u00eds. Segundo o secret\u00e1rio de Cultura, trata-se de uma cobertura em formato de concha ac\u00fastica, que garante excelente qualidade sonora e uma est\u00e9tica imponente. As equipes finalizam a montagem do palco para, na sequ\u00eancia, iniciar a instala\u00e7\u00e3o dos sistemas de som, ilumina\u00e7\u00e3o e pain\u00e9is de LED.<\/p>\n\n\n\n<p>Em raz\u00e3o da montagem da estrutura, a Prefeitura de Apucarana informa que o tr\u00e2nsito na regi\u00e3o da Pra\u00e7a Rui Barbosa passou por altera\u00e7\u00f5es desde esta quarta-feira (22) e seguir\u00e1 modificado at\u00e9 o dia 31 de janeiro. O secret\u00e1rio municipal de Seguran\u00e7a, Transporte, Tr\u00e2nsito, Mobilidade Urbana e Defesa Civil (Segtran), major Vilson Laurentino da Silva, explica que o desvio ocorre nas proximidades da loja Casas Pernambucanas, com direcionamento do tr\u00e1fego para a Rua Rio Branco.<\/p>\n\n\n\n<p>\u201cO tr\u00e2nsito pode ficar um pouco mais lento neste trecho, mas \u00e9 uma altera\u00e7\u00e3o tempor\u00e1ria e necess\u00e1ria para garantir a seguran\u00e7a de todos. Os motoristas que desejarem realizar compras no com\u00e9rcio central podem utilizar normalmente os estacionamentos entre a Caixa Econ\u00f4mica Federal e a Casas Pernambucanas\u201d, orientou o secret\u00e1rio.<\/p>\n\n\n\n<p><strong>Gastronomia, seguran\u00e7a refor\u00e7ada e transporte ampliado<\/strong><\/p>\n\n\n\n<p>A pra\u00e7a de alimenta\u00e7\u00e3o contar\u00e1 com 28 barracas gastron\u00f4micas, reunindo empreendedores da Feira da Lua, da Super Sexta da Economia Solid\u00e1ria e da Associa\u00e7\u00e3o Cultural e Esportiva de Apucarana (ACEA). O funcionamento come\u00e7a no dia 27, a partir das 18 horas. No feriado do dia 28 e no s\u00e1bado, o atendimento ser\u00e1 antecipado para as 10 horas.<\/p>\n\n\n\n<p>O p\u00fablico encontrar\u00e1 uma pra\u00e7a de alimenta\u00e7\u00e3o completa e diversificada, com op\u00e7\u00f5es como pastel, crepe, cachorro-quente, macarr\u00e3o, sukiyaki, espetinho, pizza no cone, lanche de pernil, por\u00e7\u00f5es, batata frita, torresmo, doces, sorvetes, morango do amor e bebidas em geral.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o contar\u00e1 ainda com um forte esquema de seguran\u00e7a, envolvendo atua\u00e7\u00e3o integrada das pol\u00edcias Militar e Civil, Guarda Civil Municipal, uso de tecnologia de reconhecimento facial e, de forma in\u00e9dita, a presen\u00e7a preventiva do Conselho Tutelar durante todos os dias de festa. O \u00f3rg\u00e3o ter\u00e1 espa\u00e7o pr\u00f3prio para identifica\u00e7\u00e3o preventiva de crian\u00e7as por meio de pulseiras, ampliando a tranquilidade de pais e respons\u00e1veis.<\/p>\n\n\n\n<p>Para facilitar o deslocamento da popula\u00e7\u00e3o, a Prefeitura tamb\u00e9m anunciou a amplia\u00e7\u00e3o do hor\u00e1rio do transporte coletivo. \u201cDurante os dias de festa, os \u00f4nibus v\u00e3o operar com hor\u00e1rio extra at\u00e9 meia-noite e meia, garantindo que as pessoas possam aproveitar os shows e retornar com seguran\u00e7a para casa\u201d, informou o secret\u00e1rio da Segtran.<\/p>\n\n\n\n<p><strong>AGENDA DE SHOWS<\/strong><\/p>\n\n\n\n<p>27\/01 (ter\u00e7a-feira)<br>\u2022 Ton Carfi \u2013 21h<br>\u2022 Ramon &amp; Rafael \u2013 23h<\/p>\n\n\n\n<p>28\/01 (quarta-feira)<br>\u2022 Maiara &amp; Mara\u00edsa \u2013 22h<\/p>\n\n\n\n<p>29\/01 (quinta-feira)<br>\u2022 Paralamas do Sucesso \u2013 22h<\/p>\n\n\n\n<p>30\/01 (sexta-feira)<br>\u2022 Mumuzinho \u2013 22h<\/p>\n\n\n\n<p>31\/01 (s\u00e1bado)<br>\u2022 Edson &amp; Hudson \u2013 22h<\/p>\n\n\n\n<p><strong>63\u00aa CORRIDA PEDESTRE 28 DE JANEIRO<\/strong><\/p>\n\n\n\n<p>Local: Pra\u00e7a Rui Barbosa<br>Data: 31 de janeiro<br>Hor\u00e1rios das largadas:<br>\u2022 Prova Vinteoitinha \u2013 9h<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apucarana vive um momento especial no m\u00eas em que celebra seus 82 anos. A programa\u00e7\u00e3o de anivers\u00e1rio re\u00fane an\u00fancios de obras, inaugura\u00e7\u00f5es, festejos e grandes eventos, refor\u00e7ando o sentimento de orgulho, pertencimento e amor pela cidade. O ponto alto das comemora\u00e7\u00f5es ser\u00e1 a grande festa na Pra\u00e7a Rui Barbosa, de 27 a 31 de janeiro, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-38-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8473"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8476"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}