{"id":846,"date":"2023-10-05T15:18:37","date_gmt":"2023-10-05T15:18:37","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=846"},"modified":"2023-10-05T15:18:38","modified_gmt":"2023-10-05T15:18:38","slug":"aluno-pula-muro-de-colegio-e-gm-e-acionada-apos-suspeita-de-ataque-diretora-do-colegio-civico-militar-chegou-a-trancar-os-estudantes-nas-salas-de-aula-para-garantir-a-seguranca-deles-ate-a-chegada-das","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/10\/05\/aluno-pula-muro-de-colegio-e-gm-e-acionada-apos-suspeita-de-ataque-diretora-do-colegio-civico-militar-chegou-a-trancar-os-estudantes-nas-salas-de-aula-para-garantir-a-seguranca-deles-ate-a-chegada-das\/","title":{"rendered":"Aluno pula muro de col\u00e9gio e GM \u00e9 acionada ap\u00f3s suspeita de ataque Diretora do col\u00e9gio c\u00edvico-militar chegou a trancar os estudantes nas salas de aula para garantir a seguran\u00e7a deles at\u00e9 a chegada das autoridades"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Colegio-Estadual-Irondi-Mantovani-Pugliesi-na-Zona-00798860-0-202310050917-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-847\" style=\"width:759px;height:427px\" width=\"759\" height=\"427\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Colegio-Estadual-Irondi-Mantovani-Pugliesi-na-Zona-00798860-0-202310050917-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Colegio-Estadual-Irondi-Mantovani-Pugliesi-na-Zona-00798860-0-202310050917-ScaleDownProportional-600x337.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Colegio-Estadual-Irondi-Mantovani-Pugliesi-na-Zona-00798860-0-202310050917-ScaleDownProportional-300x169.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Colegio-Estadual-Irondi-Mantovani-Pugliesi-na-Zona-00798860-0-202310050917-ScaleDownProportional-768x432.webp 768w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/figure>\n\n\n\n<p>Equipes da Guarda Municipal (GM) de\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/arapongas?d=1\">Arapongas<\/a>, no norte do Paran\u00e1, foram mobilizadas na manh\u00e3 desta quarta-feira (4) depois que uma pessoa do sexo masculino foi vista pulando o muro dos fundos do Col\u00e9gio Estadual Irondi Mantovani Pugliesi, na Zona Sul da cidade. A institui\u00e7\u00e3o, que funciona sob uma disciplina c\u00edvico-militar, fica localizada ao lado de um Posto de Sa\u00fade 18 Horas. Servidores da sa\u00fade perceberam a invas\u00e3o, ligaram para a diretora da escola e, na sequ\u00eancia, as autoridades foram chamadas.<\/p>\n\n\n\n<p>De acordo com o boletim de ocorr\u00eancia, o caso aconteceu por volta das 11 horas, hor\u00e1rio que os estudantes ainda est\u00e3o em aula. Conforme relato, a diretora do col\u00e9gio estadual tomou todas as medidas de precau\u00e7\u00e3o para casos de\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/ataque?d=1\">ataque<\/a>, trancando os alunos em suas salas at\u00e9 a chegada dos guardas municipais e a localiza\u00e7\u00e3o do invasor. No entanto, quando as equipes chegaram, perceberam que tudo n\u00e3o passava de uma grande confus\u00e3o.<\/p>\n\n\n\n<p>Foi descoberto que o homem que invadiu a escola era, na verdade, um aluno da institui\u00e7\u00e3o. O jovem relatou que pulou o muro dos fundos pois estava atrasado, e a dire\u00e7\u00e3o n\u00e3o o permitiria entrar para estudar. Durante buscas na mochila dele, foram encontrados dois controles de videogame e uma caixinha de som. Segundo a Guarda Municipal, n\u00e3o havia material escolar na bolsa.<\/p>\n\n\n\n<p>A m\u00e3e do garoto foi chamada at\u00e9 o col\u00e9gio e, no local, teria demonstrado estar bastante abalada pela atitude cometida pelo filho. Todos foram orientados, e o jovem foi advertido quanto \u00e0 necessidade de sempre utilizar o uniforme escolar para ser identificado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipes da Guarda Municipal (GM) de\u00a0Arapongas, no norte do Paran\u00e1, foram mobilizadas na manh\u00e3 desta quarta-feira (4) depois que uma pessoa do sexo masculino foi vista pulando o muro dos fundos do Col\u00e9gio Estadual Irondi Mantovani Pugliesi, na Zona Sul da cidade. A institui\u00e7\u00e3o, que funciona sob uma disciplina c\u00edvico-militar, fica localizada ao lado de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-846","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=846"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/846\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}