{"id":8427,"date":"2026-01-20T00:59:58","date_gmt":"2026-01-19T21:59:58","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8427"},"modified":"2026-01-21T01:03:07","modified_gmt":"2026-01-20T22:03:07","slug":"festa-de-82-anos-de-apucarana-tera-forte-esquema-de-seguranca-com-reforco-policial-e-reconhecimento-facial-para-garantir-tranquilidade-a-populacao","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2026\/01\/20\/festa-de-82-anos-de-apucarana-tera-forte-esquema-de-seguranca-com-reforco-policial-e-reconhecimento-facial-para-garantir-tranquilidade-a-populacao\/","title":{"rendered":"Festa de 82 anos de Apucarana ter\u00e1 forte esquema de seguran\u00e7a, com refor\u00e7o policial e reconhecimento facial para garantir tranquilidade \u00e0 popula\u00e7\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png\" alt=\"\" class=\"wp-image-8433\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-768x576.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-400x300.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-700x525.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-600x450.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A&nbsp;Prefeitura de Apucarana&nbsp;definiu um esquema especial de seguran\u00e7a, tr\u00e2nsito e mobilidade urbana para a festa de 82 anos do munic\u00edpio, que ser\u00e1 realizada entre os dias 27 e 31 de janeiro, na&nbsp;Pra\u00e7a Rui Barbosa. As medidas incluem refor\u00e7o policial, apoio tecnol\u00f3gico e altera\u00e7\u00f5es vi\u00e1rias planejadas para garantir tranquilidade ao p\u00fablico e organiza\u00e7\u00e3o durante os dias de programa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O prefeito&nbsp;Rodolfo Mota&nbsp;destacou que a seguran\u00e7a foi tratada como prioridade m\u00e1xima na organiza\u00e7\u00e3o da festa. \u201cEstamos falando do anivers\u00e1rio da nossa cidade, de um evento pensado para as fam\u00edlias. A popula\u00e7\u00e3o de Apucarana e de toda a nossa regi\u00e3o pode vir tranquila. Organizamos um esquema de seguran\u00e7a refor\u00e7ado, com integra\u00e7\u00e3o das for\u00e7as e uso de tecnologia, para garantir um ambiente seguro para todos que vierem celebrar esse momento especial\u201d, afirmou.<\/p>\n\n\n\n<p>O encontro que definiu as a\u00e7\u00f5es reuniu membros do Conselho Municipal de Turismo, representantes da Associa\u00e7\u00e3o Comercial, Industrial e de Servi\u00e7os de Apucarana (ACIA), do Sindicato do Com\u00e9rcio Varejista (SIVANA), do 10\u00ba Batalh\u00e3o da Pol\u00edcia Militar, da Guarda Civil Municipal, da Secretaria Municipal de Cultura e Turismo e da Secretaria Municipal de Seguran\u00e7a, Transporte, Tr\u00e2nsito, Mobilidade Urbana e Defesa Civil (Segtran).<\/p>\n\n\n\n<p>A montagem das barracas gastron\u00f4micas j\u00e1 teve in\u00edcio e a estrutura do palco come\u00e7ar\u00e1 a ser instalada a partir de quinta-feira (22\/01). Em raz\u00e3o disso, haver\u00e1 altera\u00e7\u00f5es no tr\u00e2nsito. O secret\u00e1rio da Segtran, major Vilson Laurentino da Silva, explicou que a Avenida Curitiba e a Rua Os\u00f3rio Ribas de Paula ser\u00e3o interditadas nas proximidades da loja Pernambucanas. \u201cPara garantir melhor fluidez, vamos inverter o sentido da Rua Rio Branco, no trecho entre a Avenida Curitiba e a Rua Munhoz da Rocha. Tamb\u00e9m ser\u00e3o instaladas faixas informativas e agentes de tr\u00e2nsito estar\u00e3o no local para orientar os motoristas sobre rotas alternativas e poss\u00edveis lentid\u00f5es\u201d, destacou.<\/p>\n\n\n\n<p>Outra medida anunciada \u00e9 a amplia\u00e7\u00e3o do hor\u00e1rio do transporte coletivo durante os dias de festa. \u201cTeremos um hor\u00e1rio extra de \u00f4nibus, com funcionamento at\u00e9 meia-noite e meia, para que as pessoas possam aproveitar os shows e retornar com seguran\u00e7a para suas casas\u201d, informou o major Vilson, destacando que o decreto autorizando a medida ser\u00e1 assinado pelo prefeito Rodolfo Mota.<\/p>\n\n\n\n<p>Na sequ\u00eancia, o secret\u00e1rio da Segtran detalhou como o esquema de seguran\u00e7a ser\u00e1 executado. Segundo o major Vilson Laurentino da Silva, a opera\u00e7\u00e3o ser\u00e1 ampliada em rela\u00e7\u00e3o ao ano anterior. \u201cEstamos preparando uma grande opera\u00e7\u00e3o, com refor\u00e7o da Pol\u00edcia Militar, incluindo equipes da RONE e da ROTAM de Londrina e Arapongas, al\u00e9m do efetivo administrativo. Tamb\u00e9m vamos triplicar o n\u00famero de guardas municipais durante os hor\u00e1rios de shows e funcionamento das barracas\u201d, explicou.<\/p>\n\n\n\n<p>O evento contar\u00e1 ainda com apoio tecnol\u00f3gico, como o sistema de reconhecimento facial, refor\u00e7ando o monitoramento e a seguran\u00e7a do p\u00fablico durante os dias de festa.<\/p>\n\n\n\n<p>Segundo o secret\u00e1rio municipal de Cultura e Turismo, Rodrigo Li\u00e9vore (Recife), o di\u00e1logo antecipado \u00e9 fundamental para garantir uma festa bem organizada, segura e respeitosa com a popula\u00e7\u00e3o e o com\u00e9rcio local. \u201cEsse \u00e9 um momento importante, que demonstra o cuidado e o carinho com que estamos conduzindo a organiza\u00e7\u00e3o da festa de 82 anos de Apucarana. \u00c9 um evento de grande porte, que exige planejamento, di\u00e1logo e respeito, especialmente com o com\u00e9rcio da regi\u00e3o central\u201d, destacou.<\/p>\n\n\n\n<p>Ele ressaltou que a programa\u00e7\u00e3o j\u00e1 faz parte da cultura da cidade e que as interven\u00e7\u00f5es no tr\u00e2nsito s\u00e3o necess\u00e1rias para a montagem da estrutura. \u201cA festa acontece tradicionalmente na regi\u00e3o da Catedral. Para montar o palco e as barracas, algumas interven\u00e7\u00f5es ser\u00e3o inevit\u00e1veis, mas tudo est\u00e1 sendo pensado com anteced\u00eancia, em conjunto com a Segtran e ouvindo comerciantes e entidades, para minimizar impactos e garantir seguran\u00e7a\u201d, afirmou.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o art\u00edstica come\u00e7a no dia 27, quando os shows ter\u00e3o in\u00edcio \u00e0s 21h e \u00e0s 23h. De quarta a s\u00e1bado, os shows est\u00e3o previstos para come\u00e7ar \u00e0s 22h. As barracas gastron\u00f4micas funcionam, na ter\u00e7a, quinta e sexta-feira, a partir das 18h. Na quarta-feira e no s\u00e1bado, o atendimento come\u00e7a \u00e0s 10h da manh\u00e3, possibilitando que moradores e visitantes almocem na pra\u00e7a e aproveitem a festa desde cedo.<\/p>\n\n\n\n<p>A festa de 82 anos de Apucarana conta com apoio da Secretaria de Turismo do Governo do Estado do Paran\u00e1 e da Itaipu Binacional. \u201c\u00c9 um momento hist\u00f3rico, de celebra\u00e7\u00e3o e de orgulho para a nossa cidade. Convidamos todas as fam\u00edlias apucaranenses para participarem desse grande evento, preparado com muito planejamento, seguran\u00e7a e carinho\u201d, concluiu o secret\u00e1rio Rodrigo Li\u00e9vore.<\/p>\n\n\n\n<p><strong>AGENDA DE SHOWS<\/strong><\/p>\n\n\n\n<p>27\/01 (ter\u00e7a-feira)<br>\u2022 Ton Carfi \u2013 21h<br>\u2022 Ramon &amp; Rafael \u2013 23h<\/p>\n\n\n\n<p>28\/01 (quarta-feira)<br>\u2022 Maiara &amp; Mara\u00edsa \u2013 22h<\/p>\n\n\n\n<p>29\/01 (quinta-feira)<br>\u2022 Paralamas do Sucesso \u2013 22h<\/p>\n\n\n\n<p>30\/01 (sexta-feira)<br>\u2022 Mumuzinho \u2013 22h<\/p>\n\n\n\n<p>31\/01 (s\u00e1bado)<br>\u2022 Edson &amp; Hudson \u2013 22h<\/p>\n\n\n\n<p><strong>63\u00aa CORRIDA PEDESTRE 28 DE JANEIRO<\/strong><\/p>\n\n\n\n<p>Local: Pra\u00e7a Rui Barbosa<br>Data: 31 de janeiro<br>Hor\u00e1rios das largadas:<br>\u2022 Prova Vinteoitinha \u2013 9h<br>\u2022 Prova de 5 km \u2013 19h<br>\u2022 Prova de 10 km \u2013 20h15<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A&nbsp;Prefeitura de Apucarana&nbsp;definiu um esquema especial de seguran\u00e7a, tr\u00e2nsito e mobilidade urbana para a festa de 82 anos do munic\u00edpio, que ser\u00e1 realizada entre os dias 27 e 31 de janeiro, na&nbsp;Pra\u00e7a Rui Barbosa. As medidas incluem refor\u00e7o policial, apoio tecnol\u00f3gico e altera\u00e7\u00f5es vi\u00e1rias planejadas para garantir tranquilidade ao p\u00fablico e organiza\u00e7\u00e3o durante os dias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png",1024,768,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-300x225.png",300,225,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-768x576.png",768,576,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png",860,645,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png",1024,768,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28.png",1024,768,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-400x300.png",400,300,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-700x525.png",700,525,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-600x450.png",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-28-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8427"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8433"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}