{"id":8338,"date":"2026-01-05T03:59:32","date_gmt":"2026-01-05T00:59:32","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8338"},"modified":"2026-01-06T04:01:06","modified_gmt":"2026-01-06T01:01:06","slug":"restaurante-popular-retoma-atendimento-nesta-segunda-feira","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2026\/01\/05\/restaurante-popular-retoma-atendimento-nesta-segunda-feira\/","title":{"rendered":"Restaurante Popular retoma atendimento nesta segunda-feira"},"content":{"rendered":"\n\n\n<p>Depois do recesso de final de ano, o Restaurante Popular retoma as atividades nesta segunda-feira (05\/01), garantindo refei\u00e7\u00f5es acess\u00edveis e de qualidade para quem mais precisa. A reabertura marca a continuidade de um servi\u00e7o essencial para centenas de pessoas, integrando as a\u00e7\u00f5es de seguran\u00e7a alimentar colocadas em pr\u00e1tica pela Prefeitura.<\/p>\n\n\n\n<p>O Restaurante Popular funciona na Avenida Corifeu de Azevedo Marques, n\u00ba 65, entre a Prefeitura e a Pra\u00e7a do Redondo. O atendimento ocorre de segunda a sexta-feira, a partir das 11 horas, at\u00e9 o limite de 300 refei\u00e7\u00f5es por dia. O primeiro card\u00e1pio de 2026 teve arroz, feij\u00e3o, picadinho bovino ao molho, macarr\u00e3o alho \u00f3leo, salada variada e fruta.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota frisa que o Restaurante Popular recome\u00e7a reafirmando o compromisso da gest\u00e3o com a seguran\u00e7a alimentar. \u201cAo longo do ano passado, foram servidas mais de 73 mil refei\u00e7\u00f5es, oferecendo \u00e0 popula\u00e7\u00e3o refei\u00e7\u00f5es balanceadas e nutritivas por apenas R$ 2\u201d, lembrou.<\/p>\n\n\n\n<p>O Restaurante Popular \u00e9 terceirizado e administrado pela Secretaria Municipal de Assist\u00eancia Social, sendo que todo o funcionamento \u00e9 acompanhado pelo Conselho Municipal de Seguran\u00e7a Alimentar e Nutricional. \u201cO servi\u00e7o atende principalmente idosos, trabalhadores, estudantes e pessoas que buscam atendimento de sa\u00fade na cidade\u201d, explicou a secret\u00e1ria municipal da Assist\u00eancia Social, Fab\u00edola Carrero.<\/p>\n\n\n\n<p>A secret\u00e1ria afirma ainda que o Restaurante Popular integra uma rede de prote\u00e7\u00e3o social que acolhe especialmente pessoas em situa\u00e7\u00e3o de vulnerabilidade. \u201cO servi\u00e7o representa dignidade e cuidado, com card\u00e1pios equilibrados, preparados para oferecer variedade nutricional ao longo da semana\u201d, completou.<\/p>\n\n\n\n<p><strong>RETOMADA DA ROTINA \u2013<\/strong>&nbsp;A garantia de ter um local para almo\u00e7ar faz parte da rotina dos usu\u00e1rios do servi\u00e7o. Maur\u00edlio Aparecido Dearo e Carlos C\u00e9sar Fonseca, ambos aposentados, contam que frequentam a unidade todos os dias, de segunda a sexta-feira, e sentiram falta do servi\u00e7o durante o recesso.<\/p>\n\n\n\n<p>A mesma expectativa marcou os dias de Ciele Aparecida Duarte Rui, pensionista de 62 anos, moradora do Parque Bela Vista. &nbsp;\u201cEu moro sozinha \u2014 s\u00f3 eu e Deus \u2014 e \u00e9 complicado cozinhar para uma pessoa s\u00f3\u201d, disse, destacando ainda o valor acess\u00edvel das refei\u00e7\u00f5es \u201cAqui \u00e9 R$ 2. Num restaurante voc\u00ea paga R$ 30 por um prato parecido e, com esse valor, d\u00e1 para comer quase o m\u00eas inteiro aqui\u201d, frisou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois do recesso de final de ano, o Restaurante Popular retoma as atividades nesta segunda-feira (05\/01), garantindo refei\u00e7\u00f5es acess\u00edveis e de qualidade para quem mais precisa. A reabertura marca a continuidade de um servi\u00e7o essencial para centenas de pessoas, integrando as a\u00e7\u00f5es de seguran\u00e7a alimentar colocadas em pr\u00e1tica pela Prefeitura. O Restaurante Popular funciona na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2026\/01\/image-2-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8338"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8341"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}