{"id":8238,"date":"2025-12-18T01:13:17","date_gmt":"2025-12-17T22:13:17","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8238"},"modified":"2025-12-19T01:15:03","modified_gmt":"2025-12-18T22:15:03","slug":"com-mais-de-55-mil-encaminhamentos-agencia-do-trabalhador-de-apucarana-mantem-destaque-no-fechamento-de-vagas-em-2025","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/12\/18\/com-mais-de-55-mil-encaminhamentos-agencia-do-trabalhador-de-apucarana-mantem-destaque-no-fechamento-de-vagas-em-2025\/","title":{"rendered":"Com mais de 5,5 mil encaminhamentos, Ag\u00eancia do Trabalhador de Apucarana mant\u00e9m destaque no fechamento de vagas em 2025"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png\" alt=\"\" class=\"wp-image-8245\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-768x576.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-400x300.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-700x525.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-600x450.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>De janeiro a novembro, a Ag\u00eancia do Trabalhador de Apucarana captou 2.205 vagas, gerando a contrata\u00e7\u00e3o efetiva de 1.584&nbsp; profissionais com carteira assinada. O resultado representa uma efetividade de 72% no fechamento das vagas, o que mant\u00e9m Apucarana entre as cidades que mais emprega no Paran\u00e1.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota enalteceu o trabalho realizado pela equipe da ag\u00eancia, chefiada pelo superintendente municipal de Trabalho e Qualifica\u00e7\u00e3o, Neno Leiroz. \u201cA efici\u00eancia no processo de intermedia\u00e7\u00e3o de m\u00e3o de obra comprova que a estrat\u00e9gia de trabalho, focada no encaixe entre perfil do trabalhador e necessidade das empresas, t\u00eam como resultado impacto direto na gera\u00e7\u00e3o de emprego e renda no munic\u00edpio\u201d, destacou Mota, frisando que as a\u00e7\u00f5es da Ag\u00eancia do Trabalhador, ligada diretamente \u00e0 Secretaria de Estado do Trabalho, Qualifica\u00e7\u00e3o e Renda (SETR), ocorrem em parceria com a Secretaria Municipal da Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, que mant\u00e9m um programa de capacita\u00e7\u00e3o profissional gratuito direcionado \u00e0 popula\u00e7\u00e3o com cursos adquiridos a servi\u00e7os de excel\u00eancia no Brasil, como Senac e Senai. \u201cAgradecemos tamb\u00e9m ao secret\u00e1rio de Estado do Trabalho, deputado estadual licenciado Do Carmo, que tem sido um grande parceiro de Apucarana\u201d, pontuou o prefeito.<\/p>\n\n\n\n<p>O superintendente do Trabalho e Qualifica\u00e7\u00e3o, Neno Leiroz, relata que al\u00e9m da capta\u00e7\u00e3o de mais de 2,2 mil vagas e empregabilidade de 1,5 mil trabalhadores, entre janeiro e novembro, a Ag\u00eancia do Trabalhador de Apucarana realizou 5.591 encaminhamentos. \u201cAgrade\u00e7o \u00e0 dedica\u00e7\u00e3o de todos os membros de minha equipe, que n\u00e3o mediram esfor\u00e7os para promover as pol\u00edticas de empregabilidades tra\u00e7adas pela gest\u00e3o, possibilitando alcan\u00e7armos mais de 72% de efetividade atrav\u00e9s de um trabalho realizado diretamente com os empres\u00e1rios de Apucarana\u201d, destaca Leiroz, enaltecendo ainda o apoio da administra\u00e7\u00e3o municipal. \u201cA gest\u00e3o do prefeito Rodolfo Mota nos d\u00e1 liberdade e autonomia para agirmos, organizar os processos e transformar vagas abertas em contrata\u00e7\u00f5es efetivas\u201d, afirma.<\/p>\n\n\n\n<p>Leiroz tamb\u00e9m valoriza a parceria com a Secretaria Municipal de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os. \u201cAo longo do ano, a Ag\u00eancia do Trabalhador muitas vezes atuou em estreita parceria com a Prefeitura de Apucarana, promovendo a\u00e7\u00f5es no sentido de n\u00e3o apenas empregar, mas tamb\u00e9m de atrair mais empresas para a cidade, pois s\u00e3o os empres\u00e1rios que geram emprego e renda\u201d, concluiu o superintendente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De janeiro a novembro, a Ag\u00eancia do Trabalhador de Apucarana captou 2.205 vagas, gerando a contrata\u00e7\u00e3o efetiva de 1.584&nbsp; profissionais com carteira assinada. O resultado representa uma efetividade de 72% no fechamento das vagas, o que mant\u00e9m Apucarana entre as cidades que mais emprega no Paran\u00e1. O prefeito Rodolfo Mota enalteceu o trabalho realizado pela [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png",1024,768,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-300x225.png",300,225,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-768x576.png",768,576,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png",860,645,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png",1024,768,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64.png",1024,768,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-400x300.png",400,300,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-700x525.png",700,525,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-600x450.png",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-64-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8238"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8245"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}