{"id":8214,"date":"2025-12-16T01:36:03","date_gmt":"2025-12-15T22:36:03","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8214"},"modified":"2025-12-17T01:39:35","modified_gmt":"2025-12-16T22:39:35","slug":"prefeitura-de-apucarana-realiza-entrega-de-certificados-de-cursos-de-qualificacao-profissional","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/12\/16\/prefeitura-de-apucarana-realiza-entrega-de-certificados-de-cursos-de-qualificacao-profissional\/","title":{"rendered":"Prefeitura de Apucarana realiza entrega de certificados de cursos de qualifica\u00e7\u00e3o profissional"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png\" alt=\"\" class=\"wp-image-8219\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-768x576.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-400x300.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-700x525.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-600x450.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Apucarana realizou, na noite de ontem (15\/12), no Cine Teatro F\u00eanix, a entrega de certificados \u00e0s pessoas que conclu\u00edram cursos gratuitos de qualifica\u00e7\u00e3o profissional ofertados pelo munic\u00edpio ao longo de 2025. A iniciativa envolveu as secretarias municipais da Mulher e Assuntos da Fam\u00edlia (SEMAF), Assist\u00eancia Social e Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, ampliando o acesso da popula\u00e7\u00e3o \u00e0 forma\u00e7\u00e3o profissional e ao mercado de trabalho.<\/p>\n\n\n\n<p>Ao todo, foram disponibilizadas 1.100 vagas, distribu\u00eddas em mais de 20 cursos de diferentes \u00e1reas, com foco na gera\u00e7\u00e3o de renda, inclus\u00e3o produtiva e desenvolvimento econ\u00f4mico local. Os cursos foram realizados em parceria com o SENAI, SESI, SENAC e o Governo do Paran\u00e1, por meio da Secretaria de Estado do Trabalho, Qualifica\u00e7\u00e3o e Renda. Pelo Programa Qualifica Paran\u00e1, os participantes tamb\u00e9m receberam bolsa no valor de R$ 1.008,00 por aluno.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota ressaltou a import\u00e2ncia do investimento cont\u00ednuo em capacita\u00e7\u00e3o profissional. \u201cInvestir em qualifica\u00e7\u00e3o \u00e9 investir no futuro e no desenvolvimento de Apucarana. S\u00e3o cursos gratuitos, de excelente qualidade, que preparam os cidad\u00e3os para novas oportunidades de trabalho e renda\u201d, afirmou.<\/p>\n\n\n\n<p>Receberam certificados os formandos dos cursos de Assistente Administrativo, Comidas Natalinas, Corte Feminino e Escova, Costura Criativa, Costura, Moda e Modelagem, Croch\u00ea com Fio de Malha, Fotografia Mobile, Hamb\u00farguer Gourmet, Massas e Risotos, Modelagem e Henna para Sobrancelha, Panifica\u00e7\u00e3o, Preparo de Salgados, Preparo de Doces e Salgados para Festas Infantis, Preparo e Decora\u00e7\u00e3o de Bolos, Verrines e Cupcakes, Inform\u00e1tica B\u00e1sica \u2013 Windows e Pacote Office, Preparo de P\u00e3es Artesanais, Preparo de Pizza, Produ\u00e7\u00e3o de P\u00e3es Doces e Salgados, Gest\u00e3o de Qualidade, Produ\u00e7\u00e3o e Manuten\u00e7\u00e3o Industrial, Cria\u00e7\u00e3o de Websites (HTML e CSS), Manuten\u00e7\u00e3o de Celulares e Smartphones, Manuten\u00e7\u00e3o para Operadores de M\u00e1quina, Opera\u00e7\u00e3o de Torno e Centro de Usinagem.<\/p>\n\n\n\n<p>A primeira-dama e secret\u00e1ria municipal da Mulher e Assuntos da Fam\u00edlia, Karine Mota, destacou que a qualifica\u00e7\u00e3o profissional representa autonomia e fortalecimento social. \u201cA capacita\u00e7\u00e3o garante gera\u00e7\u00e3o de renda para as mulheres, incluindo aquelas que est\u00e3o saindo de situa\u00e7\u00f5es de viol\u00eancia dom\u00e9stica e de depend\u00eancia financeira\u201d, pontuou.<\/p>\n\n\n\n<p>Na mesma linha, a secret\u00e1ria municipal de Assist\u00eancia Social, Fab\u00edola Carrero, enfatizou o impacto social da iniciativa. \u201cA qualifica\u00e7\u00e3o profissional \u00e9 um instrumento essencial de transforma\u00e7\u00e3o social e de promo\u00e7\u00e3o da dignidade das fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade\u201d, declarou.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, Emerson Toledo, frisou que a oferta dos cursos considera as necessidades reais do setor produtivo. \u201cOs cursos est\u00e3o alinhados \u00e0s demandas do mercado de trabalho, ampliando as chances de inser\u00e7\u00e3o dos formandos\u201d, afirmou.<\/p>\n\n\n\n<p>J\u00e1 o superintendente municipal do Trabalho e Qualifica\u00e7\u00e3o, Neno Leiroz, ressaltou a integra\u00e7\u00e3o entre os entes envolvidos. \u201cA uni\u00e3o entre munic\u00edpio, Estado, SENAI, SESI e SENAC garante uma forma\u00e7\u00e3o consistente, conectada \u00e0s vagas dispon\u00edveis na Ag\u00eancia do Trabalhador de Apucarana\u201d, destacou.<\/p>\n\n\n\n<p>Tamb\u00e9m prestigiaram a solenidade Donato Junior, representando o secret\u00e1rio de Estado do Trabalho, Qualifica\u00e7\u00e3o e Renda, deputado Do Carmo; Lucas Salvalaggio, gerente do SENAC Apucarana; e Priscila Veroneze e Elizandra Maria Lauro Stefanuto, representantes do SENAI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana realizou, na noite de ontem (15\/12), no Cine Teatro F\u00eanix, a entrega de certificados \u00e0s pessoas que conclu\u00edram cursos gratuitos de qualifica\u00e7\u00e3o profissional ofertados pelo munic\u00edpio ao longo de 2025. A iniciativa envolveu as secretarias municipais da Mulher e Assuntos da Fam\u00edlia (SEMAF), Assist\u00eancia Social e Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, ampliando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png",1024,768,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-300x225.png",300,225,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-768x576.png",768,576,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png",860,645,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png",1024,768,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54.png",1024,768,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-400x300.png",400,300,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-700x525.png",700,525,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-600x450.png",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-54-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8214"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8219"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}