{"id":8085,"date":"2025-12-06T02:59:43","date_gmt":"2025-12-05T23:59:43","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8085"},"modified":"2025-12-07T03:05:50","modified_gmt":"2025-12-07T00:05:50","slug":"hemonucleo-de-apucarana-realiza-coleta-de-sangue-neste-sabado-para-reforcar-estoques-no-fim-do-ano","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/12\/06\/hemonucleo-de-apucarana-realiza-coleta-de-sangue-neste-sabado-para-reforcar-estoques-no-fim-do-ano\/","title":{"rendered":"Hemon\u00facleo de Apucarana realiza coleta de sangue neste s\u00e1bado para refor\u00e7ar estoques no fim do ano"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png\" alt=\"\" class=\"wp-image-8095\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O s\u00e1bado (06\/12) chega com um convite para praticar a solidariedade. O Hemon\u00facleo de Apucarana vai abrir as portas para coleta de sangue, das 8 \u00e0s 11 horas, refor\u00e7ando a mobiliza\u00e7\u00e3o para manter os estoques equilibrados no per\u00edodo de festas. A a\u00e7\u00e3o busca atender quem n\u00e3o consegue doar ao longo da semana e garantir o atendimento hospitalar durante o fim do ano, quando a demanda por sangue costuma subir.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota refor\u00e7ou o convite \u00e0 popula\u00e7\u00e3o para que doe sangue, destacando o impacto do gesto. \u201cCada bolsa coletada pode salvar at\u00e9 quatro vidas. Nesta \u00e9poca do ano, muitas pessoas viajam, o que reduz o n\u00famero de doadores, enquanto a probabilidade de acidentes nas estradas cresce. Pedimos que todos programem sua doa\u00e7\u00e3o, transformando o esp\u00edrito natalino em um ato concreto de solidariedade\u201d, afirmou.<\/p>\n\n\n\n<p>Juliana Gab Petchak, chefe do Hemon\u00facleo de Apucarana, explicou que a abertura aos s\u00e1bados acontece uma vez por m\u00eas. \u201cSempre abrimos no segundo s\u00e1bado de cada m\u00eas, justamente atendendo a um pedido da popula\u00e7\u00e3o que n\u00e3o consegue comparecer durante a semana\u201d, explicou. Ela refor\u00e7a que a presen\u00e7a do m\u00e9dico \u00e9 obrigat\u00f3ria para o funcionamento e, por isso, as datas de abertura aos s\u00e1bados seguem um cronograma pr\u00e9vio.<\/p>\n\n\n\n<p>Juliana afirma que os estoques exigem reposi\u00e7\u00e3o constante e que o trabalho \u00e9 di\u00e1rio, quase de \u201cformiguinha\u201d. No fim do ano, essa reposi\u00e7\u00e3o se torna ainda mais desafiadora, porque o n\u00famero de doadores cai. \u201cEm datas comemorativas, como Natal, Ano Novo, per\u00edodo de f\u00e9rias e Carnaval, a necessidade aumenta. Por isso, pedimos que as pessoas doem antes de viajar ou participar das festas de final de ano. Assim, estar\u00e3o ajudando a manter o estoque equilibrado\u201d, solicitou.<\/p>\n\n\n\n<p>A chefe do Hemon\u00facleo detalha como ser\u00e1 o funcionamento do atendimento neste s\u00e1bado. \u201cAo chegar o doador preenche um cadastro, passa pela triagem e responde a um question\u00e1rio. Na sequ\u00eancia, ele \u00e9 encaminhado para a coleta de sangue, que leva em m\u00e9dia sete minutos &nbsp;e, ao t\u00e9rmino, recebe um lanche\u201d, detalhou.<\/p>\n\n\n\n<p><strong>QUEM PODE DOAR \u2013 ORIENTA\u00c7\u00d5ES ESSENCIAIS<\/strong><br><strong>Requisitos b\u00e1sicos:<\/strong><br>\u2013 Idade entre 16 e 69 anos (menores acompanhados do respons\u00e1vel legal)<br>\u2013 Peso m\u00ednimo de 51 kg<br>\u2013 Estar em boas condi\u00e7\u00f5es de sa\u00fade<\/p>\n\n\n\n<p><strong>No dia da doa\u00e7\u00e3o:<\/strong><br>\u2013 Levar documento oficial com foto (RG, CNH, passaporte, carteira profissional ou de trabalho)<br>\u2013 Estar descansado e alimentado<br>\u2013 Evitar alimentos gordurosos nas quatro horas anteriores<\/p>\n\n\n\n<p><strong>Coleta neste s\u00e1bado:<\/strong>&nbsp;8h \u00e0s 11 horas<br><strong>Local:<\/strong>&nbsp;Hemon\u00facleo de Apucarana \u2013 Av. Corifeu de Azevedo Marques, 501<br><strong>Informa\u00e7\u00f5es:<\/strong>&nbsp;(43) 3420-4213<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O s\u00e1bado (06\/12) chega com um convite para praticar a solidariedade. O Hemon\u00facleo de Apucarana vai abrir as portas para coleta de sangue, das 8 \u00e0s 11 horas, refor\u00e7ando a mobiliza\u00e7\u00e3o para manter os estoques equilibrados no per\u00edodo de festas. A a\u00e7\u00e3o busca atender quem n\u00e3o consegue doar ao longo da semana e garantir o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-20-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8085"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8095"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}