{"id":8062,"date":"2025-12-03T04:57:48","date_gmt":"2025-12-03T01:57:48","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=8062"},"modified":"2025-12-04T04:58:53","modified_gmt":"2025-12-04T01:58:53","slug":"premiacao-inedita-coroa-empenho-e-aprendizado-na-formatura-de-1-400-alunos-do-proerd","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/12\/03\/premiacao-inedita-coroa-empenho-e-aprendizado-na-formatura-de-1-400-alunos-do-proerd\/","title":{"rendered":"Premia\u00e7\u00e3o in\u00e9dita coroa empenho e aprendizado na formatura de 1.400 alunos do Proerd"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png\" alt=\"\" class=\"wp-image-8066\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-768x576.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-400x300.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-700x525.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-600x450.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Mais 1.400 alunos do 5\u00ba ano da rede municipal de ensino de Apucarana conclu\u00edram o Programa Educacional de Resist\u00eancia \u00e0s Drogas e \u00e0 Viol\u00eancia (Proerd). A solenidade de formatura do programa &nbsp;\u2013 que une preven\u00e7\u00e3o, cidadania e forma\u00e7\u00e3o de valores \u2013 aconteceu nesta ter\u00e7a-feira (02\/12), no gin\u00e1sio de esportes do Lago\u00e3o. O destaque deste ano foi a entrega de 35&nbsp; bicicletas aos autores das melhores reda\u00e7\u00f5es, abrangendo pela primeira vez com a premia\u00e7\u00e3o toda a rede municipal de ensino.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota \u2013 que esteve acompanhado da equipe e do secret\u00e1rio estadual do Trabalho, Qualifica\u00e7\u00e3o e Renda, do Carmo \u2013 &nbsp;destacou a for\u00e7a da parceria entre o Munic\u00edpio, por meio da Autarquia Municipal de Educa\u00e7\u00e3o (AME), com a Pol\u00edcia Militar. \u201cO Programa ensina as nossas crian\u00e7as a dizer n\u00e3o para as drogas, al\u00e9m de levar no\u00e7\u00f5es de cidadania e disciplina\u201d, ressaltou.<\/p>\n\n\n\n<p>O prefeito celebrou ainda a novidade da premia\u00e7\u00e3o, que, al\u00e9m das bicicletas para as melhores reda\u00e7\u00f5es, incluiu a entrega de camisetas comemorativas, certificados e medalhas a todos os formandos. \u201cTudo foi pensado para motivar os alunos e estimular um futuro de paz, alegria e desenvolvimento para nossas crian\u00e7as\u201d, disse, refor\u00e7ando que a Pol\u00edcia Militar \u00e9 parceira estrat\u00e9gica na constru\u00e7\u00e3o de uma cidade mais segura e ordeira.<\/p>\n\n\n\n<p>A secret\u00e1ria municipal de Educa\u00e7\u00e3o, Ana Paula do Carmo Donato,&nbsp; agradeceu a presen\u00e7a das fam\u00edlias e o empenho das equipes escolares, citando diretoras e professoras que reorganizaram rotinas e mobilizaram as turmas ao longo do ano.<\/p>\n\n\n\n<p>A major Denise Mar\u00edlia Silva, subcomandante do Batalh\u00e3o de Patrulha Escolar Comunit\u00e1ria e coordenadora estadual do Proerd, refor\u00e7ou a trajet\u00f3ria s\u00f3lida do programa no Paran\u00e1. Presentes na rede p\u00fablica e privada desde 2000, as a\u00e7\u00f5es j\u00e1 formaram mais de 2 milh\u00f5es de estudantes, que se tornaram multiplicadores da cultura de preven\u00e7\u00e3o. \u201cO policial militar trabalha em sala de aula diversos assuntos, principalmente como os alunos devem se manter seguros e respons\u00e1veis, pensando sempre nas consequ\u00eancias de suas atitudes\u201d, afirmou.<\/p>\n\n\n\n<p>A major Mar\u00edlia explica que o Batalh\u00e3o de Patrulha Escolar Comunit\u00e1ria (BPEC) \u00e9 especializado na aplica\u00e7\u00e3o do policiamento comunit\u00e1rio escolar para todo o estado do Paran\u00e1 e&nbsp;desenvolve os programas Patrulha Escolar Comunit\u00e1ria (PEC) e o Proerd.&nbsp; \u201cA Pol\u00edcia Militar est\u00e1 muito orgulhosa, principalmente do munic\u00edpio de Apucarana, que h\u00e1 tantos anos apoia o Proerd e realizou neste ano uma essa festa lind\u00edssima\u201d, disse a major.<\/p>\n\n\n\n<p><strong>Programa entrega 35 bicicletas para melhores reda\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p>O instrutor social do Proerd, sargento F\u00e1bio do Nascimento Azevedo, destacou o car\u00e1ter in\u00e9dito da premia\u00e7\u00e3o. \u201cForam 35 bicicletas destinadas aos autores das melhores reda\u00e7\u00f5es, uma por escola, reconhecendo o m\u00e9rito dos estudantes. Ap\u00f3s dez aulas, os alunos produziram a reda\u00e7\u00e3o final dentro da sala de aula, sem qualquer consulta\u201d, esclareceu.<\/p>\n\n\n\n<p>O sargento Nascimento observou ainda que o n\u00edvel das reda\u00e7\u00f5es surpreendeu pela qualidade. Para ele, a premia\u00e7\u00e3o valoriza o empenho dos alunos e refor\u00e7a que dedica\u00e7\u00e3o e aprendizado caminham juntos.<\/p>\n\n\n\n<p>O sargento lembra ainda que o Proerd \u00e9 conduzido por policiais militares especialmente selecionados e capacitados na \u00e1rea da educa\u00e7\u00e3o. Eles atuam semanalmente nas turmas do 5\u00ba ano, em parceria institucional entre o Batalh\u00e3o de Patrulha Escolar Comunit\u00e1ria e a Autarquia Municipal de Educa\u00e7\u00e3o. A formatura coroou um ciclo de trabalho que fortalece escolhas seguras e aproxima comunidade, escola e seguran\u00e7a p\u00fablica, reafirmando o compromisso&nbsp; do Munic\u00edpio de Apucarana com a preven\u00e7\u00e3o e o cuidado com as crian\u00e7as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais 1.400 alunos do 5\u00ba ano da rede municipal de ensino de Apucarana conclu\u00edram o Programa Educacional de Resist\u00eancia \u00e0s Drogas e \u00e0 Viol\u00eancia (Proerd). A solenidade de formatura do programa &nbsp;\u2013 que une preven\u00e7\u00e3o, cidadania e forma\u00e7\u00e3o de valores \u2013 aconteceu nesta ter\u00e7a-feira (02\/12), no gin\u00e1sio de esportes do Lago\u00e3o. O destaque deste ano [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png",1024,768,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-300x225.png",300,225,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-768x576.png",768,576,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png",860,645,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png",1024,768,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10.png",1024,768,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-400x300.png",400,300,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-700x525.png",700,525,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-600x450.png",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/12\/image-10-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=8062"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/8062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/8066"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=8062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=8062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=8062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}