{"id":802,"date":"2023-10-02T18:41:09","date_gmt":"2023-10-02T18:41:09","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=802"},"modified":"2023-10-02T18:41:10","modified_gmt":"2023-10-02T18:41:10","slug":"rotam-apreende-motocicleta-apos-perseguicao-em-apucarana-video","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/10\/02\/rotam-apreende-motocicleta-apos-perseguicao-em-apucarana-video\/","title":{"rendered":"Rotam apreende motocicleta ap\u00f3s persegui\u00e7\u00e3o em Apucarana; v\u00eddeo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ao perceberem a presen\u00e7a da Rotam, o piloto da motocicleta aumentou a velocidade e empreendeu fuga<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"474\" height=\"303\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/A-ocorrencia-teve-inicio-na-Avenida-Sao-Joao-no-Ja-00797724-0-202310021117-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-803\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/A-ocorrencia-teve-inicio-na-Avenida-Sao-Joao-no-Ja-00797724-0-202310021117-ScaleDownProportional.webp 474w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/A-ocorrencia-teve-inicio-na-Avenida-Sao-Joao-no-Ja-00797724-0-202310021117-ScaleDownProportional-300x192.webp 300w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p>Em uma persegui\u00e7\u00e3o que durou cerca de 15 minutos, a equipe das Rondas Ostensivas T\u00e1tico M\u00f3vel (Rotam), da Pol\u00edcia Militar (PM), de Apucarana, conseguiu interceptar dois homens que fugiam em alta velocidade em uma motocicleta Honda\/CG 160.&nbsp;<\/p>\n\n\n\n<p>A ocorr\u00eancia teve in\u00edcio na Avenida S\u00e3o Jo\u00e3o, no Jardim Apucarana, e terminou na Rua Marc\u00edlio Dias, no Residencial Monte Belo, na madrugada deste s\u00e1bado (30), por volta das 2h30.<\/p>\n\n\n\n<p>Os suspeitos foram vistos pelos policiais pr\u00f3ximo ao Posto Matrix. Ao perceberem a presen\u00e7a policial, o piloto da motocicleta aumentou a velocidade e empreendeu fuga, desrespeitando sinais vermelhos e locais de parada obrigat\u00f3ria.<\/p>\n\n\n\n<p>A persegui\u00e7\u00e3o se estendeu por v\u00e1rios bairros, incluindo o Jardim Diamantina, Jardim Am\u00e9rica, Jardim Trabalhista, Vila Nova, Jardim Marisol, Vale Verde, Jardim Apucarana e Residencial Monte Belo.<\/p>\n\n\n\n<p>A fuga terminou quando os suspeitos colidiram com um ve\u00edculo na rotat\u00f3ria da Rua Marc\u00edlio Dias, no Residencial Monte Belo. O condutor da motocicleta tentou fugir a p\u00e9 ap\u00f3s o acidente, mas foi capturado pela pol\u00edcia. Os dois suspeitos sofreram escoria\u00e7\u00f5es na queda, mas recusaram atendimento m\u00e9dico.<\/p>\n\n\n\n<p>A moto foi apreendida. Os policiais lavraram as notifica\u00e7\u00f5es cab\u00edveis e um termo circunstanciado da situa\u00e7\u00e3o. Os suspeitos foram liberados na 17\u00aa Subdivis\u00e3o Policial de Apucarana (17\u00aa SDP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao perceberem a presen\u00e7a da Rotam, o piloto da motocicleta aumentou a velocidade e empreendeu fuga Em uma persegui\u00e7\u00e3o que durou cerca de 15 minutos, a equipe das Rondas Ostensivas T\u00e1tico M\u00f3vel (Rotam), da Pol\u00edcia Militar (PM), de Apucarana, conseguiu interceptar dois homens que fugiam em alta velocidade em uma motocicleta Honda\/CG 160.&nbsp; A ocorr\u00eancia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-802","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/802\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}