{"id":7849,"date":"2025-11-14T22:08:45","date_gmt":"2025-11-14T19:08:45","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7849"},"modified":"2025-11-14T22:08:46","modified_gmt":"2025-11-14T19:08:46","slug":"apucarana-autoriza-licitacao-para-reforma-e-ampliacao-de-ubs-da-vila-reis-e-do-pirapo","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/11\/14\/apucarana-autoriza-licitacao-para-reforma-e-ampliacao-de-ubs-da-vila-reis-e-do-pirapo\/","title":{"rendered":"Apucarana autoriza licita\u00e7\u00e3o para reforma e amplia\u00e7\u00e3o de UBS da Vila Reis e do Pirap\u00f3"},"content":{"rendered":"\n<p>A Prefeitura de Apucarana autorizou, na manh\u00e3 desta sexta-feira (14\/11), a abertura do processo licitat\u00f3rio para a reforma e amplia\u00e7\u00e3o de duas importantes Unidades B\u00e1sicas de Sa\u00fade: a <strong>UBS Pedro Barreto<\/strong>, na Vila Reis, e a <strong>UBS Walter Lazarini<\/strong>, no distrito do Pirap\u00f3. Ao todo, o investimento previsto \u00e9 de <strong>R$ 884.690,45<\/strong>, com o objetivo de ampliar a capacidade de atendimento, ampliar espa\u00e7os e garantir melhores condi\u00e7\u00f5es de trabalho \u00e0s equipes de sa\u00fade.<\/p>\n\n\n\n<p>O prefeito <strong>Rodolfo Mota<\/strong> destacou que parte dos recursos foi viabilizada por meio da deputada federal <strong>Lu\u00edsa Canziani<\/strong>, com intermedia\u00e7\u00e3o dos vereadores <strong>Mois\u00e9s Tavares<\/strong> e <strong>Luciano Fachiano<\/strong>. Ele explicou que Vila Reis e Pirap\u00f3 foram priorizados devido ao grande contingente populacional que atendem.<br>\u201cEstamos muito felizes. No distrito da Vila Reis, vamos praticamente dobrar o tamanho da UBS, que chegar\u00e1 a cerca de 300 metros quadrados. No Pirap\u00f3, a unidade tamb\u00e9m ser\u00e1 ampliada e contar\u00e1 com uma farm\u00e1cia que vai descentralizar a entrega de medicamentos, facilitando muito a vida dos moradores\u201d, afirmou o prefeito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>UBS Pedro Barreto ter\u00e1 mais que o dobro da estrutura atual<\/strong><\/h3>\n\n\n\n<p>A UBS Pedro Barreto, inaugurada em 2003, receber\u00e1 <strong>R$ 621.830,48<\/strong> em melhorias. A unidade, que possui 138,21 m\u00b2, ganhar\u00e1 mais <strong>163,63 m\u00b2<\/strong>, passando a abrigar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quatro novos consult\u00f3rios<\/li>\n\n\n\n<li>Sala de triagem<\/li>\n\n\n\n<li>Copa<\/li>\n\n\n\n<li>Sala de agentes<\/li>\n\n\n\n<li>Dep\u00f3sito de material de limpeza<\/li>\n\n\n\n<li>Banheiro para funcion\u00e1rios<\/li>\n\n\n\n<li>Nova fossa s\u00e9ptica e sumidouro<\/li>\n<\/ul>\n\n\n\n<p>A obra tamb\u00e9m inclui pintura geral, adequa\u00e7\u00f5es de esquadrias, reforma interna com demoli\u00e7\u00e3o e constru\u00e7\u00e3o de paredes, instala\u00e7\u00e3o de bancadas e cubas e substitui\u00e7\u00e3o de revestimentos.<\/p>\n\n\n\n<p>O vice-prefeito <strong>Marcos da Vila Reis<\/strong> comemorou a iniciativa.<br>\u201cA UBS Pedro Barreto foi inaugurada em 2003 e atendia plenamente \u00e0s necessidades da \u00e9poca. Mas o distrito cresceu muito e a estrutura atual j\u00e1 n\u00e3o comporta a demanda. \u00c9 uma manh\u00e3 muito feliz para nossa comunidade\u201d, afirmou.<\/p>\n\n\n\n<p>A enfermeira-chefe da unidade, <strong>Thamyres Rocha<\/strong>, ressaltou os impactos diretos na rotina:<br>\u201cHoje atendemos cerca de 200 pessoas por dia e enfrentamos limita\u00e7\u00f5es de espa\u00e7o. Com a amplia\u00e7\u00e3o, poderemos acolher melhor nossos pacientes e trabalhar de forma mais organizada.\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Amplia\u00e7\u00e3o do Pirap\u00f3 inclui farm\u00e1cia in\u00e9dita<\/strong><\/h3>\n\n\n\n<p>No distrito de Pirap\u00f3, a UBS Walter Lazarini receber\u00e1 <strong>R$ 262.859,97<\/strong> em investimentos. A \u00e1rea atual de 216,30 m\u00b2 ser\u00e1 ampliada em <strong>57,22 m\u00b2<\/strong>, contemplando:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Um consult\u00f3rio<\/li>\n\n\n\n<li>Sala administrativa<\/li>\n\n\n\n<li>Primeira farm\u00e1cia do distrito<\/li>\n<\/ul>\n\n\n\n<p>A obra prev\u00ea tamb\u00e9m pintura, adequa\u00e7\u00e3o de bancadas conforme exig\u00eancias da Vigil\u00e2ncia Sanit\u00e1ria, melhorias na el\u00e9trica para climatiza\u00e7\u00e3o e implanta\u00e7\u00e3o de cobertura met\u00e1lica externa.<\/p>\n\n\n\n<p>Para o secret\u00e1rio municipal de Sa\u00fade, <strong>Dr. Guilherme de Paula<\/strong>, a inclus\u00e3o da farm\u00e1cia representa um avan\u00e7o importante.<br>\u201cHoje, os moradores de Pirap\u00f3 e Caixa de S\u00e3o Pedro precisam ir ao centro para retirar medicamentos. Com a farm\u00e1cia na UBS Walter Lazarini, o servi\u00e7o ficar\u00e1 mais acess\u00edvel e facilitar\u00e1 a vida das fam\u00edlias\u201d, ressaltou.<\/p>\n\n\n\n<p>O enfermeiro-chefe da unidade, <strong>Elton Ibanez Dicati<\/strong>, refor\u00e7ou:<br>\u201cA farm\u00e1cia permitir\u00e1 ao paciente receber o rem\u00e9dio no mesmo dia da consulta, algo essencial em tratamentos que precisam come\u00e7ar imediatamente.\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Obras devem come\u00e7ar no in\u00edcio de 2026<\/strong><\/h3>\n\n\n\n<p>O ato de autoriza\u00e7\u00e3o contou com a presen\u00e7a dos vereadores Mois\u00e9s Tavares, Odarlone Orente, Pablo da Seguran\u00e7a, al\u00e9m de secret\u00e1rios municipais e moradores dos distritos.<br>De acordo com o prefeito, a expectativa \u00e9 que as obras se iniciem entre janeiro e fevereiro, garantindo mais qualidade, agilidade e humaniza\u00e7\u00e3o no atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana autorizou, na manh\u00e3 desta sexta-feira (14\/11), a abertura do processo licitat\u00f3rio para a reforma e amplia\u00e7\u00e3o de duas importantes Unidades B\u00e1sicas de Sa\u00fade: a UBS Pedro Barreto, na Vila Reis, e a UBS Walter Lazarini, no distrito do Pirap\u00f3. Ao todo, o investimento previsto \u00e9 de R$ 884.690,45, com o objetivo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7850,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1.jpg",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-768x512.jpg",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1.jpg",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1.jpg",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1.jpg",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-400x300.jpg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-400x600.jpg",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-400x400.jpg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-400x267.jpg",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-700x500.jpg",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-700x683.jpg",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-700x467.jpg",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-1000x600.jpg",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-1024x600.jpg",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/licitacao-reforma-de-UBS008-1024x683-1-100x100.jpg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7849"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7850"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}