{"id":7811,"date":"2025-11-11T03:40:08","date_gmt":"2025-11-11T00:40:08","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7811"},"modified":"2025-11-12T03:41:57","modified_gmt":"2025-11-12T00:41:57","slug":"ultima-semana-para-renovacao-de-matriculas-nos-cmeis-e-escolas-municipais-de-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/11\/11\/ultima-semana-para-renovacao-de-matriculas-nos-cmeis-e-escolas-municipais-de-apucarana\/","title":{"rendered":"\u00daltima semana para renova\u00e7\u00e3o de matr\u00edculas nos CMEIs e Escolas Municipais de Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png\" alt=\"\" class=\"wp-image-7815\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Autarquia Municipal de Educa\u00e7\u00e3o (AME) de Apucarana informa que esta \u00e9 a \u00faltima semana para a renova\u00e7\u00e3o das matr\u00edculas dos estudantes que j\u00e1 frequentam os Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e as Escolas Municipais. O prazo termina na sexta-feira, dia 14 de novembro, e deve ser feito diretamente na unidade onde a crian\u00e7a est\u00e1 matriculada.<\/p>\n\n\n\n<p>A secret\u00e1ria de Educa\u00e7\u00e3o, professora Ana Paula do Carmo Donato, destaca a import\u00e2ncia de os pais e respons\u00e1veis realizarem o procedimento dentro do prazo. \u201cA renova\u00e7\u00e3o antecipada nos ajuda a planejar com anteced\u00eancia o pr\u00f3ximo ano letivo, garantindo o n\u00famero adequado de turmas, professores e materiais pedag\u00f3gicos. \u00c9 uma etapa essencial para que o ensino continue acontecendo com qualidade e organiza\u00e7\u00e3o\u201d, afirma.<\/p>\n\n\n\n<p>Ap\u00f3s o per\u00edodo de rematr\u00edculas, o calend\u00e1rio da Autarquia prev\u00ea novas etapas: de 17 a 28 de novembro, ser\u00e1 a matr\u00edcula das crian\u00e7as que em 2025 est\u00e3o no Infantil 3 e, em 2026, ingressar\u00e3o no Infantil 4; e de 1\u00ba a 12 de dezembro, ocorrer\u00e3o as novas matr\u00edculas e transfer\u00eancias entre unidades, conforme disponibilidade de vagas. Para efetuar a matr\u00edcula inicial ou transfer\u00eancia, \u00e9 necess\u00e1rio apresentar certid\u00e3o de nascimento, documentos pessoais do aluno e do respons\u00e1vel, comprovante de endere\u00e7o, comprovante de vacina\u00e7\u00e3o e, se houver, cart\u00e3o do Bolsa Fam\u00edlia ou espelho emitido pelo CRAS.<\/p>\n\n\n\n<p>A Prefeitura de Apucarana refor\u00e7a que \u00e9 obrigat\u00f3ria a apresenta\u00e7\u00e3o da Declara\u00e7\u00e3o de Vacina\u00e7\u00e3o com o esquema atualizado de crian\u00e7as e adolescentes de at\u00e9 18 anos, incluindo contra a Covid-19, conforme estabelece a Lei Estadual n\u00ba 19.534\/2018. O documento \u00e9 emitido pelas Unidades B\u00e1sicas de Sa\u00fade (UBSs), desde que o esquema vacinal esteja em dia. Caso haja necessidade, as equipes de sa\u00fade realizam a atualiza\u00e7\u00e3o das doses previstas no Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o.<\/p>\n\n\n\n<p>A aus\u00eancia da declara\u00e7\u00e3o n\u00e3o impede a matr\u00edcula, mas a legisla\u00e7\u00e3o determina que a escola notifique o Conselho Tutelar se o documento n\u00e3o for apresentado em at\u00e9 30 dias. As vacinas est\u00e3o dispon\u00edveis em todas as UBSs com sala de vacina\u00e7\u00e3o, de segunda a sexta-feira, das 8h \u00e0s 16h30; e nas UBSs Takaiti Miyadi (N\u00facleo Dom Romeu Alberti) e Ant\u00f4nio Sacchelli (Jardim Colonial), o atendimento se estende at\u00e9 20h30. Mais informa\u00e7\u00f5es podem ser obtidas junto \u00e0 unidade escolar ou com a AME, pelo telefone (43) 3308-1699<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Autarquia Municipal de Educa\u00e7\u00e3o (AME) de Apucarana informa que esta \u00e9 a \u00faltima semana para a renova\u00e7\u00e3o das matr\u00edculas dos estudantes que j\u00e1 frequentam os Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e as Escolas Municipais. O prazo termina na sexta-feira, dia 14 de novembro, e deve ser feito diretamente na unidade onde a crian\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-29-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7811"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7815"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}