{"id":7768,"date":"2025-11-07T05:01:51","date_gmt":"2025-11-07T02:01:51","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7768"},"modified":"2025-11-08T05:04:01","modified_gmt":"2025-11-08T02:04:01","slug":"nova-sede-da-secretaria-da-mulher-facilita-acesso-e-unifica-em-endereco-central-acolhimento-protecao-e-capacitacao-de-mulheres-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/11\/07\/nova-sede-da-secretaria-da-mulher-facilita-acesso-e-unifica-em-endereco-central-acolhimento-protecao-e-capacitacao-de-mulheres-em-apucarana\/","title":{"rendered":"Nova sede da Secretaria da Mulher facilita acesso e unifica em endere\u00e7o central acolhimento, prote\u00e7\u00e3o e capacita\u00e7\u00e3o de mulheres em Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png\" alt=\"\" class=\"wp-image-7769\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Apucarana inaugurou nesta sexta-feira (06\/11) a nova sede da Secretaria da Mulher e Assuntos da Fam\u00edlia (Semaf), que passa a centralizar em um \u00fanico endere\u00e7o os servi\u00e7os de acolhimento, prote\u00e7\u00e3o e capacita\u00e7\u00e3o voltados \u00e0s mulheres do munic\u00edpio. Localizado na Rua Professora Talita Bresolin, n\u00ba 520 \u2013 antigo Espa\u00e7o Maranata \u2013, o novo espa\u00e7o abriga as pol\u00edticas p\u00fablicas de protagonismo feminino desde o dia 20 de outubro e re\u00fane a estrutura da secretaria e do Centro de Atendimento \u00e0 Mulher (CAM), al\u00e9m de programas de qualifica\u00e7\u00e3o e gera\u00e7\u00e3o de renda.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota destacou que a mudan\u00e7a representa um avan\u00e7o concreto na rede de prote\u00e7\u00e3o. \u201cA antiga sede, no Jardim Am\u00e9rica, era limitada em espa\u00e7o e de dif\u00edcil acesso. Muitas mulheres, inclusive, tinham dificuldade de chegar at\u00e9 l\u00e1 por conta da dist\u00e2ncia ou do custo do transporte. Agora, com esta nova sede, em ponto central e pr\u00f3xima ao Terminal Urbano, \u00e0 Delegacia da Mulher, ao F\u00f3rum C\u00edvel, ao Minist\u00e9rio P\u00fablico e ao Hospital da Provid\u00eancia, o acesso ficou muito mais f\u00e1cil. Isso significa mais acolhimento, dignidade e cuidado com as mulheres que mais precisam. \u00c9 um pr\u00e9dio amplo, moderno e acolhedor, que vai permitir o atendimento integrado de psic\u00f3logos, assistentes sociais e assessoria jur\u00eddica\u201d, afirmou o prefeito.<\/p>\n\n\n\n<p>Mota tamb\u00e9m agradeceu \u00e0s institui\u00e7\u00f5es parceiras da macrorrede de prote\u00e7\u00e3o \u00e0 mulher. \u201cCentenas de mulheres j\u00e1 foram atendidas neste ano e, com esta nova estrutura, poderemos ampliar ainda mais esse trabalho \u2014 seja nos cursos de qualifica\u00e7\u00e3o, nos projetos de gera\u00e7\u00e3o de renda ou nas a\u00e7\u00f5es de prote\u00e7\u00e3o e den\u00fancia de viol\u00eancia e ass\u00e9dio\u201d, completou.<\/p>\n\n\n\n<p>A secret\u00e1ria e primeira-dama, Karine Mota, enfatizou que a nova sede simboliza mais do que uma mudan\u00e7a de endere\u00e7o. \u201cMarca o fortalecimento de uma rede de acolhimento que salva vidas todos os dias. Aqui, cada sala, cada detalhe, foi pensado para receber mulheres que precisam de apoio, escuta e prote\u00e7\u00e3o. Muitas vezes, o nosso trabalho acontece em sil\u00eancio. Nem sempre \u00e9 vis\u00edvel, mas \u00e9 transformador. S\u00e3o atendimentos di\u00e1rios, hist\u00f3rias dif\u00edceis, mulheres que chegam em busca de ajuda e encontram acolhimento, orienta\u00e7\u00e3o e uma nova chance de recome\u00e7ar\u201d, relatou.<\/p>\n\n\n\n<p>Karine ressaltou ainda que as atividades da secretaria v\u00e3o continuar crescendo. \u201c\u00c9 por isso que seguimos promovendo oficinas, cursos e at\u00e9 bingos solid\u00e1rios \u2014 s\u00e3o oportunidades de aproxima\u00e7\u00e3o com quem mais precisa. Nosso objetivo \u00e9 ir onde as mulheres est\u00e3o, resgatar v\u00edtimas, oferecer oportunidades e garantir que nenhuma fique sozinha diante da viol\u00eancia ou da vulnerabilidade. Aqui, com o trabalho de uma valiosa equipe de servidores, vamos desenvolver uma a\u00e7\u00e3o ainda melhor para as mulheres e fam\u00edlias de Apucarana\u201d, completou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana inaugurou nesta sexta-feira (06\/11) a nova sede da Secretaria da Mulher e Assuntos da Fam\u00edlia (Semaf), que passa a centralizar em um \u00fanico endere\u00e7o os servi\u00e7os de acolhimento, prote\u00e7\u00e3o e capacita\u00e7\u00e3o voltados \u00e0s mulheres do munic\u00edpio. Localizado na Rua Professora Talita Bresolin, n\u00ba 520 \u2013 antigo Espa\u00e7o Maranata \u2013, o novo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/11\/image-18-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7768"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7769"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}