{"id":7646,"date":"2025-10-29T04:54:26","date_gmt":"2025-10-29T01:54:26","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7646"},"modified":"2025-10-30T04:55:26","modified_gmt":"2025-10-30T01:55:26","slug":"escolas-cmeis-pai-e-servicos-essenciais-funcionarao-normalmente-nesta-sexta-feriado-do-dia-do-servidor","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/10\/29\/escolas-cmeis-pai-e-servicos-essenciais-funcionarao-normalmente-nesta-sexta-feriado-do-dia-do-servidor\/","title":{"rendered":"Escolas, CMEIs, PAI e servi\u00e7os essenciais funcionar\u00e3o normalmente nesta sexta, feriado do Dia do Servidor"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png\" alt=\"\" class=\"wp-image-7650\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Embora algumas reparti\u00e7\u00f5es p\u00fablicas municipais estar\u00e3o fechadas, os servi\u00e7os essenciais ser\u00e3o mantidos nesta sexta-feira, dia em que ser\u00e1 comemorado o Dia do Servidor P\u00fablico. Na sa\u00fade, UPA, SAMU e PAI funcionar\u00e3o normalmente. O mesmo acontecer\u00e1 na educa\u00e7\u00e3o, com atendimento normal em escolas e CMEIs. J\u00e1 Prefeitura e demais \u00f3rg\u00e3os da administra\u00e7\u00e3o direta estar\u00e3o fechados.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota destacou que a medida foi estabelecida pelo Decreto n\u00ba 397\/2025<strong>,<\/strong>&nbsp;&nbsp;que transferiu a comemora\u00e7\u00e3o do Dia do Servidor \u2013 tradicionalmente celebrado no dia 28 de outubro \u2013 para o dia 31 de outubro, uma sexta-feira. \u201cE para facilitar o acompanhamento pela popula\u00e7\u00e3o do que ficar\u00e1 aberto e fechado, a nossa equipe fez o detalhamento do funcionamento dos servi\u00e7os essenciais neste dia\u201d, disse Rodolfo Mota.<\/p>\n\n\n\n<p>Na \u00e1rea da sa\u00fade, os servi\u00e7os de urg\u00eancia e emerg\u00eancia funcionar\u00e3o normalmente. A Unidade de Pronto Atendimento (UPA) e o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) atendem 24 horas. O Pronto Atendimento Infantil (PAI) tamb\u00e9m estar\u00e1 aberto, das 7h \u00e0s 22h. J\u00e1 as Unidades B\u00e1sicas de Sa\u00fade (UBS) n\u00e3o ter\u00e3o expediente, com exce\u00e7\u00e3o da UBS Romeu Milani, localizada no centro de Apucarana, que funcionar\u00e1 das 8 \u00e0s 17 horas.<\/p>\n\n\n\n<p>A Guarda Civil Municipal e a Defesa Civil mant\u00eam atendimento permanente, com chamadas pelo telefone 153, garantindo o suporte \u00e0 popula\u00e7\u00e3o. O decreto tamb\u00e9m n\u00e3o provocar\u00e1 altera\u00e7\u00f5es na educa\u00e7\u00e3o, cujos setores \u2013 como escolas e CMEIs \u2013&nbsp; funcionar\u00e3o normalmente nesta sexta-feira. Ana Paula do Carmo Donato,&nbsp; secret\u00e1ria municipal de Educa\u00e7\u00e3o, lembra que os funcion\u00e1rios&nbsp; da Autarquia Municipal de Educa\u00e7\u00e3o (AME) n\u00e3o foram abrangidos pela medida, pois j\u00e1 usufru\u00edram desse direito no dia 17 de outubro, quando celebraram a data juntamente com o Dia do Professor.<\/p>\n\n\n\n<p>J\u00e1 Prefeitura e demais \u00f3rg\u00e3os da administra\u00e7\u00e3o direta estar\u00e3o fechados. No entanto, o secret\u00e1rio municipal de Gest\u00e3o P\u00fablica, Robson de Souza Cruz, lembra que, mesmo com o ponto facultativo, as pessoas poder\u00e3o recorrer aos servi\u00e7os online da Prefeitura. Pelo site oficial (www.apucarana.pr.gov.br) e pelo Portal do Cidad\u00e3o (apucarana.atende.net), ser\u00e1 poss\u00edvel emitir emitir certid\u00f5es, consultar protocolos, renovar alvar\u00e1s, parcelar d\u00e9bitos e acessar diversos outros servi\u00e7os dispon\u00edveis 24 horas por dia.<\/p>\n\n\n\n<p><strong>O QUE ABRE E O QUE FECHA \u2013 Recesso do Dia do Servidor (sexta, 31\/10)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>LOCAL<\/strong><\/td><td><strong>FUNCIONAMENTO<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Prefeitura<\/strong><\/td><td>Fechada<\/td><\/tr><tr><td><strong>UPA, Farm\u00e1cia 24h, SAMU<\/strong><\/td><td>Abertos (atendimento 24h)<\/td><\/tr><tr><td><strong>Pronto Atendimento Infantil (PAI)<\/strong><\/td><td>Aberto (7h \u00e0s 22h)<\/td><\/tr><tr><td><strong>Farm\u00e1cia Central<\/strong><\/td><td>Fechada<\/td><\/tr><tr><td><strong>Unidades B\u00e1sicas de Sa\u00fade (UBS)<\/strong><\/td><td>Fechadas&nbsp;<em>(exceto UBS Romeu Milani, das 8h \u00e0s 17h)<\/em><\/td><\/tr><tr><td><strong>Centro Infantil<\/strong><\/td><td>Fechado<\/td><\/tr><tr><td><strong>Escolas e CMEIs<\/strong><\/td><td>Abertos&nbsp;<em>(funcionamento normal conforme calend\u00e1rio escolar)<\/em><\/td><\/tr><tr><td><strong>Guarda Civil Municipal (GCM)<\/strong><\/td><td>Funcionamento normal&nbsp;<em>(servi\u00e7o essencial)<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Embora algumas reparti\u00e7\u00f5es p\u00fablicas municipais estar\u00e3o fechadas, os servi\u00e7os essenciais ser\u00e3o mantidos nesta sexta-feira, dia em que ser\u00e1 comemorado o Dia do Servidor P\u00fablico. Na sa\u00fade, UPA, SAMU e PAI funcionar\u00e3o normalmente. O mesmo acontecer\u00e1 na educa\u00e7\u00e3o, com atendimento normal em escolas e CMEIs. J\u00e1 Prefeitura e demais \u00f3rg\u00e3os da administra\u00e7\u00e3o direta estar\u00e3o fechados. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/10\/image-84-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7646"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7650"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}