{"id":750,"date":"2023-09-27T15:29:00","date_gmt":"2023-09-27T15:29:00","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=750"},"modified":"2023-09-27T15:29:01","modified_gmt":"2023-09-27T15:29:01","slug":"idoso-de-71-anos-fica-ferido-apos-capotar-carro-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/27\/idoso-de-71-anos-fica-ferido-apos-capotar-carro-em-apucarana\/","title":{"rendered":"Idoso de 71 anos fica ferido ap\u00f3s capotar carro em Apucarana"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">V\u00edtima teve contus\u00f5es e escoria\u00e7\u00f5es pelo corpo e foi encaminhada para o Hospital da Provid\u00eancia<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Socorristas-foram-acionados-e-retiraram-o-homem-qu-00796244-0-202309271108-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-751\" style=\"width:649px;height:487px\" width=\"649\" height=\"487\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Socorristas-foram-acionados-e-retiraram-o-homem-qu-00796244-0-202309271108-ScaleDownProportional.webp 742w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Socorristas-foram-acionados-e-retiraram-o-homem-qu-00796244-0-202309271108-ScaleDownProportional-600x450.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Socorristas-foram-acionados-e-retiraram-o-homem-qu-00796244-0-202309271108-ScaleDownProportional-300x225.webp 300w\" sizes=\"(max-width: 649px) 100vw, 649px\" \/><\/figure>\n\n\n\n<p>Um idoso de 71 anos ficou preso nas ferragens ap\u00f3s perder a dire\u00e7\u00e3o do carro, uma Toyota Hilux, e\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/capotamento?d=1\" target=\"_blank\">capotar<\/a>\u00a0nesta ter\u00e7a-feira (27) em\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\" target=\"_blank\">Apucarana<\/a>, no norte do Paran\u00e1. O acidente aconteceu na BR-376, no sentido Jandaia do Sul para Apucarana, pr\u00f3ximo ao distrito do Pirap\u00f3<\/p>\n\n\n\n<p>O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) e o Corpo de Bombeiros foram acionados at\u00e9 o local. Segundo os socorristas, ap\u00f3s perder a dire\u00e7\u00e3o, o carro desceu um barranco pr\u00f3ximo, capotando algumas vezes.<\/p>\n\n\n\n<p>Ap\u00f3s serrar parte do ve\u00edculo, os bombeiros conseguiram retirar a v\u00edtima do carro. Ele teve diversas contus\u00f5es e escoria\u00e7\u00f5es pelo corpo e foi encaminhado para o Hospital da Provid\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtima teve contus\u00f5es e escoria\u00e7\u00f5es pelo corpo e foi encaminhada para o Hospital da Provid\u00eancia Um idoso de 71 anos ficou preso nas ferragens ap\u00f3s perder a dire\u00e7\u00e3o do carro, uma Toyota Hilux, e\u00a0capotar\u00a0nesta ter\u00e7a-feira (27) em\u00a0Apucarana, no norte do Paran\u00e1. O acidente aconteceu na BR-376, no sentido Jandaia do Sul para Apucarana, pr\u00f3ximo ao [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-750","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=750"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/750\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}