{"id":7312,"date":"2025-09-26T23:13:28","date_gmt":"2025-09-26T20:13:28","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7312"},"modified":"2025-09-26T23:13:30","modified_gmt":"2025-09-26T20:13:30","slug":"idosos-do-centro-dia-de-apucarana-deixam-legado-ao-meio-ambiente-com-plantio-de-arvores-frutiferas-no-parque-municipal-jaboti","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/09\/26\/idosos-do-centro-dia-de-apucarana-deixam-legado-ao-meio-ambiente-com-plantio-de-arvores-frutiferas-no-parque-municipal-jaboti\/","title":{"rendered":"Idosos do Centro Dia de Apucarana deixam legado ao meio ambiente com plantio de \u00e1rvores frut\u00edferas no Parque Municipal Jaboti"},"content":{"rendered":"\n<p>Assessorados por t\u00e9cnicos municipais, o grupo realizou o plantio de mudas de ara\u00e7\u00e1, pitanga, amora, ameixa amarela e gabiroba, em uma \u00e1rea abaixo do Bosque e Memorial em Homenagem \u00e0s V\u00edtimas da Covid-19<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8.png\" alt=\"\" class=\"wp-image-7313\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/image-8-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201cNa velhice ainda dar\u00e3o frutos, ser\u00e3o vi\u00e7osos e florescentes, para anunciar que o Senhor \u00e9 reto.\u201d Com a mensagem b\u00edblica do Salmos 92:14-15 transcrita em um cart\u00e3o, nesta sexta-feira (26\/09) assistidos pelo Centro Dia da Pessoa Idosa da Prefeitura de Apucarana foram convidados pelas secretarias da Assist\u00eancia Social, de Meio Ambiente e de Servi\u00e7os P\u00fablicos a protagonizarem uma atividade especial no Parque Municipal Jaboti.<\/p>\n\n\n\n<p>Assessorados por t\u00e9cnicos municipais, o grupo realizou o plantio de mudas de ara\u00e7\u00e1, pitanga, amora, ameixa amarela e gabiroba, em uma \u00e1rea abaixo do Bosque e Memorial em Homenagem \u00e0s V\u00edtimas da Covid-19, que foi estruturado em janeiro de 2021 (anivers\u00e1rio de 77 anos de Apucarana) com o plantio de 77 \u00e1rvores nativas ao centro e 77 cerejeiras-ornamentais no entorno, simbolizando o abra\u00e7o da popula\u00e7\u00e3o e dos profissionais da sa\u00fade \u00e0s fam\u00edlias.<\/p>\n\n\n\n<p>Acostumada a mexer com a terra, Cirema da Cruz de Oliveira, teve a honra de realizar o primeiro plantio. A esp\u00e9cie escolhida foi o ara\u00e7\u00e1. \u201cMantenho v\u00e1rias \u00e1rvores frut\u00edferas no meu quintal e hoje plantar em um parque est\u00e1 sendo uma experi\u00eancia especial e diferente. Saber que em pouco tempo dar\u00e1 frutos para quem por aqui passar, \u00e9 uma alegria\u201d, disse a idosa. Moradora de Apucarana h\u00e1 64 anos, Vani da Silva conta que chegou na cidade com 11 anos vindo do interior de Minas Gerais. \u201cViemos morar aqui pr\u00f3ximo, mas na \u00e9poca s\u00f3 existia o c\u00f3rrego Jaboti, bem pequeno. N\u00e3o havia esse lago, o parque. Estou muito feliz em voltar e poder participar deste plantio\u201d, afirmou.<\/p>\n\n\n\n<p>O Centro Dia da Pessoa Idosa oferece atendimento especializado a pessoas em situa\u00e7\u00e3o de vulnerabilidade social que possuem algum grau de depend\u00eancia de cuidados. Na a\u00e7\u00e3o ambiental, o prefeito Rodolfo Mota esteve representado pelos secret\u00e1rios Fab\u00edola Carrero (Assist\u00eancia Social), Diego Silva (Meio Ambiente) e Wendel Metta (Servi\u00e7os P\u00fablicos). \u201cNo \u00faltimo domingo \u2013 21 de setembro \u2013 comemoramos o Dia da \u00c1rvore ent\u00e3o, em conjunto com a Secretaria da Assist\u00eancia Social, pensamos nesta a\u00e7\u00e3o. \u00c9 uma satisfa\u00e7\u00e3o para essa gest\u00e3o, que trabalha para cuidar das pessoas e construir o futuro, proporcionar este momento onde agradecermos, em nome da popula\u00e7\u00e3o de Apucarana, tudo que voc\u00eas idosos fizeram e, como nesta tarde, mostram o quanto ainda podem contribuir. Essas \u00e1rvores que est\u00e3o plantando v\u00e3o ficar para as pr\u00f3ximas gera\u00e7\u00f5es, para as pessoas que visitarem o parque, al\u00e9m de seus frutos servirem de alimento para os passarinhos. \u00c9 mais um legado que deixam para a cidade\u201d, destacou o secret\u00e1rio Diego Silva.<\/p>\n\n\n\n<p>A secret\u00e1ria da Assist\u00eancia Social, Fab\u00edola Carrero, tamb\u00e9m enalteceu o momento, pensado em conjunto com a equipe t\u00e9cnica do Centro Dia da Pessoa Idosa. \u201cO Parque Jaboti \u00e9 um cart\u00e3o postal de Apucarana e \u00e9 um orgulho para a gente deixar um pedacinho nosso nesta terra. Quero agradecer todos os servidores do Centro Dia por proporcionarem esses momentos para nossos idosos, garantindo acesso a direitos como lazer, cultura, educa\u00e7\u00e3o e contato com o meio ambiente\u201d, salientou a secret\u00e1ria, agradecendo ainda a parceria das secretarias de Meio Ambiente e de Servi\u00e7os P\u00fablicos.<\/p>\n\n\n\n<p>Ao final da atividade ambiental, todos os idosos foram presenteados com uma muda de cuf\u00e9ria, tamb\u00e9m conhecida como falsa \u00c9rica, uma planta muito apreciada por florescer o ano todo e exigir pouca manuten\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assessorados por t\u00e9cnicos municipais, o grupo realizou o plantio de mudas de ara\u00e7\u00e1, pitanga, amora, ameixa amarela e gabiroba, em uma \u00e1rea abaixo do Bosque e Memorial em Homenagem \u00e0s V\u00edtimas da Covid-19 \u201cNa velhice ainda dar\u00e3o frutos, ser\u00e3o vi\u00e7osos e florescentes, para anunciar que o Senhor \u00e9 reto.\u201d Com a mensagem b\u00edblica do Salmos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1.jpg",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-768x512.jpg",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1.jpg",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1.jpg",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1.jpg",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-400x300.jpg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-400x600.jpg",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-400x400.jpg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-400x267.jpg",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-700x500.jpg",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-700x683.jpg",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-700x467.jpg",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-1000x600.jpg",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-1024x600.jpg",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/09\/dia-da-arvore-12-1024x683-1-100x100.jpg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7312"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7314"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}