{"id":708,"date":"2023-09-25T18:56:15","date_gmt":"2023-09-25T18:56:15","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=708"},"modified":"2023-09-25T18:56:16","modified_gmt":"2023-09-25T18:56:16","slug":"jovem-que-matou-casal-de-idosos-e-condenado-a-86-anos-de-prisao","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/25\/jovem-que-matou-casal-de-idosos-e-condenado-a-86-anos-de-prisao\/","title":{"rendered":"Jovem que matou casal de idosos \u00e9 condenado a 86 anos de pris\u00e3o"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O crime ocorreu na Rua Humberto Contato, nas proximidades do Col\u00e9gio Polivalente, em mar\u00e7o deste ano<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Armando-Guarnieri-de-79-anos-e-Maria-de-Lourdes-65-00795523-0-202309251535-edited-1.webp\" alt=\"\" class=\"wp-image-711\" style=\"width:394px;height:701px\" width=\"394\" height=\"701\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Armando-Guarnieri-de-79-anos-e-Maria-de-Lourdes-65-00795523-0-202309251535-edited-1.webp 313w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Armando-Guarnieri-de-79-anos-e-Maria-de-Lourdes-65-00795523-0-202309251535-edited-1-169x300.webp 169w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/><\/figure>\n\n\n\n<p>Gustavo Henrique Palhinha da Rocha, de 23 anos, um dos jovens envolvidos no latroc\u00ednio de dois idosos em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\">Apucarana<\/a>, no Norte do Paran\u00e1, ocorrido em 15 de mar\u00e7o de 2023, foi condenado a 86 anos e oito meses de pris\u00e3o em regime fechado, al\u00e9m de 42 dias de multa. A senten\u00e7a foi proferida pelo juiz Jos\u00e9 Roberto Silv\u00e9rio, da 2\u00aa Vara Criminal, na \u00faltima quinta-feira (21).\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana\/casal-de-idosos-e-espancado-dentro-de-casa-e-um-morre-em-apucarana-738503?d=1\">O casal foi espancado dentro de casa.<\/a><\/p>\n\n\n\n<p>O crime ocorreu na Rua Humberto Contato, nas proximidades do Col\u00e9gio Polivalente Carlos Domingos Silva. Gustavo Henrique Palhinha da Rocha e um outro jovem, Renan Anderson da Silva, de 24 anos, invadiram a resid\u00eancia do casal Armando Guarnieri, de 79 anos, e Maria de Lourdes, 65 anos.<\/p>\n\n\n\n<p>Durante o assalto, os idosos foram espancados com chutes e &#8220;pis\u00f5es&#8221; na cabe\u00e7a, segundo a investiga\u00e7\u00e3o policial. Para entrar na casa, os autores do crime pularam o muro e arrombaram a porta. Ap\u00f3s agredir o casal, eles ainda ficaram na casa at\u00e9 o final da madrugada, onde comeram e at\u00e9 tomaram banho.<\/p>\n\n\n\n<p>Armando Guarnieri morreu no local, enquanto Maria de Lourdes n\u00e3o resistiu aos ferimentos e morreu tr\u00eas dias depois no Hospital da provid\u00eancia. Os criminosos praticaram o crime para roubar um celular, um rel\u00f3gio, R$ 150 em dinheiro e chocolates. Os itens furtados e o dinheiro foram trocados por drogas, segundo a Pol\u00edcia Civil.<\/p>\n\n\n\n<p>Gustavo Henrique Palhinha da Rocha foi preso uma semana depois do crime no Jardim Casa Grande. J\u00e1 Renan Anderson da Silva\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana\/segundo-envolvido-em-latrocinio-morre-apos-confronto-com-a-pm-740774?d=1\">morreu no mesmo dia da pris\u00e3o do colega em confronto<\/a>\u00a0com a Pol\u00edcia Militar (PM). Ele foi localizado Residencial Texas e teria reagido \u00e0 abordagem dos policiais.<\/p>\n\n\n\n<p>Na senten\u00e7a, o juiz destacou o desrespeito \u00e0 vida humana pelo r\u00e9u. \u201c<em>O motivo do delito revela-se na busca da vantagem patrimonial sem o desempenho da atividade laborativa honesta em detrimento dos bens alheios. Ocorre que, no caso em an\u00e1lise, verifica-se exasperada repugn\u00e2ncia e extremo desvalor pela vida humana, pois o acusado ceifou a vida de duas v\u00edtimas idosas em excessiva agressividade com o interesse de adquirir drogas<\/em>\u201d.<\/p>\n\n\n\n<p>O magistrado tamb\u00e9m citou a repercuss\u00e3o do crime. \u201c<em>No concernente \u00e0s consequ\u00eancias, foram graves, j\u00e1 que demonstraram um demasiado abalo ps\u00edquico sofrido pelos parentes das v\u00edtimas, e pela comunidade pr\u00f3xima \u00e0s mesmas, em raz\u00e3o da forma em que ceifaram suas vidas, causando, ainda, grande como\u00e7\u00e3o e revolta na cidade, j\u00e1 que se trata de Comarca de porte mediano, tendo a not\u00edcia tomado grande repercuss\u00e3o<\/em>.\u201d<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Ftnonline.uol.com.br%2F_%2F795523\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O crime ocorreu na Rua Humberto Contato, nas proximidades do Col\u00e9gio Polivalente, em mar\u00e7o deste ano Gustavo Henrique Palhinha da Rocha, de 23 anos, um dos jovens envolvidos no latroc\u00ednio de dois idosos em\u00a0Apucarana, no Norte do Paran\u00e1, ocorrido em 15 de mar\u00e7o de 2023, foi condenado a 86 anos e oito meses de pris\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-708","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=708"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/708\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}