{"id":7005,"date":"2025-06-20T04:28:05","date_gmt":"2025-06-20T01:28:05","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=7005"},"modified":"2025-06-21T04:28:43","modified_gmt":"2025-06-21T01:28:43","slug":"apucarana-chega-a-46-de-cobertura-e-supera-media-nacional-de-vacinacao-contra-influenza-em-grupos-prioritarios","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/06\/20\/apucarana-chega-a-46-de-cobertura-e-supera-media-nacional-de-vacinacao-contra-influenza-em-grupos-prioritarios\/","title":{"rendered":"Apucarana chega a 46% de cobertura e supera m\u00e9dia nacional de vacina\u00e7\u00e3o contra Influenza em grupos priorit\u00e1rios"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"662\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png\" alt=\"\" class=\"wp-image-7006\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-300x194.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-768x497.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-400x259.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-700x453.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-600x388.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Cerca de 10 mil pessoas foram imunizadas contra o v\u00edrus da Influenza em Apucarana entre os dias 14 de abril e 14 de junho. Al\u00e9m da aplica\u00e7\u00e3o nas unidades b\u00e1sicas de sa\u00fade (UBSs), a Autarquia Municipal de Sa\u00fade (AMS) adotou, a partir de meados de abril, estrat\u00e9gias de busca ativa com a instala\u00e7\u00e3o de postos volantes de vacina\u00e7\u00e3o em locais de grande circula\u00e7\u00e3o de pessoas.<\/p>\n\n\n\n<p>Segundo balan\u00e7o divulgado nesta quarta-feira (18\/06) pelo prefeito Rodolfo Mota, somente nos \u00faltimos 30 dias foram aplicadas 7.224 doses em pessoas de todas as faixas et\u00e1rias, elevando o \u00edndice de cobertura vacinal de Apucarana \u2014 que at\u00e9 ent\u00e3o era inferior a 20% entre os grupos priorit\u00e1rios (crian\u00e7as de seis meses at\u00e9 5 anos, 11 meses e 29 dias, gestantes e idosos) \u2014 para os atuais 46,24%, patamar superior \u00e0 m\u00e9dia do Brasil (39,18%) e em empate t\u00e9cnico com a m\u00e9dia do Paran\u00e1 (46,23%).<\/p>\n\n\n\n<p>\u201cAl\u00e9m destas mais de 7,2 mil pessoas vacinadas em a\u00e7\u00f5es executadas na \u00e1rea central, terminal urbano, Espa\u00e7o das Feiras, com\u00e9rcio e ind\u00fastrias (Trabalhador Vacinado), col\u00e9gios, escolas, CMEIs, supermercados, feira do produtor, entre outros locais, estima-se que pelo menos outras 3 mil foram imunizadas diretamente na aten\u00e7\u00e3o b\u00e1sica, nas UBSs com sala de vacina\u201d, informa o prefeito Rodolfo Mota.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio municipal da Sa\u00fade, m\u00e9dico Guilherme de Paula, a efic\u00e1cia das a\u00e7\u00f5es de busca ativa ficou evidente ao ponto de quase zerar o estoque da autarquia. \u201cNesta quinta-feira, nossa equipe da Vigil\u00e2ncia em Sa\u00fade esteve na 16\u00aa Regional de Sa\u00fade para buscar um novo lote com 5 mil doses, garantindo a continuidade das a\u00e7\u00f5es volantes\u201d, relata o secret\u00e1rio.<\/p>\n\n\n\n<p>Ele alerta, no entanto, que a cobertura vacinal entre os grupos-alvo ainda est\u00e1 abaixo do ideal. \u201cSolicitamos que pais e respons\u00e1veis levem as crian\u00e7as com idade at\u00e9 5 anos, 11 meses e 29 dias para serem imunizadas. O apelo tamb\u00e9m se estende \u00e0s gestantes e aos idosos\u201d, refor\u00e7a de Paula.<\/p>\n\n\n\n<p>O coordenador da Vigil\u00e2ncia em Sa\u00fade da AMS, enfermeiro Luciano Simpl\u00edcio Sobrinho, informa que, apesar do refor\u00e7o no estoque da autarquia, que contava com apenas 200 doses, todas as 28 unidades b\u00e1sicas com sala de vacina\u00e7\u00e3o est\u00e3o abastecidas. Segundo ele, devido ao feriado de Corpus Christi, as a\u00e7\u00f5es de busca ativa estar\u00e3o pausadas nesta semana, retornando na pr\u00f3xima semana. \u201cNos dias 26 e 27 de junho, das 18 \u00e0s 20h30, haver\u00e1 vacina\u00e7\u00e3o nos supermercados Muffato, Amig\u00e3o e Max Atacadista. No s\u00e1bado, dia 28 de junho, das 13 \u00e0s 17 horas, a imuniza\u00e7\u00e3o ser\u00e1 realizada nas UBSs Ant\u00f4nio Sachelli (Colonial), Eunice Penharbel (Sumatra) e Leopoldo Hartwig Jr. (Vila Nova)\u201d, informa o coordenador.<\/p>\n\n\n\n<p>Ele destaca ainda que, seguindo determina\u00e7\u00e3o do prefeito Rodolfo Mota e do secret\u00e1rio Guilherme de Paula, a AMS tem intensificado a busca ativa dos n\u00e3o vacinados, principalmente dos grupos priorit\u00e1rios, al\u00e9m de estreitar parcerias com escolas, igrejas, conselhos locais, CRAS e outros segmentos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 10 mil pessoas foram imunizadas contra o v\u00edrus da Influenza em Apucarana entre os dias 14 de abril e 14 de junho. Al\u00e9m da aplica\u00e7\u00e3o nas unidades b\u00e1sicas de sa\u00fade (UBSs), a Autarquia Municipal de Sa\u00fade (AMS) adotou, a partir de meados de abril, estrat\u00e9gias de busca ativa com a instala\u00e7\u00e3o de postos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png",1024,662,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-300x194.png",300,194,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-768x497.png",768,497,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png",860,556,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png",1024,662,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56.png",1024,662,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-400x259.png",400,259,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-700x662.png",700,662,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-700x453.png",700,453,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-600x388.png",600,388,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-56-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=7005"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/7005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/7006"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=7005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=7005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=7005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}