{"id":6890,"date":"2025-06-05T00:57:33","date_gmt":"2025-06-04T21:57:33","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6890"},"modified":"2025-06-06T00:57:46","modified_gmt":"2025-06-05T21:57:46","slug":"prefeitura-firma-convenio-com-a-fap-e-garante-descontos-em-cursos-de-graduacao-para-servidores-e-dependentes","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/06\/05\/prefeitura-firma-convenio-com-a-fap-e-garante-descontos-em-cursos-de-graduacao-para-servidores-e-dependentes\/","title":{"rendered":"Prefeitura firma conv\u00eanio com a FAP e garante descontos em cursos de gradua\u00e7\u00e3o para servidores e dependentes"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png\" alt=\"\" class=\"wp-image-6891\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Funcion\u00e1rios p\u00fablicos municipais, efetivos ou comissionados, e estagi\u00e1rios vinculados \u00e0 Prefeitura de Apucarana e suas autarquias ter\u00e3o direito a um desconto de 30% em todas as mensalidades at\u00e9 a conclus\u00e3o da forma\u00e7\u00e3o acad\u00eamica, caso ingressem em algum dos 12 cursos de gradua\u00e7\u00e3o presencial da Faculdade de Apucarana (FAP) neste segundo semestre.<\/p>\n\n\n\n<p>O benef\u00edcio, que tamb\u00e9m \u00e9 estendido a familiares, est\u00e1 previsto em um conv\u00eanio firmado nesta quinta-feira (05\/06) entre a Prefeitura de Apucarana e o Centro de Ensino Superior de Apucarana (Cesuap), entidade mantenedora da faculdade. O documento foi assinado em ato no gabinete municipal pelo prefeito Rodolfo Mota, pelo diretor-executivo e Acad\u00eamico, Paulo Henrique Pavolak e pelo diretor de Opera\u00e7\u00f5es da FAP, F\u00e1bio Miquelin. \u201cA concess\u00e3o \u00e9 para todos os 12 cursos de gradua\u00e7\u00e3o presencial. Al\u00e9m disto, neste s\u00e1bado (07\/06), teremos o \u201cDia D\u201d de matr\u00edculas, das 8 \u00e0s 20 horas, especialmente voltado aos servidores p\u00fablicos municipais, estagi\u00e1rios e familiares interessados, onde al\u00e9m do desconto previsto (30%) ser\u00e1 concedido um b\u00f4nus de mais 15% nas mensalidades para os dois primeiros semestres letivos (2025\/2 e 2026\/1)\u201d, informou Michelin.<\/p>\n\n\n\n<p>Segundo o diretor-executivo Paulo Pavolak, outra vantagem prevista no conv\u00eanio \u00e9 o valor da parcela referente a julho (matr\u00edcula). \u201cO servidor, estagi\u00e1rio ou familiar benefici\u00e1rio pagar\u00e1 R$ 399,00 no primeiro m\u00eas, exceto o curso de Odontologia, cujo valor da parcela referente a julho ser\u00e1 de R$ 599,00\u201d, disse Pavolak, agradecemos a prefeitura, na pessoa do prefeito Rodolfo Mota, pela parceria.<\/p>\n\n\n\n<p>Os cursos de gradua\u00e7\u00e3o da FAP s\u00e3o: Administra\u00e7\u00e3o, Direito, Biomedicina, Engenharia Civil, Engenharia Agron\u00f4mica, Engenharia Ambiental, Fisioterapia, Enfermagem, Nutri\u00e7\u00e3o, Sistemas de Informa\u00e7\u00e3o, Psicologia e Odontologia. \u201c\u00c9 mais uma boa not\u00edcia para nossos servidores, estagi\u00e1rios e familiares que j\u00e1 conclu\u00edram o ensino m\u00e9dio. Este conv\u00eanio representa uma excelente oportunidade para quem deseja iniciar uma gradua\u00e7\u00e3o com condi\u00e7\u00f5es mais acess\u00edveis. Parabenizamos a FAP pela iniciativa, que facilita o acesso ao ensino superior e incentiva a qualifica\u00e7\u00e3o profissional\u201d, concluiu o prefeito Rodolfo Mota.<\/p>\n\n\n\n<p><strong>Confira as vantagens do conv\u00eanio<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td>Curso<\/td><td>Valor original da mensalidade<\/td><td>Com o conv\u00eanio (30%)<\/td><\/tr><\/thead><tbody><tr><td>Direito<\/td><td>R$ 1.023,98<\/td><td>R$ 609,27<\/td><\/tr><tr><td>Administra\u00e7\u00e3o<\/td><td>R$ 706,23<\/td><td>R$ 420,21<\/td><\/tr><tr><td>Fisioterapia<\/td><td>R$ 1.269,98<\/td><td>R$ 755,64<\/td><\/tr><tr><td>Enfermagem<\/td><td>R$ 1.054,73<\/td><td>R$ 627,56<\/td><\/tr><tr><td>Nutri\u00e7\u00e3o<\/td><td>R$ 1.023,98<\/td><td>R$ 609,27<\/td><\/tr><tr><td>Psicologia<\/td><td>R$ 1.126,48<\/td><td>R$ 670,26<\/td><\/tr><tr><td>Sistemas de Informa\u00e7\u00e3o<\/td><td>R$ 839,48<\/td><td>R$ 499,49<\/td><\/tr><tr><td>Biomedicina<\/td><td>R$ 1.126,48<\/td><td>R$ 670,26<\/td><\/tr><tr><td>Odontologia<\/td><td>R$ 2.438,48<\/td><td>R$ 1.450,90<\/td><\/tr><tr><td>Engenharia Ambiental<\/td><td>R$ 952,23<\/td><td>R$ 566,58<\/td><\/tr><tr><td>Agronomia<\/td><td>R$ 1.634,88<\/td><td>R$ 972,75<\/td><\/tr><tr><td>Engenharia Civil<\/td><td>R$ 1.228,98<\/td><td>R$ 731,24<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Funcion\u00e1rios p\u00fablicos municipais, efetivos ou comissionados, e estagi\u00e1rios vinculados \u00e0 Prefeitura de Apucarana e suas autarquias ter\u00e3o direito a um desconto de 30% em todas as mensalidades at\u00e9 a conclus\u00e3o da forma\u00e7\u00e3o acad\u00eamica, caso ingressem em algum dos 12 cursos de gradua\u00e7\u00e3o presencial da Faculdade de Apucarana (FAP) neste segundo semestre. O benef\u00edcio, que tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-21-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6890"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6891"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}