{"id":6852,"date":"2025-06-02T05:02:01","date_gmt":"2025-06-02T02:02:01","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6852"},"modified":"2025-06-03T05:02:10","modified_gmt":"2025-06-03T02:02:10","slug":"apucarana-anuncia-implantacao-historica-do-pronto-atendimento-infantil-e-avanca-na-area-da-saude","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/06\/02\/apucarana-anuncia-implantacao-historica-do-pronto-atendimento-infantil-e-avanca-na-area-da-saude\/","title":{"rendered":"Apucarana anuncia implanta\u00e7\u00e3o hist\u00f3rica do Pronto Atendimento Infantil e avan\u00e7a na \u00e1rea da Sa\u00fade"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png\" alt=\"\" class=\"wp-image-6853\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O prefeito Rodolfo Mota anunciou, em entrevista coletiva na manh\u00e3 desta segunda-feira (2\/6), que Apucarana ter\u00e1 um Pronto Atendimento Infantil (PAI). A nova unidade, destinada ao atendimento exclusivo de crian\u00e7as em casos de urg\u00eancia e emerg\u00eancia, ser\u00e1 instalada no futuro Hospital de Apucarana, pr\u00e9dio onde atualmente funciona o Centro de Atendimento 18 Horas da Dengue, na Rua Miguel Sime\u00e3o, perto do shopping.<\/p>\n\n\n\n<p>O an\u00fancio representa um avan\u00e7o hist\u00f3rico para a sa\u00fade do munic\u00edpio. \u201cCom a expressiva redu\u00e7\u00e3o dos casos de dengue em Apucarana, encerraremos as atividades do Pronto Atendimento 18 Horas a partir da pr\u00f3xima semana. No mesmo local, ser\u00e1 inaugurado o Pronto Atendimento Infantil, que funcionar\u00e1 das 7h \u00e0s 22h, de domingo a domingo, contando com pediatras e m\u00e9dicos com experi\u00eancia no atendimento infantil. A entrada ser\u00e1 pela porta principal do pr\u00e9dio. Fora do hor\u00e1rio de atendimento do PAI, as crian\u00e7as continuar\u00e3o a ser atendidas na UPA\u201d, afirmou Rodolfo Mota.<\/p>\n\n\n\n<p>O prefeito acrescentou que Apucarana esperava por essa conquista h\u00e1 mais de vinte anos. \u201cNossa equipe est\u00e1 finalizando os preparativos, organizando a equipe de servidores e definindo os aspectos financeiros. A previs\u00e3o \u00e9 de que o PAI seja inaugurado dentro de quinze a vinte dias\u201d, adiantou.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Sa\u00fade, Dr. Guilherme de Paula, destacou que a cria\u00e7\u00e3o do PAI visa oferecer um servi\u00e7o de sa\u00fade de melhor qualidade para as crian\u00e7as da cidade. \u201cAtualmente, os pais precisam levar seus filhos \u00e0 Unidade de Pronto Atendimento (UPA) em casos de urg\u00eancia e emerg\u00eancia. Com a inaugura\u00e7\u00e3o da nova unidade, esses atendimentos ser\u00e3o realizados no PAI. A Cl\u00ednica da Crian\u00e7a receber\u00e1 melhorias e continuar\u00e1 funcionando, mas passar\u00e1 a atender somente consultas eletivas, agendadas previamente e encaminhadas pelos m\u00e9dicos das Unidades B\u00e1sicas de Sa\u00fade (UBS)\u201d, explicou.<\/p>\n\n\n\n<p>Estiveram presentes na coletiva a primeira-dama Karine Mota, os vereadores Danylo Acioli (presidente da C\u00e2mara), Mois\u00e9s Tavares (l\u00edder do prefeito no Legislativo), Tiago Cordeiro, Luciano Facchiano, Gabriel Caldeira, Adan Lenharo, Eliana Rocha, Guilherme Livoti, Luiz Vila Boas e Sidnei da Levelimp, al\u00e9m de representantes de diversos ve\u00edculos de comunica\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Rodolfo Mota anunciou, em entrevista coletiva na manh\u00e3 desta segunda-feira (2\/6), que Apucarana ter\u00e1 um Pronto Atendimento Infantil (PAI). A nova unidade, destinada ao atendimento exclusivo de crian\u00e7as em casos de urg\u00eancia e emerg\u00eancia, ser\u00e1 instalada no futuro Hospital de Apucarana, pr\u00e9dio onde atualmente funciona o Centro de Atendimento 18 Horas da Dengue, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-9-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6852"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6853"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}