{"id":6831,"date":"2025-05-30T01:31:18","date_gmt":"2025-05-29T22:31:18","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6831"},"modified":"2025-06-01T01:31:26","modified_gmt":"2025-05-31T22:31:26","slug":"servidores-aniversariantes-de-maio-sao-homenageados-com-cafe-da-manha-no-gabinete-do-prefeito","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/05\/30\/servidores-aniversariantes-de-maio-sao-homenageados-com-cafe-da-manha-no-gabinete-do-prefeito\/","title":{"rendered":"Servidores aniversariantes de maio s\u00e3o homenageados com caf\u00e9 da manh\u00e3 no gabinete do prefeito"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png\" alt=\"\" class=\"wp-image-6832\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Apucarana prestou, nesta sexta-feira (30\/5), uma homenagem aos servidores p\u00fablicos municipais que celebram anivers\u00e1rio em maio. Cerca de 30 funcion\u00e1rios com mais de 55 anos de idade, representando todos os aniversariantes do m\u00eas, participaram de um caf\u00e9 da manh\u00e3 especial no gabinete do prefeito Rodolfo Mota, com a presen\u00e7a do vice-prefeito Marcos da Vila Reis.<\/p>\n\n\n\n<p>A iniciativa, realizada desde o in\u00edcio deste ano, ocorre sempre no \u00faltimo dia \u00fatil de cada m\u00eas. O objetivo \u00e9 reconhecer e valorizar os servidores que atuam diretamente no atendimento \u00e0 popula\u00e7\u00e3o. \u201cEssa singela homenagem \u00e9 a forma que encontramos de agradecer a quem est\u00e1 na linha de frente do servi\u00e7o p\u00fablico. Eu gostaria de parabenizar pessoalmente todos os mais de 300 aniversariantes do m\u00eas, mas isso n\u00e3o \u00e9 vi\u00e1vel. Por isso, convidamos aqueles com mais tempo de vida e de servi\u00e7o prestado para esse momento especial\u201d, destacou o prefeito Rodolfo Mota.<\/p>\n\n\n\n<p>Durante o encontro, o vice-prefeito conduziu um momento de espiritualidade, com uma b\u00ean\u00e7\u00e3o aos aniversariantes. \u201c\u00c9 muito gratificante poder conversar com os nossos colaboradores e conhecer suas trajet\u00f3rias. Esta homenagem tem o prop\u00f3sito de refor\u00e7ar o quanto valorizamos o trabalho de cada servidor, essencial para o bom funcionamento do munic\u00edpio\u201d, afirmou Marcos da Vila Reis.<\/p>\n\n\n\n<p>O evento reuniu representantes de diversos setores da administra\u00e7\u00e3o direta e indireta, como a Superintend\u00eancia de Recursos Humanos, o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU), o P\u00e1tio de M\u00e1quinas, os Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs), Escolas Municipais, Unidades B\u00e1sicas de Sa\u00fade (UBS) e a Autarquia Municipal de Servi\u00e7os Funer\u00e1rios.<\/p>\n\n\n\n<p>Entre os homenageados, a servidora Alice Ribeiro de Oliveira, com 45 anos de atua\u00e7\u00e3o no servi\u00e7o p\u00fablico, relembrou o in\u00edcio de sua trajet\u00f3ria. \u201cEntrei na Prefeitura em 31 de janeiro de 1980, quando o prefeito era Voldimir Mir\u00e3o Maistrovicz. Sempre trabalhei na Superintend\u00eancia de Recursos Humanos. Naquela \u00e9poca, us\u00e1vamos m\u00e1quina de escrever. Hoje, com computadores e internet, tudo ficou mais \u00e1gil\u201d, contou.<\/p>\n\n\n\n<p>A professora Maria Luceny de Aguiar Batista, da Escola Municipal F\u00e1bio Henrique da Silva, viveu uma dupla comemora\u00e7\u00e3o. \u201cFiz anivers\u00e1rio na quarta-feira (28) e hoje encerro meu ciclo profissional, pois estou me aposentando. Em todos esses anos, \u00e9 a primeira vez que entro no gabinete do prefeito\u201d, revelou.<\/p>\n\n\n\n<p>J\u00e1 a professora S\u00edlvia Elo\u00edsa da Silva Avanci, que leciona h\u00e1 37 anos na Escola Vereador Jos\u00e9 Ramos de Oliveira, no distrito de Pirap\u00f3, emocionou-se ao comentar sua trajet\u00f3ria. \u201cTenho tempo suficiente para me aposentar, mas continuo na ativa porque amo o que fa\u00e7o\u201d, declarou.<\/p>\n\n\n\n<p>Entre os servidores homens, o assessor t\u00e9cnico Amilton Prijma, da Superintend\u00eancia de Recursos Humanos, destacou-se pelo longo tempo de servi\u00e7o: 26 anos. \u201cN\u00e3o me lembro de ter recebido uma homenagem como essa em gest\u00f5es anteriores. \u00c0s vezes, um simples \u2018obrigado\u2019 vale mais que qualquer gratifica\u00e7\u00e3o financeira\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana prestou, nesta sexta-feira (30\/5), uma homenagem aos servidores p\u00fablicos municipais que celebram anivers\u00e1rio em maio. Cerca de 30 funcion\u00e1rios com mais de 55 anos de idade, representando todos os aniversariantes do m\u00eas, participaram de um caf\u00e9 da manh\u00e3 especial no gabinete do prefeito Rodolfo Mota, com a presen\u00e7a do vice-prefeito Marcos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/06\/image-2-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6831"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6832"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}