{"id":6769,"date":"2025-05-26T00:19:26","date_gmt":"2025-05-25T21:19:26","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6769"},"modified":"2025-05-27T00:19:34","modified_gmt":"2025-05-26T21:19:34","slug":"vacinacao-em-supermercados-e-no-espaco-das-feiras-imuniza-11-mil-apucaranenses-contra-a-gripe","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/05\/26\/vacinacao-em-supermercados-e-no-espaco-das-feiras-imuniza-11-mil-apucaranenses-contra-a-gripe\/","title":{"rendered":"Vacina\u00e7\u00e3o em supermercados e no Espa\u00e7o das Feiras\u00a0imuniza 1,1 mil apucaranenses contra a gripe"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"731\" height=\"1024\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png\" alt=\"\" class=\"wp-image-6770\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png 731w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-214x300.png 214w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-400x560.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-700x981.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-600x840.png 600w\" sizes=\"(max-width: 731px) 100vw, 731px\" \/><\/figure>\n\n\n\n<p>A estrat\u00e9gia de busca ativa com vacina\u00e7\u00e3o fora das unidades b\u00e1sicas de sa\u00fade (UBSs) tem alcan\u00e7ado bons resultados em Apucarana. No \u00faltimo s\u00e1bado (24\/05), 770 doses da vacina contra a gripe foram aplicadas pelas equipes da Autarquia Municipal de Sa\u00fade (AMS) em postos volantes instalados em supermercados (Muffato, Amig\u00e3o e Box Atacadista) e tamb\u00e9m no Espa\u00e7o das Feiras.<\/p>\n\n\n\n<p>Somadas \u00e0s aplica\u00e7\u00f5es realizadas na quinta e sexta-feira, um total de 1,1 mil apucaranenses, com idade acima de seis meses, foi imunizado contra a influenza por meio da estrat\u00e9gia. Com isso, Apucarana atinge 34,96% de cobertura vacinal. De acordo com o secret\u00e1rio municipal da Sa\u00fade, m\u00e9dico Guilherme de Paula, na a\u00e7\u00e3o extramuros foram vacinadas 41 crian\u00e7as, 111 idosos e 948 pessoas da popula\u00e7\u00e3o geral. \u201cTivemos uma boa procura pela vacina nesses postos volantes, mas precisamos de um maior engajamento da popula\u00e7\u00e3o. Apenas 21,13% das crian\u00e7as do p\u00fablico-alvo (menores de 6 anos) foram imunizadas at\u00e9 o momento. O n\u00famero de gestantes tamb\u00e9m \u00e9 baixo, apenas 27,65%, e, quanto aos idosos, 40,22% procuraram a vacina\u201d, detalha o secret\u00e1rio, ressaltando que a imuniza\u00e7\u00e3o \u00e9 essencial para o controle da circula\u00e7\u00e3o dos v\u00edrus respirat\u00f3rios, especialmente da Influenza A e o v\u00edrus sincicial respirat\u00f3rio (VSR), bem como evitar o agravamento da doen\u00e7a em casos de cont\u00e1gio.<\/p>\n\n\n\n<p>O enfermeiro Luciano Simpl\u00edcio Sobrinho, coordenador da Vigil\u00e2ncia em Sa\u00fade da AMS, confirma que a a\u00e7\u00e3o de vacina\u00e7\u00e3o em supermercados e no Espa\u00e7o das Feiras continua. \u201cNas quintas e sextas-feiras, o hor\u00e1rio de atendimento nos mercados (Muffato \u2013 Igrejinha \u2013, Amig\u00e3o e Box Atacadista) \u00e9 das 18 \u00e0s 20h30, e, no s\u00e1bado, entre 16 e 20 horas. J\u00e1 no Espa\u00e7o das Feiras, o atendimento acontece somente aos s\u00e1bados, das 8 \u00e0s 12 horas\u201d, afirma Sobrinho, destacando a import\u00e2ncia da apresenta\u00e7\u00e3o da carteirinha de vacina\u00e7\u00e3o e de um documento de identifica\u00e7\u00e3o pessoal no ato da imuniza\u00e7\u00e3o.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota assinala que o munic\u00edpio segue trabalhando para levar sa\u00fade \u00e0 popula\u00e7\u00e3o. \u201cA partir de agora, nossas equipes das unidades b\u00e1sicas de sa\u00fade tamb\u00e9m ir\u00e3o intensificar a busca ativa de pessoas dos grupos priorit\u00e1rios e levar a imuniza\u00e7\u00e3o contra a gripe para dentro das empresas localizadas em suas \u00e1reas de abrang\u00eancia\u201d, informa.<\/p>\n\n\n\n<p>Outra estrat\u00e9gia ser\u00e1 a vacina\u00e7\u00e3o aos s\u00e1bados em \u00e1reas com maior concentra\u00e7\u00e3o de popula\u00e7\u00e3o socialmente vulner\u00e1vel. Neste m\u00eas de junho, j\u00e1 est\u00e1 confirmada vacina\u00e7\u00e3o no dia 14, das 13 \u00e0s 17 horas, nas UBSs Maria do Caf\u00e9 (Jardim Ponta Grossa), Bolivar Pav\u00e3o (Jardim Am\u00e9rica) e Takaiti Miyadi (Dom Romeu). No dia 28, tamb\u00e9m das 13 \u00e0s 17 horas, a vacina\u00e7\u00e3o ocorrer\u00e1 nas UBSs Ant\u00f4nio Sachelli (Colonial), Eunice Penharbel (Sumatra) e Leopoldo Hartwig Jr. (Vila Nova). \u201c\u00c9 importante sempre salientar que a vacina \u00e9 gratuita e tamb\u00e9m est\u00e1 dispon\u00edvel durante os dias de semana, das 8h \u00e0s 16h30, em todas as unidades com sala de vacina\u00e7\u00e3o\u201d, informa Pablo Saito, coordenador da Vigil\u00e2ncia Epidemiol\u00f3gica da AMS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A estrat\u00e9gia de busca ativa com vacina\u00e7\u00e3o fora das unidades b\u00e1sicas de sa\u00fade (UBSs) tem alcan\u00e7ado bons resultados em Apucarana. No \u00faltimo s\u00e1bado (24\/05), 770 doses da vacina contra a gripe foram aplicadas pelas equipes da Autarquia Municipal de Sa\u00fade (AMS) em postos volantes instalados em supermercados (Muffato, Amig\u00e3o e Box Atacadista) e tamb\u00e9m no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png",731,1024,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-214x300.png",214,300,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png",731,1024,false],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png",731,1024,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png",731,1024,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92.png",731,1024,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-400x560.png",400,560,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-700x981.png",700,981,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-731x600.png",731,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-731x600.png",731,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-600x840.png",600,840,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-92-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6769"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6770"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}