{"id":6674,"date":"2025-05-16T12:20:00","date_gmt":"2025-05-16T09:20:00","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6674"},"modified":"2025-05-17T02:14:06","modified_gmt":"2025-05-16T23:14:06","slug":"secretario-carboni-libera-para-apucarana-r-500-mil-do-fundo-da-infancia-e-adolescencia","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/05\/16\/secretario-carboni-libera-para-apucarana-r-500-mil-do-fundo-da-infancia-e-adolescencia\/","title":{"rendered":"Secret\u00e1rio Carboni libera para Apucarana R$ 500 mil do Fundo da Inf\u00e2ncia e Adolesc\u00eancia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png\" alt=\"\" class=\"wp-image-6675\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O secret\u00e1rio de Estado do Desenvolvimento Social e Fam\u00edlia do Paran\u00e1, Rog\u00e9rio Carboni, esteve em Apucarana nesta sexta-feira (16\/05) e liberou R$ 500 mil para a cidade. Os recursos foram anunciados durante reuni\u00e3o da Associa\u00e7\u00e3o dos Munic\u00edpios do Vale do Iva\u00ed (Amuvi) e s\u00e3o oriundos do Fundo para a Inf\u00e2ncia e Adolesc\u00eancia (FIA).<\/p>\n\n\n\n<p>O termo que garante a libera\u00e7\u00e3o dos recursos foi assinado pelo prefeito Rodolfo Mota e pelo vice, Marcos da Vila Reis, que foram os anfitri\u00f5es da reuni\u00e3o da Amuvi. Mota ressaltou que em 130 dias \u00e0 frente da prefeitura de Apucarana j\u00e1 recebeu a visita de oito secret\u00e1rios de Estado. \u201cIsso \u00e9 algo in\u00e9dito na hist\u00f3ria de Apucarana, pois nunca num prazo t\u00e3o curto de tempo vieram a Apucarana tantos secret\u00e1rios. Isso mostra o quanto Apucarana est\u00e1 vivendo um novo momento, de constru\u00e7\u00e3o e de protagonismo\u201d, frisa Rodolfo Mota.<\/p>\n\n\n\n<p>O prefeito de Apucarana tamb\u00e9m disse que est\u00e1 buscando colocar em pr\u00e1tica um ensinamento do governador Carlos Roberto Massa J\u00fanior (Ratinho Junior). \u201cNesses primeiros 130 dias, tenho levado muito a s\u00e9rio algo que o governador ensinou. Ele teve a coragem de fazer o que era necess\u00e1rio, cuidar primeiro do dinheiro dos paranaenses, das finan\u00e7as do Estado, e agora o governador est\u00e1 tendo as condi\u00e7\u00f5es para transformar esse cuidado do dinheiro em cuidado com as pessoas\u201d, assinala Rodolfo Mota.<\/p>\n\n\n\n<p>Os R$500 mil ser\u00e3o repassados na modalidade fundo a fundo e poder\u00e3o ser usados de maneira aut\u00f4noma pelo Munic\u00edpio. \u201cS\u00e3o recursos que poder\u00e3o ser aplicados desde equipamentos para o Conselho Tutelar ou ve\u00edculo, o desenvolvimento de atividades para o fortalecimento de v\u00ednculos, oficinas de bal\u00e9, jiu-jitsu, karat\u00ea, esporte ou a qualifica\u00e7\u00e3o desses adolescentes. Basta fazer o plano de trabalho e o plano de a\u00e7\u00e3o\u201d, refor\u00e7ou Carboni.<\/p>\n\n\n\n<p>A reuni\u00e3o da Amuvi foi coordenada pelo presidente da associa\u00e7\u00e3o e prefeito de Godoy Moreira, Primis de Oliveira. Al\u00e9m de Apucarana, os demais munic\u00edpios que integram a Amuvi tamb\u00e9m foram contemplados com os recursos do FIA, somando cerca de R$ 10 milh\u00f5es. O secret\u00e1rio do Desenvolvimento Social e Fam\u00edlia do Paran\u00e1, afirmou ainda que o governo do Estado disponibiliza recursos tamb\u00e9m por meio de outros fundos, como o dos Direitos do Idoso e o dos Direitos da Pessoa com Defici\u00eancia e solicitou que os munic\u00edpios elaborarem rapidamente os projetos para acessar os recursos dispon\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio de Estado do Desenvolvimento Social e Fam\u00edlia do Paran\u00e1, Rog\u00e9rio Carboni, esteve em Apucarana nesta sexta-feira (16\/05) e liberou R$ 500 mil para a cidade. Os recursos foram anunciados durante reuni\u00e3o da Associa\u00e7\u00e3o dos Munic\u00edpios do Vale do Iva\u00ed (Amuvi) e s\u00e3o oriundos do Fundo para a Inf\u00e2ncia e Adolesc\u00eancia (FIA). O termo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-58-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6674"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6675"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}