{"id":6642,"date":"2025-05-14T00:13:23","date_gmt":"2025-05-13T21:13:23","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6642"},"modified":"2025-05-15T00:13:32","modified_gmt":"2025-05-14T21:13:32","slug":"sesc-de-apucarana-faz-o-lancamento-regional-do-dia-do-desafio","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/05\/14\/sesc-de-apucarana-faz-o-lancamento-regional-do-dia-do-desafio\/","title":{"rendered":"Sesc de Apucarana faz o lan\u00e7amento regional do Dia do Desafio"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1024x682.png\" alt=\"\" class=\"wp-image-6643\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1024x682.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1536x1024.png 1536w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-2048x1365.png 2048w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-700x466.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O Servi\u00e7o Social do Com\u00e9rcio (Sesc), de Apucarana, fez nesta quarta-feira (14\/05) o lan\u00e7amento do Dia do Desafio de 2025 para os 13 munic\u00edpios de abrang\u00eancia da unidade. A mobiliza\u00e7\u00e3o, que busca conscientizar sobre a import\u00e2ncia da pr\u00e1tica regular de atividades f\u00edsicas e que neste ano completa 30 anos, acontece em 28 de maio (\u00faltima quarta-feira do m\u00eas).<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de esportes, Bruno Marchi, representou o prefeito Rodolfo Mota na cerim\u00f4nia. Marchi afirma que eventos como o Dia do Desafio conseguem atingir e conscientizar pessoas sedent\u00e1rias. \u201cNesses eventos de mobiliza\u00e7\u00e3o \u00e9 quando atingimos a pessoa que n\u00e3o estava fazendo nenhuma atividade f\u00edsica. Ao participar de um evento como esse, a pessoa sente prazer e ent\u00e3o vai passar a fazer continuamente a atividade f\u00edsica. Somente 3,5% da popula\u00e7\u00e3o faz exerc\u00edcio f\u00edsico de forma sistematizada. Isso \u00e9 muito pouco em rela\u00e7\u00e3o ao n\u00famero de habitantes de uma cidade e pode ser aumentado com mobiliza\u00e7\u00f5es como o Dia do Desafio\u201d, pontua Marchi.<\/p>\n\n\n\n<p>O gerente-executivo da unidade do Sesc Apucarana, Ronaldo Romano Ficagno, destacou que no ano passado os 13 munic\u00edpios de abrang\u00eancia aderiram \u00e0 mobiliza\u00e7\u00e3o e, por conta disso, receberam uma placa de agradecimento. \u201cA gente sabe que uma pessoa que pratica esporte e que faz atividades regulares, vai menos ao m\u00e9dico e tem menos problemas de ansiedade e de depress\u00e3o. Essa \u00e9 uma mensagem importante que \u00e9 passada pelo Dia do Desafio\u201d, frisa Ficagno.<\/p>\n\n\n\n<p>Durante o evento, a t\u00e9cnica de esportes do Sesc, Nat\u00e1lia Coutinho, repassou informa\u00e7\u00f5es relativas \u00e0 din\u00e2mica do evento. De acordo com ela, neste ano n\u00e3o haver\u00e1 a exig\u00eancia de realizar a atividade por um tempo espec\u00edfico para poder fazer o registro. \u201cEm anos anteriores, tinha um limite de tempo para ser realizada a atividade para estar computando, registrando a participa\u00e7\u00e3o. Este ano n\u00e3o tem mais. Ent\u00e3o, assim que o grupo realizou 3 ou 5 minutos de atividade, pode estar fazendo o registro no site&nbsp;<a href=\"http:\/\/www.sescpr.com.br\/ddd\">www.sescpr.com.br\/ddd<\/a>\u201d, explica, acrescentando que o evento come\u00e7a \u00e0 meia noite do dia 28 de maio e os registros poder\u00e3o ser feitos at\u00e9 \u00e0s 21 horas.<\/p>\n\n\n\n<p><strong>SOLIDARIEDADE \u2013<\/strong>&nbsp;Al\u00e9m do combate ao sedentarismo, o Dia do Desafio tamb\u00e9m incentiva a solidariedade por meio da campanha de arrecada\u00e7\u00e3o de leite. Essa a\u00e7\u00e3o j\u00e1 est\u00e1 acontecendo e se estender\u00e1 at\u00e9 o dia 31 de maio. No ano passado, foram arrecadados 2,2 mil litros e o objetivo em 2025 \u00e9 bater essa meta. Em Apucarana, as doa\u00e7\u00f5es devem ser levadas ao Sesc Apucarana (Rua S\u00e3o Paulo, 95) e no Dia do Desafio (28 de maio) tamb\u00e9m haver\u00e1 um ponto de&nbsp; entrega na Pra\u00e7a Rui Barbosa.<\/p>\n\n\n\n<p>Durante o lan\u00e7amento regional da mobiliza\u00e7\u00e3o, foram veiculadas mensagens de v\u00eddeo do vice-governador e presidente do Sistema Fecom\u00e9rcio no Paran\u00e1, Darci Piana, e de Carlos Alberto de Sotti Lopes, diretor do Sesc Paran\u00e1.<\/p>\n\n\n\n<p>Tamb\u00e9m estiveram presentes na cerim\u00f4nia a conselheira da Fecom\u00e9rcio e presidente do Sindicato do Com\u00e9rcio Varejista de Apucarana (Sivana<em>),&nbsp;<\/em>Aida Santos Assun\u00e7\u00e3o<strong>,&nbsp;<\/strong>Lucas&nbsp;Salvalaggio da Silva, gerente-executivo do Senac Apucarana, e Al\u00e9cio Colombo, representando o N\u00facleo Regional de Educa\u00e7\u00e3o (NRE), al\u00e9m de secret\u00e1rios municipais de esportes, vereadores e representantes dos 13 munic\u00edpios abrangidos pelo Sesc Apucarana.<\/p>\n\n\n\n<p><strong>30 ANOS DE COMBATE AO SEDENTARISMO \u2013<\/strong>&nbsp;Presente em 14 pa\u00edses da Am\u00e9rica Latina, h\u00e1 30 anos o Dia do Desafio mobiliza institui\u00e7\u00f5es p\u00fablicas e privadas chamando a aten\u00e7\u00e3o da popula\u00e7\u00e3o para a import\u00e2ncia da pr\u00e1tica regular de atividades f\u00edsicas e esportivas. Localmente, \u00e9 uma coordena\u00e7\u00e3o do Sesc e Prefeitura de Apucarana, sendo uma iniciativa global liderada pela TAFISA (The Association For International Sport for All), que conta com apoio institucional da ISCA (International Sport and Culture Association) e da UNESCO (Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura). No Paran\u00e1, conta ainda com apoio da Fecom\u00e9rcio-PR, Sesc, Senac E Instituto Fecom\u00e9rcio de Pesquisa e Desenvolvimento (IFPD).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o Social do Com\u00e9rcio (Sesc), de Apucarana, fez nesta quarta-feira (14\/05) o lan\u00e7amento do Dia do Desafio de 2025 para os 13 munic\u00edpios de abrang\u00eancia da unidade. A mobiliza\u00e7\u00e3o, que busca conscientizar sobre a import\u00e2ncia da pr\u00e1tica regular de atividades f\u00edsicas e que neste ano completa 30 anos, acontece em 28 de maio (\u00faltima [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46.png",2560,1706,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1024x682.png",860,573,true],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1536x1024.png",1536,1024,true],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-2048x1365.png",2048,1365,true],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-700x466.png",700,466,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-1200x600.png",1200,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-46-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6642"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6643"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}