{"id":659,"date":"2023-09-22T15:44:04","date_gmt":"2023-09-22T15:44:04","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=659"},"modified":"2023-09-22T15:44:06","modified_gmt":"2023-09-22T15:44:06","slug":"policia-civil-de-sp-prende-em-apucarana-dois-suspeitos-de-roubos","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/22\/policia-civil-de-sp-prende-em-apucarana-dois-suspeitos-de-roubos\/","title":{"rendered":"Pol\u00edcia Civil de SP prende em Apucarana dois suspeitos de roubos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Pris\u00f5es aconteceram no Jardim Veneza e est\u00e3o relacionadas ao combate ao roubo de cargas; saiba mais<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"501\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Os-dois-homens-teriam-cometido-diversos-roubos-pri-00794832-0-202309220932-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-660\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Os-dois-homens-teriam-cometido-diversos-roubos-pri-00794832-0-202309220932-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Os-dois-homens-teriam-cometido-diversos-roubos-pri-00794832-0-202309220932-ScaleDownProportional-600x337.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Os-dois-homens-teriam-cometido-diversos-roubos-pri-00794832-0-202309220932-ScaleDownProportional-300x169.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Os-dois-homens-teriam-cometido-diversos-roubos-pri-00794832-0-202309220932-ScaleDownProportional-768x432.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>A Pol\u00edcia Civil, de S\u00e3o Paulo, prendeu duas pessoas na manh\u00e3 desta sexta-feira (22) em&nbsp;<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\">Apucarana<\/a>, na regi\u00e3o Norte do Paran\u00e1, durante opera\u00e7\u00e3o de combate ao roubo de cargas e outros crimes ocorridos naquele estado. Os detidos foram localizados no Jardim Veneza. As pris\u00f5es contaram com apoio de policiais civis da 17\u00aa Subdivis\u00e3o Policial (SDP).<\/p>\n\n\n\n<p>Os policiais civis da Ger\u00eancia de Opera\u00e7\u00f5es Especiais (GOE), do Estado de S\u00e3o Paulo, vieram da cidade de Bauru e cumpriram os mandados por volta das 6 horas desta sexta-feira. Na casa, foram localizados os dois suspeitos e algumas armas.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil deve divulgar mais informa\u00e7\u00f5es sobre esta a\u00e7\u00e3o ainda nesta sexta-feira (22).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pris\u00f5es aconteceram no Jardim Veneza e est\u00e3o relacionadas ao combate ao roubo de cargas; saiba mais A Pol\u00edcia Civil, de S\u00e3o Paulo, prendeu duas pessoas na manh\u00e3 desta sexta-feira (22) em&nbsp;Apucarana, na regi\u00e3o Norte do Paran\u00e1, durante opera\u00e7\u00e3o de combate ao roubo de cargas e outros crimes ocorridos naquele estado. Os detidos foram localizados no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-659","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=659"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/659\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}