{"id":6538,"date":"2025-05-06T06:33:49","date_gmt":"2025-05-06T03:33:49","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6538"},"modified":"2025-05-07T06:33:59","modified_gmt":"2025-05-07T03:33:59","slug":"apucarana-realiza-no-sabado-o-dia-d-da-vacinacao-contra-a-gripe-em-horario-especial","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/05\/06\/apucarana-realiza-no-sabado-o-dia-d-da-vacinacao-contra-a-gripe-em-horario-especial\/","title":{"rendered":"Apucarana realiza no s\u00e1bado o Dia D da vacina\u00e7\u00e3o contra a gripe em hor\u00e1rio especial"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/05\/Vacinacao-ze-gotinha-e-gripe-20-1024x683.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Visando atingir um maior n\u00famero de pessoas, Apucarana realiza neste s\u00e1bado (10\/05) o Dia D da Vacina\u00e7\u00e3o Contra a Influenza, com atendimento em hor\u00e1rio diferenciado, das 12 horas \u00e0s 18 horas. A mobiliza\u00e7\u00e3o acontecer\u00e1 nas 28 Unidades B\u00e1sicas de Sa\u00fade (UBS) que possuem sala de vacina.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Sa\u00fade, Guilherme de Paula, afirma que a escolha pelo atendimento no per\u00edodo da tarde foi definida em conjunto com as equipes da Divis\u00e3o de Vigil\u00e2ncia Epidemiol\u00f3gica e da Estrat\u00e9gia Sa\u00fade da Fam\u00edlia (ESF). \u201cAs equipes relataram que a busca pela vacina em campanhas anteriores sempre foi maior no per\u00edodo da tarde. Por isso, optamos em concentrar o atendimento nesse hor\u00e1rio, com seis horas de vacina\u00e7\u00e3o ininterrupta, buscando alcan\u00e7ar o maior n\u00famero de pessoas\u201d, explica.<\/p>\n\n\n\n<p>A campanha de vacina\u00e7\u00e3o contra a gripe come\u00e7ou em Apucarana no dia 1\u00ba de abril e, desde ent\u00e3o, est\u00e1 aberta a todos os grupos priorit\u00e1rios. \u201cEm anos anteriores, a campanha era liberada por etapas. Como neste ano foram contemplados todos os p\u00fablicos priorit\u00e1rios desde come\u00e7o, muitos deles \u2013 principalmente os idosos \u2013 j\u00e1 se imunizaram nas primeiras semanas\u201d, afirma.<\/p>\n\n\n\n<p>De Paula assinala que a estrat\u00e9gia de realizar o Dia D no per\u00edodo da tarde busca atingir especialmente as crian\u00e7as e trabalhadores. \u201cDurante o hor\u00e1rio comercial, muitas pessoas n\u00e3o conseguem ir at\u00e9 uma UBS. Por isso, no s\u00e1bado \u00e0 tarde a nossa expectativa \u00e9 que possamos atender mais trabalhadores e tamb\u00e9m que os pais levem seus filhos\u201d, salienta.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota conclama a popula\u00e7\u00e3o a participar da mobiliza\u00e7\u00e3o. \u201c\u00c9 muito importante que os pais aproveitem essa oportunidade para levar seus filhos e que os trabalhadores que n\u00e3o conseguiram se imunizar durante a semana procurem as unidades neste s\u00e1bado. Estamos nos aproximando do inverno e a preocupa\u00e7\u00e3o com a quest\u00e3o das infec\u00e7\u00f5es respirat\u00f3rias aumenta\u201d, observa.<\/p>\n\n\n\n<p>O coordenador da Divis\u00e3o de Vigil\u00e2ncia Epidemiol\u00f3gica da AMS, Pablo Saito, reitera a preocupa\u00e7\u00e3o com as crian\u00e7as do grupo priorit\u00e1rio de 6 meses a menores de 6 anos de idade.&nbsp; \u201cJ\u00e1 estamos vendo pela imprensa alguns estados vizinhos aqui do Paran\u00e1 com aumento nas interna\u00e7\u00f5es por doen\u00e7a respirat\u00f3ria. Sem a vacina, a pessoa pode ter uma gripe mais forte, a imunidade cai e fica suscet\u00edvel a infec\u00e7\u00f5es bacterianas ou outras infec\u00e7\u00f5es virais, aumentando tamb\u00e9m o risco de pneumonia\u201d, alerta.<\/p>\n\n\n\n<p>Saito afirma ainda que os usu\u00e1rios que comparecerem \u00e0s unidades de sa\u00fade tamb\u00e9m ter\u00e3o a oportunidade de atualizar a carteira de vacina\u00e7\u00e3o, com doses de outros imunizantes. As pessoas que ir\u00e3o se vacinar e os respons\u00e1veis pelos menores de idade devem levar documento com foto e carteirinha de vacina\u00e7\u00e3o (f\u00edsica ou digital). \u201cJ\u00e1 os trabalhadores de todos os grupos elencados devem tamb\u00e9m comprovar a profiss\u00e3o por meio de carteirinha de classe ou holerite\u201d, completa.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>GRUPOS PRIORIT\u00c1RIOS<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<ul class=\"wp-block-list\">\n<li>Crian\u00e7as de 6 meses a menores de 6 anos de idade (5 anos, 11 meses e 29 dias)<\/li>\n\n\n\n<li>Gestantes<\/li>\n\n\n\n<li>Idosos com 60 anos ou mais de idade<\/li>\n\n\n\n<li>Pu\u00e9rperas<\/li>\n\n\n\n<li>Trabalhadores da Sa\u00fade<\/li>\n\n\n\n<li>Professores do ensino b\u00e1sico e superior<\/li>\n\n\n\n<li>Pessoas com doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis e outras condi\u00e7\u00f5es cl\u00ednicas especiais<\/li>\n\n\n\n<li>Profissionais das For\u00e7as de Seguran\u00e7a e Salvamento<\/li>\n\n\n\n<li>Profissionais das For\u00e7as Armadas<\/li>\n\n\n\n<li>Pessoas com defici\u00eancia permanente<\/li>\n\n\n\n<li>Caminhoneiros<\/li>\n\n\n\n<li>Trabalhadores de transporte coletivo rodovi\u00e1rio para passageiros urbanos e de longo curso<\/li>\n\n\n\n<li>Trabalhadores dos Correios<\/li>\n\n\n\n<li>Popula\u00e7\u00e3o privada de liberdade e funcion\u00e1rios do sistema de priva\u00e7\u00e3o de liberdade<\/li>\n\n\n\n<li>Adolescentes e jovens de 12 a 21 anos de idade sob medidas socioeducativas<\/li>\n\n\n\n<li>Pessoas em situa\u00e7\u00e3o de rua<\/li>\n\n\n\n<li>Ind\u00edgenas<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><strong>UNIDADES DE SA\u00daDE ONDE AS DOSES EST\u00c3O DISPON\u00cdVEIS<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>UBS MYIOJI KOGURE (JARDIM ACLIMA\u00c7\u00c3O)<\/li>\n\n\n\n<li>UBS DR ANTONIO SACHELLI (JARDIM COLONIAL)<\/li>\n\n\n\n<li>UBS EM\u00cdLIA CRETUCHI (PARQUE BELA VISTA)<\/li>\n\n\n\n<li>UBS PADRE DOMINIQUE (CAIXA S\u00c3O PEDRO)<\/li>\n\n\n\n<li>UBS ROMEU MILANI (CENTRO)<\/li>\n\n\n\n<li>UBS IZILIA FOLADOR (FARIZ GEBRIM)<\/li>\n\n\n\n<li>UBS DR. MASSAYOSHI TATESUZI (JARDIM PRIMAVERA)<\/li>\n\n\n\n<li>UBS EROS PACHECO (N\u00daCLEO AFONSO CAMARGO)<\/li>\n\n\n\n<li>UBS ELAYNE MAZUR (JARDIM INTERLAGOS)<\/li>\n\n\n\n<li>UBS EUNICE PENHARBEL (RESIDENCIAL SUMATRA)<\/li>\n\n\n\n<li>UBS BOLIVAR PAV\u00c3O (JARDIM AM\u00c9RICA)<\/li>\n\n\n\n<li>UBS ANA MARIA PEPATO (JARDIM TRABALHISTA)<\/li>\n\n\n\n<li>UBS JOAQUIM TRIZOTTI (N\u00daCLEO ADRIANO CORREA)<\/li>\n\n\n\n<li>UBS LEOPOLDO HARTWIG JR. (VILA NOVA)<\/li>\n\n\n\n<li>UBS MARIA DO CAF\u00c9 (JARDIM PONTA GROSSA)<\/li>\n\n\n\n<li>UBS MERCEDES SILVA MORENO (VILA REGINA)<\/li>\n\n\n\n<li>UBS ORESTE G. MARQUITO (JARDIM MARISSOL)<\/li>\n\n\n\n<li>UBS OSVALDO DAMIN (JABOTI)<\/li>\n\n\n\n<li>UBS MARCOS S. MASCARO (N\u00daCELO PARIGOT DE SOUZA)<\/li>\n\n\n\n<li>UBS PEDRO BARRETO (DISTRITO VILA REIS)<\/li>\n\n\n\n<li>UBS RODRIGO TRAMONTIN YOSHII (VILA APUCARANINHA)<\/li>\n\n\n\n<li>UBS RAUL CASTILHO (NUCLEO JO\u00c3O PAULO)<\/li>\n\n\n\n<li>UBS TAKAITI MIYADI (N\u00daCLEO DOM ROMEU)<\/li>\n\n\n\n<li>UBS VALDECIR DE PAULA (JARDIM DAS FLORES)<\/li>\n\n\n\n<li>UBS WALTER LAZARINI (DISTRITO DE PIRAP\u00d3)<\/li>\n\n\n\n<li>UBS BENEDITO CL\u00c1UDIO \u201cPINGA FOGO\u201d DE OLIVEIRA (RESIDENCIAL SOLO SAGRADO)<\/li>\n\n\n\n<li>UBS JULIA RENCZKOWSKI (N\u00daCLEO HABITACIONAL MARCOS FREIRE)<\/li>\n\n\n\n<li>UBS MARIO VERUSSA (CORREIA DE FREITAS)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Visando atingir um maior n\u00famero de pessoas, Apucarana realiza neste s\u00e1bado (10\/05) o Dia D da Vacina\u00e7\u00e3o Contra a Influenza, com atendimento em hor\u00e1rio diferenciado, das 12 horas \u00e0s 18 horas. A mobiliza\u00e7\u00e3o acontecer\u00e1 nas 28 Unidades B\u00e1sicas de Sa\u00fade (UBS) que possuem sala de vacina. O secret\u00e1rio municipal de Sa\u00fade, Guilherme de Paula, afirma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/05\/image-13-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6538"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6539"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}