{"id":6415,"date":"2025-04-16T04:48:57","date_gmt":"2025-04-16T01:48:57","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6415"},"modified":"2025-04-17T04:49:37","modified_gmt":"2025-04-17T01:49:37","slug":"apucarana-anuncia-regularizacao-de-avancos-e-progressoes-dos-servidores-municipais","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/04\/16\/apucarana-anuncia-regularizacao-de-avancos-e-progressoes-dos-servidores-municipais\/","title":{"rendered":"Apucarana anuncia regulariza\u00e7\u00e3o de avan\u00e7os e progress\u00f5es dos servidores municipais"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png\" alt=\"\" class=\"wp-image-6416\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O prefeito Rodolfo Mota anunciou nesta quarta-feira (16\/04) a concess\u00e3o dos avan\u00e7os e progress\u00f5es funcionais para servidores da prefeitura e do quadro da Autarquia Municipal de Educa\u00e7\u00e3o (AME). Direitos previstos pelo Sistema de Cargos e Carreiras do Funcionalismo P\u00fablico Municipal de Apucarana, ser\u00e3o beneficiados com a medida administrativa servidores que tiveram direito adquiridos at\u00e9 o m\u00eas de abril. \u201cFizemos um levantamento para descobrir a quantidade de servidores da prefeitura e da Educa\u00e7\u00e3o que est\u00e3o sem receber esses avan\u00e7os. Na folha de pagamento de abril vamos colocar em dia todos esses direitos adquiridos\u201d, disse o prefeito Rodolfo Mota, assinalando que neste m\u00eas ser\u00e3o atendidos 89 servidores na prefeitura e 55 servidores da Autarquia de Educa\u00e7\u00e3o. \u201cPara maio, tamb\u00e9m na Educa\u00e7\u00e3o, teremos mais 263 professores tendo a implanta\u00e7\u00e3o de seus direitos\u201d, revelou Mota.<\/p>\n\n\n\n<p>O prefeito relatou que apesar de ser direito da categoria, em alguns per\u00edodos da hist\u00f3ria o servidor municipal precisou de processo judicial para conseguir a devida implanta\u00e7\u00e3o. \u201cN\u00f3s estamos pondo fim a isso. O nosso planejamento agora \u00e9 instalar uma rotina administrativa para que esses avan\u00e7os e progress\u00f5es sejam implementadas automaticamente a cada 60 dias, de acordo com o direito adquirido dos servidores\u201d, informou Rodolto Mota.<\/p>\n\n\n\n<p><strong>Para entender<\/strong>&nbsp;\u2013 Cada cargo p\u00fablico possui um n\u00edvel inicial na carreira e o Sistema de Cargos e Carreiras do Funcionalismo P\u00fablico Municipal de Apucarana prev\u00ea duas modalidades de eleva\u00e7\u00e3o. O \u201cAvan\u00e7o Funcional\u201d, que \u00e9 a passagem do servidor a n\u00edvel de vencimento imediatamente superior, por for\u00e7a do tempo de servi\u00e7o, considerado o interst\u00edcio de 24 meses para cada n\u00edvel e a \u201cProgress\u00e3o Funcional\u201d, que \u00e9 a passagem do servidor a n\u00edvel de vencimento seguinte em decorr\u00eancia de m\u00e9rito no desempenho profissional.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Rodolfo Mota anunciou nesta quarta-feira (16\/04) a concess\u00e3o dos avan\u00e7os e progress\u00f5es funcionais para servidores da prefeitura e do quadro da Autarquia Municipal de Educa\u00e7\u00e3o (AME). Direitos previstos pelo Sistema de Cargos e Carreiras do Funcionalismo P\u00fablico Municipal de Apucarana, ser\u00e3o beneficiados com a medida administrativa servidores que tiveram direito adquiridos at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-43-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6415"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6416"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}