{"id":6312,"date":"2025-04-02T21:39:14","date_gmt":"2025-04-02T21:39:14","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6312"},"modified":"2025-04-02T21:39:15","modified_gmt":"2025-04-02T21:39:15","slug":"caixa-e-confirmada-para-dar-parecer-tecnico-sobre-as-obras-do-futuro-hospital-de-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/04\/02\/caixa-e-confirmada-para-dar-parecer-tecnico-sobre-as-obras-do-futuro-hospital-de-apucarana\/","title":{"rendered":"Caixa \u00e9 confirmada para dar parecer t\u00e9cnico sobre as obras do futuro Hospital de Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png\" alt=\"\" class=\"wp-image-6313\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O departamento de engenharia da Caixa Econ\u00f4mica Federal ser\u00e1 respons\u00e1vel pela emiss\u00e3o de um parecer t\u00e9cnico conclusivo sobre as reais condi\u00e7\u00f5es em que as obras de adequa\u00e7\u00e3o do pr\u00e9dio do futuro Hospital de Apucarana (H.A.) foram recebidas pela prefeitura. A contrata\u00e7\u00e3o da institui\u00e7\u00e3o federal foi confirmada nesta quarta-feira (02\/04) pelo prefeito Rodolfo Mota e pelos secret\u00e1rios municipais Dr. Guilherme de Paula (Sa\u00fade) e engenheiro civil Mateus Franciscon Fernandes (Obras). \u201cA Prefeitura de Apucarana quer saber se realmente todos os requisitos previstos no contrato de licita\u00e7\u00e3o e apontamentos feitos em vistorias da Secretaria de Obras foram atendidos pela Termale Engenharia Ltda, empreiteira respons\u00e1vel pelas obras de estrutura\u00e7\u00e3o\u201d, afirma o prefeito Rodolfo Mota.<\/p>\n\n\n\n<p>O contrato entre a prefeitura e Caixa ser\u00e1 firmado nos pr\u00f3ximos dias na modalidade dispensa de licita\u00e7\u00e3o, mas o protocolo de inten\u00e7\u00f5es de parceria para a presta\u00e7\u00e3o de servi\u00e7os de assist\u00eancia e acompanhamento da obra foi assinado nesta quarta-feira pelo prefeito e pela superintendente Executiva de Governo da Caixa Econ\u00f4mica Federal, Viviane Barcala Gon\u00e7alves. Tamb\u00e9m acompanharam o ato, realizado no pr\u00e9dio do futuro hospital, os vereadores Guilherme Livoti, Gabriel Caldeira e Wellington Gentil, al\u00e9m de outros secret\u00e1rios municipais e agentes do banco. \u201cOptamos pela Caixa pelo hist\u00f3rico, pela credibilidade da institui\u00e7\u00e3o e expertise dos t\u00e9cnicos e profissionais\u201d, disse Mota.<\/p>\n\n\n\n<p>O valor do contrato a ser celebrado ser\u00e1 na ordem de R$33 mil. \u201cConvenhamos, algo bastante especial diante do valor da obra, que somou investimento muito significativo, de mais de R$26 milh\u00f5es. Ent\u00e3o, agrade\u00e7o publicamente \u00e0 Caixa Econ\u00f4mica, que \u00e9 parceria do Munic\u00edpio em diversas outras obras e programas, por aceitar somar tamb\u00e9m neste processo que visa certificar que todos os pontos de execu\u00e7\u00e3o obra atenderam ao contrato\u201d, explicou o prefeito Rodolfo Mota.<\/p>\n\n\n\n<p>Ao assinar o protocolo de inten\u00e7\u00f5es de parceria, a superintendente Executiva de Governo da Caixa Econ\u00f4mica Federal, Viviane Barcala Gon\u00e7alves, tamb\u00e9m agradeceu ao Munic\u00edpio. \u201cIsso refor\u00e7a a import\u00e2ncia da Caixa, que est\u00e1 sempre presente e se posicionando como parceira dos munic\u00edpios. Nossa equipe de engenharia de fato conta com toda expertise para este trabalho e vamos, assim que concretizado o contrato, estar acompanhando e assessorando o munic\u00edpio de Apucarana na tomada de decis\u00e3o para que possa colocar em atividades essa obra t\u00e3o importante que \u00e9 o hospital municipal\u201d, disse a superintendente.<\/p>\n\n\n\n<p>Durante o ato, o prefeito Rodolfo Mota tamb\u00e9m agradeceu a todo trabalho da equipe da Secretaria de Obras. \u201cNossos servidores promoveram um trabalho de vistoria muito importante at\u00e9 aqui mas, como j\u00e1 disse anteriormente, dado o simbolismo dessa obra, \u00e9 relevante que contemos tamb\u00e9m com algu\u00e9m que tenha expertise, conhecimento e a credibilidade, que neste cen\u00e1rio s\u00e3o os t\u00e9cnicos da Caixa\u201d, finalizou Mota.<\/p>\n\n\n\n<p><strong>Dos fatos<\/strong>&nbsp;\u2013 O pr\u00e9dio onde ir\u00e1 funcionar o Hospital de Apucarana (H. A.) foi oficialmente entregue ao Munic\u00edpio no \u00faltimo dia 28 de mar\u00e7o pela Termale Engenharia Ltda, empreiteira respons\u00e1vel pelas obras de estrutura\u00e7\u00e3o. No total, foram 22 meses de trabalho. Na oportunidade, o prefeito Rodolfo Mota j\u00e1 havia anunciado que a prefeitura iria procurar firmar parceria com a Caixa Econ\u00f4mica Federal (CEF) para emiss\u00e3o de um parecer t\u00e9cnico para verifica\u00e7\u00e3o se a execu\u00e7\u00e3o atendeu a todos os requisitos do contrato licitado, reafirmando compromisso de dar total transpar\u00eancia a todas as quest\u00f5es relacionadas ao projeto do hospital.<\/p>\n\n\n\n<p><strong>O hospital \u2013<\/strong>&nbsp;A obra do Hospital de Apucarana (H. A.) absorveu investimento de mais de R$ 26 milh\u00f5es, sendo R$21 milh\u00f5es em recursos municiais e R$5 milh\u00f5es do Deputado Arilson Chiorato atrav\u00e9s de emendas da deputada Federal Gleisi Hoffmann. A estrutura inclui um centro cir\u00fargico e 58 leitos de internamento, al\u00e9m do Pronto Atendimento Infantil 24 Horas, implantado no t\u00e9rreo do bloco principal. O pr\u00e9dio tem ampla acessibilidade e conta com rampas e dois elevadores. A obra conta com ainda com instala\u00e7\u00f5es de ar condicionado, hidr\u00e1ulica, el\u00e9trica, gases medicinais, rede l\u00f3gica, sistema de SPDA, usina de oxig\u00eanio e transformador pr\u00f3prio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O departamento de engenharia da Caixa Econ\u00f4mica Federal ser\u00e1 respons\u00e1vel pela emiss\u00e3o de um parecer t\u00e9cnico conclusivo sobre as reais condi\u00e7\u00f5es em que as obras de adequa\u00e7\u00e3o do pr\u00e9dio do futuro Hospital de Apucarana (H.A.) foram recebidas pela prefeitura. A contrata\u00e7\u00e3o da institui\u00e7\u00e3o federal foi confirmada nesta quarta-feira (02\/04) pelo prefeito Rodolfo Mota e pelos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/04\/image-11-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6312"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6313"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}