{"id":6260,"date":"2025-03-29T14:49:45","date_gmt":"2025-03-29T14:49:45","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6260"},"modified":"2025-03-29T14:50:21","modified_gmt":"2025-03-29T14:50:21","slug":"lei-torna-bonetizando-uma-politica-permanente-na-educacao-de-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/03\/29\/lei-torna-bonetizando-uma-politica-permanente-na-educacao-de-apucarana\/","title":{"rendered":"Lei torna \u201cBonetizando\u201d uma pol\u00edtica permanente na Educa\u00e7\u00e3o de Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png\" alt=\"\" class=\"wp-image-6261\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O prefeito Rodolfo Mota sancionou nesta sexta-feira (28\/03) a Lei Municipal n\u00ba 011\/2025, que institui o Projeto Bonetizando como pol\u00edtica p\u00fablica permanente em Apucarana. O projeto de lei que deu origem \u00e0 legisla\u00e7\u00e3o, de autoria do vereador e presidente do Legislativo Municipal, Danylo Acioli, foi aprovado por unanimidade em fevereiro deste ano.<\/p>\n\n\n\n<p>Realizada entre mar\u00e7o e maio de 2024, a primeira edi\u00e7\u00e3o do projeto foi promovida pela Autarquia Municipal de Educa\u00e7\u00e3o (AME), Sindicato das Ind\u00fastrias do Vestu\u00e1rio de Apucarana e Vale do Iva\u00ed (Sivale) e Arranjo Produtivo Local de Bon\u00e9s e Confec\u00e7\u00f5es (APL Bon\u00e9s e Confec\u00e7\u00f5es). A iniciativa envolveu mais de 1.400 alunos do terceiro ano da rede municipal de ensino.<\/p>\n\n\n\n<p>\u201cApucarana \u00e9 a Capital Nacional do Bon\u00e9 e o principal polo t\u00eaxtil e do vestu\u00e1rio do Paran\u00e1. O \u201cBonetizando\u201d\u2019 aproxima a comunidade escolar do setor industrial, fortalecendo os v\u00ednculos com a hist\u00f3ria local. Al\u00e9m disso, promove nas novas gera\u00e7\u00f5es a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia do setor de confec\u00e7\u00f5es, especialmente de bon\u00e9s, para a economia e identidade cultural da cidade. Por isso, sanciono esta lei com grande satisfa\u00e7\u00e3o\u201d, destacou o prefeito Rodolfo Mota, parabenizando todas as institui\u00e7\u00f5es e escolas envolvidas na iniciativa.<\/p>\n\n\n\n<p>Durante a primeira edi\u00e7\u00e3o do \u201cBonetizando\u201d, que tem como mote \u201cDe Apucarana para o Mundo\u201d, os alunos visitaram mais de 30 ind\u00fastrias de confec\u00e7\u00f5es da cidade, onde puderam conhecer de perto o processo produtivo dos bon\u00e9s. Eles tamb\u00e9m visitaram o Monumento ao Bon\u00e9 (Bonez\u00e3o), localizado na sa\u00edda para Londrina (BR-369). \u201cJ\u00e1 em sala de aula, as crian\u00e7as continuaram aprendendo sobre a hist\u00f3ria do setor em Apucarana, produzindo desenhos e ilustra\u00e7\u00f5es sobre o que vivenciaram\u201d, acrescentou o prefeito.<\/p>\n\n\n\n<p>A cerim\u00f4nia de san\u00e7\u00e3o da lei contou com a presen\u00e7a do diretor-administrativo da C\u00e2mara de Vereadores, Daniel Rodrigo de Souza, do vereador Guilherme Livoti, da presidente do Sivale, empres\u00e1ria Bete Ardigo, do presidente do APL Bon\u00e9s e Confec\u00e7\u00f5es e vice-presidente da Associa\u00e7\u00e3o Comercial, Industrial e de Servi\u00e7os de Apucarana (Acia), empres\u00e1rio Jayme Leonel; al\u00e9m de outros representantes das entidades parceiras e do consultor do Sebrae Apucarana, Tiago Cunha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Rodolfo Mota sancionou nesta sexta-feira (28\/03) a Lei Municipal n\u00ba 011\/2025, que institui o Projeto Bonetizando como pol\u00edtica p\u00fablica permanente em Apucarana. O projeto de lei que deu origem \u00e0 legisla\u00e7\u00e3o, de autoria do vereador e presidente do Legislativo Municipal, Danylo Acioli, foi aprovado por unanimidade em fevereiro deste ano. Realizada entre mar\u00e7o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-123-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6260"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6261"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}