{"id":6201,"date":"2025-03-25T17:43:19","date_gmt":"2025-03-25T17:43:19","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6201"},"modified":"2025-03-25T17:43:21","modified_gmt":"2025-03-25T17:43:21","slug":"novos-diretores-escolares-passam-por-formacao-antes-de-assumirem-o-cargo","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/03\/25\/novos-diretores-escolares-passam-por-formacao-antes-de-assumirem-o-cargo\/","title":{"rendered":"Novos Diretores Escolares passam por forma\u00e7\u00e3o antes de assumirem o cargo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png\" alt=\"\" class=\"wp-image-6202\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-768x576.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-400x300.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-700x525.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-600x450.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Autarquia Municipal de Educa\u00e7\u00e3o est\u00e1 promovendo, nesta semana, a transi\u00e7\u00e3o de diretores nos 24 Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e nas 36 Escolas Municipais de Apucarana. Os novos diretores assumir\u00e3o seus cargos para o bi\u00eanio 2025\/2026 e ser\u00e3o empossados em cerim\u00f4nia marcada para a pr\u00f3xima sexta-feira (28\/3), \u00e0s 19h30, no Cine Teatro F\u00eanix.<\/p>\n\n\n\n<p>A presidente da Comiss\u00e3o Central do Processo de Escolha para Diretores Escolares, professora Adilene Ananias, detalhou como est\u00e1 sendo realizada a transi\u00e7\u00e3o nas unidades de ensino. \u201cAo longo desta semana, os novos diretores est\u00e3o acompanhando os que deixar\u00e3o o cargo, com o objetivo de se familiarizarem com a documenta\u00e7\u00e3o e a rotina administrativa das escolas e CMEIs. Desde ontem (24) at\u00e9 o dia 27, eles tamb\u00e9m est\u00e3o participando de uma forma\u00e7\u00e3o sobre Gest\u00e3o Escolar, que acontece no per\u00edodo noturno, no audit\u00f3rio do SENAC. A forma\u00e7\u00e3o est\u00e1 sendo conduzida pela professora doutora Adriana Salvaterra, da UNESPAR \u2013 Universidade Estadual do Paran\u00e1\u201d, explicou.<\/p>\n\n\n\n<p>O Processo de Escolha para Diretores Escolares foi composto por cinco etapas: inscri\u00e7\u00e3o e envio da documenta\u00e7\u00e3o exigida pelo Decreto 97\/2025, aprova\u00e7\u00e3o em Prova de M\u00e9ritos, Prova de T\u00edtulos, Avalia\u00e7\u00e3o Funcional de Desempenho do Servidor e Consulta P\u00fablica aos Servidores das institui\u00e7\u00f5es de ensino. \u201cDos 114 candidatos aptos a concorrer, 38 foram aprovados ao final do concurso. A administra\u00e7\u00e3o municipal indicou os novos diretores nas unidades de ensino que n\u00e3o tiveram candidatos aprovados\u201d, complementou Claudemir Ockner, membro da Comiss\u00e3o Central do Processo de Escolha.<\/p>\n\n\n\n<p>O cargo de diretor escolar \u00e9 de grande responsabilidade e desempenha um papel essencial na gest\u00e3o da institui\u00e7\u00e3o. Entre suas fun\u00e7\u00f5es est\u00e3o a administra\u00e7\u00e3o das finan\u00e7as da escola, a presta\u00e7\u00e3o de contas \u00e0 comunidade escolar, a gest\u00e3o de pessoal, a manuten\u00e7\u00e3o dos recursos e estoques, o conhecimento das legisla\u00e7\u00f5es e normas educacionais, a lideran\u00e7a na elabora\u00e7\u00e3o do Projeto Pol\u00edtico-Pedag\u00f3gico (PPP) e o fortalecimento do relacionamento entre a equipe escolar e as fam\u00edlias dos alunos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Autarquia Municipal de Educa\u00e7\u00e3o est\u00e1 promovendo, nesta semana, a transi\u00e7\u00e3o de diretores nos 24 Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e nas 36 Escolas Municipais de Apucarana. Os novos diretores assumir\u00e3o seus cargos para o bi\u00eanio 2025\/2026 e ser\u00e3o empossados em cerim\u00f4nia marcada para a pr\u00f3xima sexta-feira (28\/3), \u00e0s 19h30, no Cine Teatro F\u00eanix. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png",1024,768,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-300x225.png",300,225,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-768x576.png",768,576,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png",860,645,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png",1024,768,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104.png",1024,768,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-400x300.png",400,300,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-700x525.png",700,525,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-600x450.png",600,450,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-104-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6201"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6202"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}