{"id":612,"date":"2023-09-20T12:39:46","date_gmt":"2023-09-20T12:39:46","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=612"},"modified":"2023-09-20T12:39:46","modified_gmt":"2023-09-20T12:39:46","slug":"policia-militar-frustra-tentativa-de-furto-de-betoneira-em-faxinal","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/20\/policia-militar-frustra-tentativa-de-furto-de-betoneira-em-faxinal\/","title":{"rendered":"Pol\u00edcia Militar frustra tentativa de furto de betoneira em Faxinal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">A tentativa de furto foi na ter\u00e7a-feira em uma casa em constru\u00e7\u00e3o na Rua Waldemar Pepeleascov<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-tentativa-de-furto-ocorreu-na-terca-feira-na-Rua-00794109-0-202309200745-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-613\" style=\"width:738px;height:411px\" width=\"738\" height=\"411\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-tentativa-de-furto-ocorreu-na-terca-feira-na-Rua-00794109-0-202309200745-ScaleDownProportional.webp 800w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-tentativa-de-furto-ocorreu-na-terca-feira-na-Rua-00794109-0-202309200745-ScaleDownProportional-600x334.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-tentativa-de-furto-ocorreu-na-terca-feira-na-Rua-00794109-0-202309200745-ScaleDownProportional-300x167.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-tentativa-de-furto-ocorreu-na-terca-feira-na-Rua-00794109-0-202309200745-ScaleDownProportional-768x427.webp 768w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/figure>\n\n\n\n<p>A\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/pmpr?d=1\" target=\"_blank\">Pol\u00edcia Militar\u00a0<\/a>(PM) frustrou uma tentativa de furto de uma betoneira em uma casa em constru\u00e7\u00e3o, em<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/faxinal?d=1\" target=\"_blank\">\u00a0Faxinal<\/a>, na ter\u00e7a-feir<\/p>\n\n\n\n<p>A a\u00e7\u00e3o policial foi logo ap\u00f3s o Copom receber informa\u00e7\u00f5es an\u00f4nimas de que na Rua Waldemar Pepeleascov estaria ocorrendo uma situa\u00e7\u00e3o de furto de uma betoneira.<\/p>\n\n\n\n<p>A equipe se deslocou ao local onde na chegada da equipe ningu\u00e9m foi localizado e nem a betoneira.<\/p>\n\n\n\n<p>Por\u00e9m a equipe constatou que havia rastros deixados pelo equipamento que foi seguido pelos policiais, e encontraram a betoneira em um pasto escuro a uns 300 metros do local do furto.<\/p>\n\n\n\n<p>A PM entrou em contato com o propriet\u00e1rio da obra que mandou seu funcion\u00e1rio ao local. Sendo ent\u00e3o orientado sobre os procedimentos cab\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tentativa de furto foi na ter\u00e7a-feira em uma casa em constru\u00e7\u00e3o na Rua Waldemar Pepeleascov A\u00a0Pol\u00edcia Militar\u00a0(PM) frustrou uma tentativa de furto de uma betoneira em uma casa em constru\u00e7\u00e3o, em\u00a0Faxinal, na ter\u00e7a-feir A a\u00e7\u00e3o policial foi logo ap\u00f3s o Copom receber informa\u00e7\u00f5es an\u00f4nimas de que na Rua Waldemar Pepeleascov estaria ocorrendo uma situa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-612","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/612\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}