{"id":6096,"date":"2025-03-17T12:54:53","date_gmt":"2025-03-17T12:54:53","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6096"},"modified":"2025-03-17T13:00:48","modified_gmt":"2025-03-17T13:00:48","slug":"autarquia-municipal-de-educacao-divulga-local-de-provas-do-processo-seletivo-para-diretores-escolares","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/03\/17\/autarquia-municipal-de-educacao-divulga-local-de-provas-do-processo-seletivo-para-diretores-escolares\/","title":{"rendered":"Autarquia Municipal de Educa\u00e7\u00e3o divulga local de provas do Processo Seletivo para Diretores Escolares"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png\" alt=\"\" class=\"wp-image-6097\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Autarquia Municipal de Educa\u00e7\u00e3o de Apucarana divulgou, nesta quinta-feira (13\/3), o local onde ser\u00e3o realizadas as provas objetivas do Processo Seletivo para Diretores Escolares. Um total de 113 candidatos est\u00e1 apto a concorrer \u00e0s 60 vagas dispon\u00edveis, distribu\u00eddas entre 24 Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e 36 Escolas Municipais.<\/p>\n\n\n\n<p>A aplica\u00e7\u00e3o das provas ocorrer\u00e1 no pr\u00f3ximo domingo, dia 16 de mar\u00e7o, no campus da Universidade Estadual do Paran\u00e1 (Unespar). Os port\u00f5es ser\u00e3o abertos \u00e0s 12h e fechados pontualmente \u00e0s 12h50min. N\u00e3o ser\u00e1 tolerado atraso. O in\u00edcio da prova est\u00e1 marcado para as 13h, com dura\u00e7\u00e3o de quatro horas.<\/p>\n\n\n\n<p>Os candidatos dever\u00e3o comparecer ao local de prova munidos de caneta esferogr\u00e1fica de tinta azul ou preta e de um documento de identidade oficial, que pode ser o Registro Geral (RG), a Carteira Nacional de Habilita\u00e7\u00e3o (CNH), a Carteira de \u00d3rg\u00e3o ou Conselho de Classe (reconhecido por lei), a Carteira de Trabalho e Previd\u00eancia Social (CTPS), o Certificado Militar ou o Passaporte. Em caso de perda ou furto do documento, o candidato deve apresentar o Boletim de Ocorr\u00eancia (original ou c\u00f3pia autenticada).<\/p>\n\n\n\n<p>A Comiss\u00e3o Central respons\u00e1vel pelo processo seletivo publicar\u00e1 o gabarito e o resultado da prova objetiva no dia 18 de mar\u00e7o, no site oficial da Prefeitura de Apucarana (www.apucarana.pr.gov.br).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Autarquia Municipal de Educa\u00e7\u00e3o de Apucarana divulgou, nesta quinta-feira (13\/3), o local onde ser\u00e3o realizadas as provas objetivas do Processo Seletivo para Diretores Escolares. Um total de 113 candidatos est\u00e1 apto a concorrer \u00e0s 60 vagas dispon\u00edveis, distribu\u00eddas entre 24 Centros Municipais de Educa\u00e7\u00e3o Infantil (CMEIs) e 36 Escolas Municipais. A aplica\u00e7\u00e3o das provas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-69-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6096"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6097"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}