{"id":6081,"date":"2025-03-14T17:04:34","date_gmt":"2025-03-14T17:04:34","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6081"},"modified":"2025-03-14T17:04:36","modified_gmt":"2025-03-14T17:04:36","slug":"autarquia-de-saude-alerta-para-o-aumento-de-viroses-e-doencas-respiratorias-em-criancas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/03\/14\/autarquia-de-saude-alerta-para-o-aumento-de-viroses-e-doencas-respiratorias-em-criancas\/","title":{"rendered":"Autarquia de Sa\u00fade alerta para o aumento de viroses e doen\u00e7as respirat\u00f3rias em crian\u00e7as"},"content":{"rendered":"\n<ol class=\"wp-block-list\"><\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"730\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png\" alt=\"\" class=\"wp-image-6082\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-300x214.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-768x548.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-400x285.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-700x499.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-600x428.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Autarquia de Sa\u00fade de Apucarana (AMS) emitiu nesta segunda-feira (10\/03) um informe sobre o crescimento do n\u00famero de atendimento de crian\u00e7as por viroses e doen\u00e7as respirat\u00f3rias. De acordo com o secret\u00e1rio municipal Dr. Guilherme de Paula, tamb\u00e9m \u00e9 significativo junto \u00e0 rede p\u00fablica o aumento de casos respirat\u00f3rios em adultos. \u201cEstamos acompanhando de perto a situa\u00e7\u00e3o e refor\u00e7ando as estrat\u00e9gias para garantir o melhor atendimento poss\u00edvel ao cidad\u00e3o. Para isso, estamos ampliando a capacidade de atendimento na aten\u00e7\u00e3o b\u00e1sica, na UPA 24 horas e tamb\u00e9m no Centro Infantil, garantindo que os m\u00e9dicos estejam preparados para atender a demanda de pediatria tamb\u00e9m nas unidades b\u00e1sicas\u201d, esclarece de Paula.<\/p>\n\n\n\n<p>Ele pede que a popula\u00e7\u00e3o redobre os cuidados para evitar a transmiss\u00e3o das doen\u00e7as. \u201cImportante que todos colaborem para interrompermos o ciclo de transmiss\u00e3o, adotando medidas simples, como lavar as m\u00e3os com frequ\u00eancia, manter os ambientes ventilados e higienizados, beber bastante \u00e1gua, manter uma alimenta\u00e7\u00e3o equilibrada e evitar aglomera\u00e7\u00f5es\u201d, orientou o m\u00e9dico e secret\u00e1rio de Sa\u00fade.<\/p>\n\n\n\n<p>De Paula assinala que as unidades b\u00e1sicas de sa\u00fade est\u00e3o preparadas para atender a popula\u00e7\u00e3o. \u201cEm caso de sintomas leves, a pessoa deve procurar a UBS de refer\u00eancia para atendimento m\u00e9dico. A UPA \u00e9 destinada para urg\u00eancias e emerg\u00eancias\u201d, pontua Dr. Guilherme de Paula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Autarquia de Sa\u00fade de Apucarana (AMS) emitiu nesta segunda-feira (10\/03) um informe sobre o crescimento do n\u00famero de atendimento de crian\u00e7as por viroses e doen\u00e7as respirat\u00f3rias. De acordo com o secret\u00e1rio municipal Dr. Guilherme de Paula, tamb\u00e9m \u00e9 significativo junto \u00e0 rede p\u00fablica o aumento de casos respirat\u00f3rios em adultos. \u201cEstamos acompanhando de perto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png",1024,730,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-300x214.png",300,214,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-768x548.png",768,548,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png",860,613,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png",1024,730,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64.png",1024,730,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-400x285.png",400,285,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-700x499.png",700,499,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-600x428.png",600,428,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-64-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6081"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6082"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}