{"id":6062,"date":"2025-03-13T17:49:48","date_gmt":"2025-03-13T17:49:48","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=6062"},"modified":"2025-03-13T17:49:52","modified_gmt":"2025-03-13T17:49:52","slug":"secretaria-de-seguranca-e-transito-vai-dar-destinacao-a-mais-de-mil-placas-de-sinalizacao-que-estavam-abandonadas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/03\/13\/secretaria-de-seguranca-e-transito-vai-dar-destinacao-a-mais-de-mil-placas-de-sinalizacao-que-estavam-abandonadas\/","title":{"rendered":"Secretaria de Seguran\u00e7a e Tr\u00e2nsito vai dar destina\u00e7\u00e3o a mais de mil placas de sinaliza\u00e7\u00e3o que estavam abandonadas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png\" alt=\"\" class=\"wp-image-6063\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>No in\u00edcio de janeiro, a atual gest\u00e3o encontrou mais de mil placas de tr\u00e2nsito depositadas e sem serem utilizadas, em uma \u00e1rea do Aeroporto Capit\u00e3o Jo\u00e3o Busse. O Munic\u00edpio est\u00e1 concluindo o invent\u00e1rio do material e agora vai elaborar um cronograma para dar uma destina\u00e7\u00e3o \u00e0s placas.<\/p>\n\n\n\n<p>O fato foi trazido a p\u00fablico neste final de semana pelo prefeito Rodolfo Mota e pelo secret\u00e1rio&nbsp;de Seguran\u00e7a P\u00fablica, Tr\u00e2nsito, Transporte e Mobilidade, major&nbsp;Vilson&nbsp;Laurentino&nbsp;da Silva. O prefeito Rodolfo Mota afirma que n\u00e3o houve nenhuma refer\u00eancia sobre o dep\u00f3sito no per\u00edodo de transi\u00e7\u00e3o de governo e a atual gest\u00e3o&nbsp; tomou conhecimento da situa\u00e7\u00e3o somente em uma vistoria de praxe feita no aeroporto, logo no come\u00e7o da gest\u00e3o.<\/p>\n\n\n\n<p>\u201cEnquanto isso, muitos locais necessitam h\u00e1 muito tempo de uma sinaliza\u00e7\u00e3o adequada e que garanta&nbsp; maior seguran\u00e7a, tanto em bairros e quanto na \u00e1rea central de Apucarana\u201d, lamenta Rodolfo Mota, acrescentando que a maioria das placas estava em \u00e1rea coberta e protegida, mas algumas delas foram encontradas literalmente abandonadas na \u00e1rea externa.<\/p>\n\n\n\n<p>O prefeito afirma que, ao tomar conhecimento da situa\u00e7\u00e3o no in\u00edcio de janeiro, a atual gest\u00e3o iniciou um invent\u00e1rio do material. \u201cAt\u00e9 o momento, o levantamento registrou 1.065 somente de placas de sinaliza\u00e7\u00e3o vertical de tr\u00e2nsito. No entanto, existem tamb\u00e9m ainda dezenas de placas de sinaliza\u00e7\u00e3o tur\u00edstica, de indica\u00e7\u00e3o de estradas rurais, de parques e de entradas da cidade\u201d, cita Rodolfo Mota.<\/p>\n\n\n\n<p>A atual gest\u00e3o estima que o dep\u00f3sito encontrado representa um investimento de cerca de mais de R$ 200 mil. \u201cInfelizmente, algumas n\u00e3o v\u00e3o poder ser utilizadas, pois j\u00e1 est\u00e3o fora do padr\u00e3o do C\u00f3digo de Tr\u00e2nsito. Mas a maioria delas est\u00e1 em boas condi\u00e7\u00f5es e poder\u00e1 ser aproveitada. Temos muitos problemas em cruzamentos, por exemplo, que conseguiremos resolver com esse estoque que encontramos. Vamos adquirir outros materiais tamb\u00e9m e fazer uma sinaliza\u00e7\u00e3o adequada em toda a cidade\u201d, ressalta Rodolfo Mota.<\/p>\n\n\n\n<p>De acordo com o major Vilson, h\u00e1 placas que atendem as diversas necessidades de tr\u00e2nsito, como de pare, siga em frente, proibido estacionar, sem\u00e1foro, de embarque e desembarque, carga e descarga, proibido retorno, proibida convers\u00e3o, sentido de circula\u00e7\u00e3o na rotat\u00f3ria, de \u00e1rea de estacionamento do rotativo e de vaga para idoso, entre outras.<\/p>\n\n\n\n<p>O major afirma que h\u00e1 muitos pedidos de placas feitos pela popula\u00e7\u00e3o, muitos deles via protocolo. \u201cVamos analisar os pedidos, verificando qual deles realmente t\u00eam viabilidade. J\u00e1 come\u00e7amos a colocar essas placas que foram encontradas e vamos intensificar o trabalho, dentro de um planejamento elaborado pela nossa equipe\u201d, completa o secret\u00e1rio municipal de Seguran\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio de janeiro, a atual gest\u00e3o encontrou mais de mil placas de tr\u00e2nsito depositadas e sem serem utilizadas, em uma \u00e1rea do Aeroporto Capit\u00e3o Jo\u00e3o Busse. O Munic\u00edpio est\u00e1 concluindo o invent\u00e1rio do material e agora vai elaborar um cronograma para dar uma destina\u00e7\u00e3o \u00e0s placas. O fato foi trazido a p\u00fablico neste final [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/03\/image-57-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=6062"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/6062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/6063"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=6062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=6062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=6062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}