{"id":5892,"date":"2025-02-26T21:11:58","date_gmt":"2025-02-26T21:11:58","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=5892"},"modified":"2025-02-26T21:12:54","modified_gmt":"2025-02-26T21:12:54","slug":"apucarana-repassa-160-mil-mudas-a-cafeicultores-2","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/02\/26\/apucarana-repassa-160-mil-mudas-a-cafeicultores-2\/","title":{"rendered":"Apucarana repassa 160 mil mudas a cafeicultores"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"771\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png\" alt=\"\" class=\"wp-image-5893\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-300x226.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-768x578.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-400x301.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-700x527.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-600x452.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Apucarana deu in\u00edcio \u00e0 entrega de mudas de caf\u00e9 a produtores rurais cadastrados na Secretaria Municipal da Agricultura. Ao todo, 160 mil unidades produzidas pelo munic\u00edpio est\u00e3o sendo repassadas. \u201cEstamos trabalhando para aumentar esse n\u00famero para a pr\u00f3xima safra, garantindo apoio ao cafeicultor de Apucarana, que produz um gr\u00e3o de qualidade reconhecido nacionalmente\u201d, assinala o prefeito Rodolfo Mota, frisando que a cultura do caf\u00e9 desempenha um importante papel social e econ\u00f4mico na cidade, movimentando mais de R$ 215 milh\u00f5es por ano e se destacando como a quarta maior atividade do Munic\u00edpio.<\/p>\n\n\n\n<p>A cidade vem buscando o registro de Indica\u00e7\u00e3o Geogr\u00e1fica (IG), na modalidade Denomina\u00e7\u00e3o de Origem (DO), para o Caf\u00e9 da Serra de Apucarana. Hoje, Apucarana \u00e9 a quinta maior produtora de caf\u00e9 do Paran\u00e1, com uma \u00e1rea cultivada de 1.100 hectares e uma produ\u00e7\u00e3o anual de 2.376 toneladas. \u201cA Serra de Apucarana produz um caf\u00e9 especial que, a partir da conquista deste registro, certamente vai ser ainda mais valorizado no Brasil e at\u00e9 em outros pa\u00edses\u201d, diz Jo\u00e3o Carmo da Fonseca, secret\u00e1rio Municipal da Agricultura.<\/p>\n\n\n\n<p>A an\u00e1lise para a concess\u00e3o da IG ser\u00e1 feita pelo Instituto Nacional de Propriedade Industrial (INPI), \u00f3rg\u00e3o respons\u00e1vel pela certifica\u00e7\u00e3o. O dep\u00f3sito foi viabilizado com subs\u00eddio do programa Sebraetec, do Sebrae\/PR, e recursos da Prefeitura de Apucarana, por meio da Associa\u00e7\u00e3o dos Cafeicultores de Apucarana (Acap), e tamb\u00e9m contou com apoio do IDR-Paran\u00e1, que ofereceu suporte por meio de capacita\u00e7\u00f5es e estudos t\u00e9cnicos.<\/p>\n\n\n\n<p>O caf\u00e9 da Denomina\u00e7\u00e3o de Origem \u201cSerra de Apucarana\u201d \u00e9 cultivado em altitudes entre 700 e 950 metros, em solo vulc\u00e2nico, clima de chuvas regulares e ventos constantes, que influenciam nas caracter\u00edsticas sensoriais.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana deu in\u00edcio \u00e0 entrega de mudas de caf\u00e9 a produtores rurais cadastrados na Secretaria Municipal da Agricultura. Ao todo, 160 mil unidades produzidas pelo munic\u00edpio est\u00e3o sendo repassadas. \u201cEstamos trabalhando para aumentar esse n\u00famero para a pr\u00f3xima safra, garantindo apoio ao cafeicultor de Apucarana, que produz um gr\u00e3o de qualidade reconhecido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png",1024,771,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-300x226.png",300,226,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-768x578.png",768,578,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png",860,648,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png",1024,771,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140.png",1024,771,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-400x301.png",400,301,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-700x700.png",700,700,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-700x527.png",700,527,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-600x452.png",600,452,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-140-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5892"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/5893"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}