{"id":5743,"date":"2025-02-15T21:02:55","date_gmt":"2025-02-15T21:02:55","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=5743"},"modified":"2025-02-15T21:03:27","modified_gmt":"2025-02-15T21:03:27","slug":"tres-adultos-e-uma-crianca-de-dois-anos-ficam-feridos-apos-caminhonete-sair-da-pista-e-capotar-em-rodovia-do-parana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/02\/15\/tres-adultos-e-uma-crianca-de-dois-anos-ficam-feridos-apos-caminhonete-sair-da-pista-e-capotar-em-rodovia-do-parana\/","title":{"rendered":"Tr\u00eas adultos e uma crian\u00e7a de dois anos ficam feridos ap\u00f3s caminhonete sair da pista e capotar em rodovia do Paran\u00e1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"445\" height=\"655\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png\" alt=\"\" class=\"wp-image-5744\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png 445w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-204x300.png 204w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-400x589.png 400w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><figcaption class=\"wp-element-caption\">Foto: Samu<\/figcaption><\/figure>\n\n\n\n<p>Tr\u00eas adultos e uma crian\u00e7a de dois anos ficaram feridos ap\u00f3s a caminhonete em que eles estavam sair da pista e capotar na PR-317, entre Nossa Senhora das Gra\u00e7as e Santa F\u00e9, no norte do Paran\u00e1. O caso aconteceu neste s\u00e1bado (15).<\/p>\n\n\n\n<p>Segundo o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), uma mulher de 55 anos ficou presa \u00e0s ferragens. Ela foi socorrida em estado grave com politraumatismo e foi encaminhada para o Hospital Bom Samaritano, em Maring\u00e1, no norte do estado.<\/p>\n\n\n\n<p>Outra passageira, de 38 anos, quebrou a clav\u00edcula esquerda, e uma crian\u00e7a de dois anos teve uma trauma de cr\u00e2nio leve, tamb\u00e9m de acordo com o Samu. As duas foram encaminhadas para a Santa Casa de Maring\u00e1.<\/p>\n\n\n\n<p>O motorista do ve\u00edculo conseguiu sair sozinho da caminhonete e teve ferimentos leves. Segundo o Samu, ele foi levado para o Hospital Bom Samaritano. De acordo com os socorristas, o homem n\u00e3o soube explicar o que motivou o acidente.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas adultos e uma crian\u00e7a de dois anos ficaram feridos ap\u00f3s a caminhonete em que eles estavam sair da pista e capotar na PR-317, entre Nossa Senhora das Gra\u00e7as e Santa F\u00e9, no norte do Paran\u00e1. O caso aconteceu neste s\u00e1bado (15). Segundo o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), uma mulher de 55 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-204x300.png",204,300,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-400x589.png",400,589,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-445x500.png",445,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-445x600.png",445,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-445x600.png",445,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE.png",445,655,false],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/ACIDENTE-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5743"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/5744"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}