{"id":5584,"date":"2025-02-07T21:35:00","date_gmt":"2025-02-07T21:35:00","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=5584"},"modified":"2025-02-07T21:35:02","modified_gmt":"2025-02-07T21:35:02","slug":"parque-tecnologico-vai-transformar-apucarana-em-polo-de-inovacao-no-pr","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/02\/07\/parque-tecnologico-vai-transformar-apucarana-em-polo-de-inovacao-no-pr\/","title":{"rendered":"Parque tecnol\u00f3gico vai transformar Apucarana em polo de inova\u00e7\u00e3o no PR"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13.png\" alt=\"\" class=\"wp-image-5585\" style=\"width:810px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13-768x512.png 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13-400x267.png 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13-700x467.png 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-13-600x400.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O secret\u00e1rio estadual da Inova\u00e7\u00e3o, Moderniza\u00e7\u00e3o e Transforma\u00e7\u00e3o Digital do Paran\u00e1 (SEI), Alex Canziani, esteve em Apucarana nesta sexta-feira (07\/02), quando apresentou o projeto do Parque Tecnol\u00f3gico Estadual Regional de Apucarana. A estrutura ser\u00e1 implantada em espa\u00e7o situado no Col\u00e9gio Agr\u00edcola, vai receber investimentos de mais de R$ 4 milh\u00f5es e transformar Apucarana em polo estrat\u00e9gico regional de inova\u00e7\u00e3o no Paran\u00e1.<\/p>\n\n\n\n<p>O projeto foi apresentado ao prefeito Rodolfo Mota, em reuni\u00e3o que ocorreu no sal\u00e3o nobre da Prefeitura, e contou com a presen\u00e7a da diretoria da Associa\u00e7\u00e3o Comercial, Industrial e de Servi\u00e7os (Acia) e de representantes das diversas institui\u00e7\u00f5es que integram o Conecta.<\/p>\n\n\n\n<p>Alex Canziani afirma que o projeto do parque de Apucarana ser\u00e1 desenvolvido concomitantemente com o do parque de Londrina e, juntos, v\u00e3o somar investimentos de mais de R$ 12 milh\u00f5es. De acordo com ele, \u00e9 uma iniciativa do governo do Estado com o objetivo de criar ambientes de inova\u00e7\u00e3o e um eixo de desenvolvimento entre Londrina, Apucarana e o Vale do Iva\u00ed.<\/p>\n\n\n\n<p>\u201cUm parque que vai estar dentro de uma escola agr\u00edcola e que vai atender a regi\u00e3o e lev\u00e1-la para o outro patamar. Da mesma forma que o governador vem fazendo em v\u00e1rias \u00e1reas, queremos que esse parque tecnol\u00f3gico seja uma nova refer\u00eancia para o Paran\u00e1 e para o Brasil\u201d, ressalta Canziani.<\/p>\n\n\n\n<p>O prefeito Rodolfo Mota salienta que o agroneg\u00f3cio \u00e9 uma voca\u00e7\u00e3o natural de Apucarana e do Vale do Iva\u00ed. \u201cO parque vai abarcar todo o conhecimento que n\u00f3s temos aqui e atrair novos investimentos. Isso abrir\u00e1 um leque de oportunidades, especialmente no agroneg\u00f3cio. Esperamos que o que aconteceu l\u00e1 atr\u00e1s com o Centro Moda se repita novamente. Obrigado, Alex Canziani, por nos dar essa tarefa e essa miss\u00e3o de construir um projeto t\u00e3o grande\u201d, assinala Rodolfo Mota.<\/p>\n\n\n\n<p>O Parque Tecnol\u00f3gico vai transformar Apucarana em polo estrat\u00e9gico regional de inova\u00e7\u00e3o no Paran\u00e1, conectando universidades, centros de capacita\u00e7\u00e3o e clusters produtivos regionais. Com infraestrutura e espa\u00e7os colaborativos, vai fortalecer a transfer\u00eancia de tecnologia e a cria\u00e7\u00e3o de neg\u00f3cios inovadores.<\/p>\n\n\n\n<p><strong>PIONEIRISMO \u2013<\/strong>&nbsp;O professor Jos\u00e9 Eduardo Padilha de Sousa, que fez a apresenta\u00e7\u00e3o do projeto, afirma que esse dever\u00e1 ser o primeiro parque tecnol\u00f3gico que ser\u00e1 implantado e operacionalizado totalmente dentro de um espa\u00e7o p\u00fablico. De acordo com ele, todo esse processo ser\u00e1 conduzido com a consultoria do Parque de Inova\u00e7\u00e3o Tecnol\u00f3gico (PIT) de S\u00e3o Jos\u00e9 dos Campos, que \u00e9 pioneiro em S\u00e3o Paulo neste tipo de iniciativa.<\/p>\n\n\n\n<p>O presidente da Acia e do Conecta, Wanderlei Faganello, destacou a presen\u00e7a de representantes de diversas institui\u00e7\u00f5es, afirmando que todos tiveram a oportunidade de dar sugest\u00f5es e tirar d\u00favidas. De acordo com ele, a partir de agora dever\u00e1 ser criado um grupo de trabalho e uma visita ao PIT de S\u00e3o Jos\u00e9 dos Campos dever\u00e1 ser agendada.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio estadual da Inova\u00e7\u00e3o, Moderniza\u00e7\u00e3o e Transforma\u00e7\u00e3o Digital do Paran\u00e1 (SEI), Alex Canziani, esteve em Apucarana nesta sexta-feira (07\/02), quando apresentou o projeto do Parque Tecnol\u00f3gico Estadual Regional de Apucarana. A estrutura ser\u00e1 implantada em espa\u00e7o situado no Col\u00e9gio Agr\u00edcola, vai receber investimentos de mais de R$ 4 milh\u00f5es e transformar Apucarana em polo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14.png",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-150x150.png",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-300x200.png",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-768x512.png",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14.png",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14.png",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14.png",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-400x300.png",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-400x600.png",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-400x400.png",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-400x267.png",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-700x500.png",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-700x683.png",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-700x467.png",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-1000x600.png",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-1024x600.png",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-300x300.png",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-600x400.png",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/02\/image-14-100x100.png",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5584"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/5586"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}