{"id":556,"date":"2023-09-18T19:53:59","date_gmt":"2023-09-18T19:53:59","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=556"},"modified":"2023-09-18T19:54:03","modified_gmt":"2023-09-18T19:54:03","slug":"apucarana-recupera-pontes-na-divisa-com-california","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/18\/apucarana-recupera-pontes-na-divisa-com-california\/","title":{"rendered":"Apucarana recupera pontes na divisa com Calif\u00f3rnia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Ponte-Figueirinha2-989x1024-1.jpeg\" alt=\"\" class=\"wp-image-557\" style=\"width:687px;height:711px\" width=\"687\" height=\"711\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Ponte-Figueirinha2-989x1024-1.jpeg 989w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Ponte-Figueirinha2-989x1024-1-600x621.jpeg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Ponte-Figueirinha2-989x1024-1-290x300.jpeg 290w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Ponte-Figueirinha2-989x1024-1-768x795.jpeg 768w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/figure>\n\n\n\n<p>A Secretaria de Servi\u00e7os P\u00fablicos da Prefeitura de Apucarana concluiu na \u00faltima semana a reforma de duas passagens sobre rios. As pontes, localizadas nas estradas rurais Figueirinha e Jacucaca, na regi\u00e3o do Distrito de S\u00e3o Pedro Taquara, atendem ainda a produtores rurais do munic\u00edpio de Calif\u00f3rnia.<\/p>\n\n\n\n<p>Segundo explica o prefeito J\u00fanior da Femac, a melhoria foi executada totalmente por Apucarana. \u201cAl\u00e9m de estradas em condi\u00e7\u00f5es de trafegabilidade, o homem do campo necessita de pontes seguras. Desde 2019, dezenas de passagens sobre rios e c\u00f3rregos foram revitalizadas e agora, na \u00faltima semana, nossas equipes executaram melhorias na Figueirinha e na Jacucaca, beneficiando o escoamento da safra de trigo\u201d, comenta o prefeito.<\/p>\n\n\n\n<p>De acordo com o superintendente da Secretaria de Servi\u00e7os P\u00fablicos, Mauro Toshio Kitano, a maior ponte recuperada foi a da Estrada Figueirinha, com 13 metros de comprimento. J\u00e1 a da Jacucaca, tem 7 metros. \u201cAl\u00e9m da produ\u00e7\u00e3o agr\u00edcola, s\u00e3o pontes que recebem diariamente o tr\u00e1fego de linhas do transporte escolar\u201d, acentua Toshio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Servi\u00e7os P\u00fablicos da Prefeitura de Apucarana concluiu na \u00faltima semana a reforma de duas passagens sobre rios. As pontes, localizadas nas estradas rurais Figueirinha e Jacucaca, na regi\u00e3o do Distrito de S\u00e3o Pedro Taquara, atendem ainda a produtores rurais do munic\u00edpio de Calif\u00f3rnia. Segundo explica o prefeito J\u00fanior da Femac, a melhoria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-556","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/556\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}