{"id":550,"date":"2023-09-18T19:39:35","date_gmt":"2023-09-18T19:39:35","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=550"},"modified":"2023-09-18T19:39:36","modified_gmt":"2023-09-18T19:39:36","slug":"apucarana-implanta-programa-brigadas-escolares-na-rede-municipal-de-educacao","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/18\/apucarana-implanta-programa-brigadas-escolares-na-rede-municipal-de-educacao\/","title":{"rendered":"Apucarana implanta programa \u2018Brigadas Escolares\u2019 na rede municipal de educa\u00e7\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-15-at-20.30.45-2-1024x682-1.jpeg\" alt=\"\" class=\"wp-image-551\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-15-at-20.30.45-2-1024x682-1.jpeg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-15-at-20.30.45-2-1024x682-1-600x400.jpeg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-15-at-20.30.45-2-1024x682-1-300x200.jpeg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-15-at-20.30.45-2-1024x682-1-768x512.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Apucarana \u00e9 a primeira cidade, na \u00e1rea de abrang\u00eancia do N\u00facleo Regional de Educa\u00e7\u00e3o, a implantar o programa \u2018Brigadas Escolares\u2019 nas sessenta unidades da rede municipal de ensino. Aproximadamente 450 professores e servidores j\u00e1 conclu\u00edram a primeira etapa do curso de forma\u00e7\u00e3o, na modalidade de Educa\u00e7\u00e3o a Dist\u00e2ncia (EaD). A abertura da segunda fase, presencial, foi realizada na noite de hoje (15\/9) no Cine Teatro F\u00eanix.<\/p>\n\n\n\n<p>O prefeito Junior da Femac destacou a import\u00e2ncia do programa \u2018Brigadas Escolares\u2019 para a preven\u00e7\u00e3o e o enfrentamento de situa\u00e7\u00f5es de risco. \u201cOs brigadistas escolares s\u00e3o servidores que recebem treinamento espec\u00edfico para fazer o atendimento b\u00e1sico de outros servidores e estudantes em casos de emerg\u00eancia, liderar o abandono da edifica\u00e7\u00e3o escolar \u2013 se necess\u00e1rio \u2013 com seguran\u00e7a, levantar as necessidades de adequa\u00e7\u00e3o do ambiente e incentivar a constru\u00e7\u00e3o de uma cultura de preven\u00e7\u00e3o na comunidade escolar,\u201d explicou.<\/p>\n\n\n\n<p>A Lei n\u00ba 18.424, de 8 de janeiro de 2015, instituiu as Brigadas Escolares na rede estadual de educa\u00e7\u00e3o do Paran\u00e1. Posteriormente, em 7 de dezembro de 2021, a Lei n\u00ba 20.863, possibilitou que o programa fosse estendido tamb\u00e9m \u00e0s redes municipais de ensino.<\/p>\n\n\n\n<p>\u201cA primeira etapa do curso de forma\u00e7\u00e3o de brigadistas foi ofertada pela Escola de Defesa Civil, no per\u00edodo de 26 de junho a 14 de agosto, e teve carga hor\u00e1ria de 70 horas, referentes a conte\u00fados te\u00f3ricos. J\u00e1 a segunda fase, que iniciamos agora, ser\u00e1 ministrada presencialmente por militares do Batalh\u00e3o de Patrulha Escolar Comunit\u00e1ria e do 11\u00ba Grupamento de Bombeiros, e ter\u00e1 carga hor\u00e1ria de 24 horas, referentes a simula\u00e7\u00f5es e atividades pr\u00e1ticas,\u201d detalhou a secret\u00e1ria municipal de educa\u00e7\u00e3o, professora Marli Fernandes.<\/p>\n\n\n\n<p>Na noite desta sexta-feira (15\/9), no Cine Teatro F\u00eanix, os futuros brigadistas assistiram a tr\u00eas breves palestras, proferidas pelo Major \u00c9lcio Jos\u00e9 de Meira (11\u00ba GB), pela Sargento Camila Aniele Pinto (BPEC) e pela secret\u00e1ria de educa\u00e7\u00e3o Marli Fernandes. Estudantes da turma de 4\u00ba ano da Escola Municipal Jos\u00e9 Id\u00e9sio Brianezi abrilhantaram a programa\u00e7\u00e3o com a apresenta\u00e7\u00e3o de uma coreografia da can\u00e7\u00e3o Heroes, do DJ Alesso.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apucarana \u00e9 a primeira cidade, na \u00e1rea de abrang\u00eancia do N\u00facleo Regional de Educa\u00e7\u00e3o, a implantar o programa \u2018Brigadas Escolares\u2019 nas sessenta unidades da rede municipal de ensino. Aproximadamente 450 professores e servidores j\u00e1 conclu\u00edram a primeira etapa do curso de forma\u00e7\u00e3o, na modalidade de Educa\u00e7\u00e3o a Dist\u00e2ncia (EaD). A abertura da segunda fase, presencial, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-550","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=550"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/550\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}