{"id":5481,"date":"2025-01-17T12:40:14","date_gmt":"2025-01-17T12:40:14","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=5481"},"modified":"2025-01-17T12:40:16","modified_gmt":"2025-01-17T12:40:16","slug":"ainda-restam-250-vagas-para-a-prova-28-de-janeiro","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2025\/01\/17\/ainda-restam-250-vagas-para-a-prova-28-de-janeiro\/","title":{"rendered":"Ainda restam 250 vagas para a Prova 28 de Janeiro"},"content":{"rendered":"\n<p>Quem quiser participar da Prova Pedestre 28 de Janeiro, ainda d\u00e1 tempo. O prefeito Rodolfo Mota anunciou na manh\u00e3 desta sexta-feira (17\/01) que ainda restam 250 vagas remanescentes. Os interessados devem fazer as inscri\u00e7\u00f5es pelo site&nbsp;<a href=\"https:\/\/www.apucarana.pr.gov.br\/corrida28\">https:\/\/www.apucarana.pr.gov.br\/corrida28<\/a><\/p>\n\n\n\n<p>Rodolfo Mota reitera que a capacidade m\u00e1xima da prova \u00e9 de 4.200 atletas e as 250 vagas remanescentes s\u00e3o de corredores que, por algum motivo, deixaram de confirmar a inscri\u00e7\u00e3o. O prefeito orienta os interessados a fazerem a inscri\u00e7\u00e3o o mais r\u00e1pido poss\u00edvel. \u201cNa \u00faltima vez em que abrimos as inscri\u00e7\u00f5es para vagas remanescentes, elas se esgotaram em menos de tr\u00eas horas\u201d, observa Rodolfo Mota, ressaltando que a inscri\u00e7\u00e3o \u00e9 confirmada somente ap\u00f3s o pagamento do boleto.<\/p>\n\n\n\n<p>A prova integra a programa\u00e7\u00e3o de anivers\u00e1rio da cidade e acontecer\u00e1 na abertura dos festejos, no dia 25 de janeiro. &nbsp;Al\u00e9m dos corredores amadores, est\u00e3o confirmados atletas de ponta do pedestrianismo nacional e internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem quiser participar da Prova Pedestre 28 de Janeiro, ainda d\u00e1 tempo. O prefeito Rodolfo Mota anunciou na manh\u00e3 desta sexta-feira (17\/01) que ainda restam 250 vagas remanescentes. Os interessados devem fazer as inscri\u00e7\u00f5es pelo site&nbsp;https:\/\/www.apucarana.pr.gov.br\/corrida28 Rodolfo Mota reitera que a capacidade m\u00e1xima da prova \u00e9 de 4.200 atletas e as 250 vagas remanescentes s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre.jpg",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-150x150.jpg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-768x512.jpg",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre.jpg",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre.jpg",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre.jpg",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-400x300.jpg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-400x600.jpg",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-400x400.jpg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-400x267.jpg",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-700x500.jpg",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-700x683.jpg",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-700x467.jpg",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-1000x600.jpg",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-1024x600.jpg",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2025\/01\/corre-100x100.jpg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5481"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/5482"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}