{"id":5259,"date":"2024-12-16T12:12:05","date_gmt":"2024-12-16T12:12:05","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=5259"},"modified":"2024-12-16T12:12:06","modified_gmt":"2024-12-16T12:12:06","slug":"apucarana-publica-livro-sobre-educacao-integral-nas-cidades-educadoras","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/12\/16\/apucarana-publica-livro-sobre-educacao-integral-nas-cidades-educadoras\/","title":{"rendered":"Apucarana publica livro sobre Educa\u00e7\u00e3o Integral nas Cidades Educadoras"},"content":{"rendered":"\n<p>Na noite de ontem (12\/12), no Cine Teatro F\u00eanix, a Autarquia Municipal de Educa\u00e7\u00e3o apresentou o livro \u201cEduca\u00e7\u00e3o Integral: curr\u00edculo e cidadania nas Cidades Educadoras\u201d. Organizada pela secret\u00e1ria municipal de educa\u00e7\u00e3o, Marli Fernandes, e publicada pela Editora Compass, a obra \u00e9 inspirada na trajet\u00f3ria do munic\u00edpio na implementa\u00e7\u00e3o de um modelo educacional que levou Apucarana a conquistar, em agosto de 2023, o t\u00edtulo de Cidade Educadora.<\/p>\n\n\n\n<p>O CEO da Editora Compass, Juan Fortun, destacou a relev\u00e2ncia da obra para a dissemina\u00e7\u00e3o de projetos educacionais bem-sucedidos em todo o pa\u00eds. \u201cPercebemos que existem iniciativas excelentes em muitos munic\u00edpios, mas muitas vezes elas permanecem restritas \u00e0 sua localidade. Por isso, criamos a Cole\u00e7\u00e3o Cidades Educadoras, com o objetivo de divulgar projetos como o de Apucarana, que \u00e9 pioneiro e refer\u00eancia em Educa\u00e7\u00e3o Integral. Apucarana se tornou modelo e a Professora Marli Fernandes e sua equipe foram convidadas para organizar este livro\u201d, afirmou.<\/p>\n\n\n\n<p>A secret\u00e1ria Marli Fernandes ressaltou que o livro aborda a integra\u00e7\u00e3o do curr\u00edculo da Educa\u00e7\u00e3o Integral com a Base Nacional Comum Curricular (BNCC), os Temas Contempor\u00e2neos Transversais, os Objetivos de Desenvolvimento Sustent\u00e1vel (ODS) e as potencialidades das Cidades Educadoras. \u201cA publica\u00e7\u00e3o \u00e9 resultado de um esfor\u00e7o coletivo, com a colabora\u00e7\u00e3o de todos os professores e servidores da rede municipal de Apucarana, que contribu\u00edram para transformar essa obra em realidade\u201d, afirmou.<\/p>\n\n\n\n<p>O prefeito Junior da Femac, presente no evento, comemorou a import\u00e2ncia do livro. \u201cAcredito que o maior patrim\u00f4nio de uma cidade \u00e9 sua popula\u00e7\u00e3o, e, por isso, a educa\u00e7\u00e3o tem sido minha prioridade. Este livro \u00e9 a materializa\u00e7\u00e3o da experi\u00eancia de Apucarana e servir\u00e1 como base para pesquisas acad\u00eamicas e refer\u00eancia para gestores de outros munic\u00edpios que queiram replicar nossas iniciativas\u201d, destacou.<\/p>\n\n\n\n<p>Durante o evento, o professor titular da Faculdade de Educa\u00e7\u00e3o da Universidade Estadual de Campinas (UNICAMP), Dr. C\u00e9sar Nunes, ministrou a palestra \u201cA Educa\u00e7\u00e3o Integral da Cidade Educadora\u201d. Ao final da palestra, ele entregou ao prefeito Junior da Femac e \u00e0 secret\u00e1ria Marli Fernandes o Diploma de M\u00e9rito Educacional Professor Darcy Ribeiro, concedido pelo Instituto Darcy Ribeiro a pessoas que se destacam por sua contribui\u00e7\u00e3o \u00e0 educa\u00e7\u00e3o no Brasil.<\/p>\n\n\n\n<p>A obra conta ainda com a colabora\u00e7\u00e3o de diversos coordenadores pedag\u00f3gicos da Autarquia Municipal de Educa\u00e7\u00e3o de Apucarana, que contribu\u00edram com os artigos que comp\u00f5em o livro. Entre eles, est\u00e3o Alice Damiana Morciani Kanno, Aline Barboza Domaredzki, Cristiane Regina Bellafronte de Castro, Danieli Cristina dos Santos Jorgeto, \u00c9lida Lusia Fenato, Ellen Carolina Pereira Castilho, Evelyn Bispo da Silva, Geizebel Viana Ribeiro Rodrigues, Janete Aparecida Primon, L\u00e9ia Sofia Soares dos Santos Viale, Leiliane Barros Cardoso Almeida, Lucilene Moraes Ribeiro da Silva, Lucimara de Mattos, Maria Aparecida Taborda Fernandes de Barros, Mateus Morial Carrascoso, Patr\u00edcia de Jesus Pinto, Rodolfo J\u00fanio do Nascimento, R\u00fabia Cristina de Almeida Gon\u00e7alves da Silva, Shaiana Gomes de Moraes, Tairine Suelen Carneiro, Tha\u00eds Ang\u00e9lica Carneiro Moreira, Vitor Felipe Bota e Margarete Maria Baldini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite de ontem (12\/12), no Cine Teatro F\u00eanix, a Autarquia Municipal de Educa\u00e7\u00e3o apresentou o livro \u201cEduca\u00e7\u00e3o Integral: curr\u00edculo e cidadania nas Cidades Educadoras\u201d. Organizada pela secret\u00e1ria municipal de educa\u00e7\u00e3o, Marli Fernandes, e publicada pela Editora Compass, a obra \u00e9 inspirada na trajet\u00f3ria do munic\u00edpio na implementa\u00e7\u00e3o de um modelo educacional que levou Apucarana [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1.jpg",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-150x150.jpg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-768x512.jpg",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1.jpg",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1.jpg",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1.jpg",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-400x300.jpg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-400x600.jpg",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-400x400.jpg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-400x267.jpg",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-700x500.jpg",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-700x683.jpg",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-700x467.jpg",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-1000x600.jpg",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-1024x600.jpg",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/12\/Lancamento-Livro-14-1024x683-1-100x100.jpg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=5259"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/5259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/5260"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=5259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=5259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=5259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}