{"id":518,"date":"2023-09-15T16:35:49","date_gmt":"2023-09-15T16:35:49","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=518"},"modified":"2023-09-15T16:35:50","modified_gmt":"2023-09-15T16:35:50","slug":"morre-no-hospital-a-quarta-crianca-vitima-de-atropelamento-em-londrina","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/15\/morre-no-hospital-a-quarta-crianca-vitima-de-atropelamento-em-londrina\/","title":{"rendered":"Morre no hospital a quarta crian\u00e7a v\u00edtima de atropelamento em Londrina"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O tr\u00e1gico acidente ocorreu por volta das 18 horas. As crian\u00e7as retornavam da escola quando foram atropeladas<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"644\" height=\"402\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-Kombi-era-conduzida-por-um-homem-de-73-anos-mora-00792818-0-202309150823-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-519\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-Kombi-era-conduzida-por-um-homem-de-73-anos-mora-00792818-0-202309150823-ScaleDownProportional.webp 644w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-Kombi-era-conduzida-por-um-homem-de-73-anos-mora-00792818-0-202309150823-ScaleDownProportional-600x375.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/A-Kombi-era-conduzida-por-um-homem-de-73-anos-mora-00792818-0-202309150823-ScaleDownProportional-300x187.webp 300w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><\/figure>\n\n\n\n<p>Morreu no Hospital Universit\u00e1rio (HU), por volta das 22 horas desta quinta-feira (14), a quarta crian\u00e7a v\u00edtima de atropelamento por uma VW Kombi, no distrito de S\u00e3o Luiz, em\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/londrina?d=1\" target=\"_blank\">Londrina<\/a>\u00a0no norte do Paran\u00e1.<\/p>\n\n\n\n<p>As crian\u00e7as mortas na trag\u00e9dia s\u00e3o as irm\u00e3s Kemilly e Kelly, de 6 e 10 anos, e os irm\u00e3os g\u00eameos Adrian e Vin\u00edcius, de 7 anos. Uma adolescente de 15 anos ficou ferida. Irm\u00e3 das meninas mortas, ela teve ferimentos moderados e n\u00e3o corre risco de morte.<\/p>\n\n\n\n<p>O acidente ocorreu por volta das 18 horas desta quinta-feira (14). Segundo a Pol\u00edcia Militar (PM), os g\u00eameos tinham sa\u00eddo da casa de uma cuidadora. J\u00e1 as tr\u00eas irm\u00e3s tinham sa\u00eddo da escola e tamb\u00e9m passaram na casa da cuidadora para buscar os meninos.<\/p>\n\n\n\n<p>O condutor do ve\u00edculo, de 73 anos, morador de Londrina, seguia sentido Guaravera para S\u00e3o Luiz e estava vendendo produtos de limpeza na regi\u00e3o. Ele relatou que foi atrapalhado pelo sol e n\u00e3o teria visto as crian\u00e7as, que estavam caminhando no sentido oposto ao ve\u00edculo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tr\u00e1gico acidente ocorreu por volta das 18 horas. As crian\u00e7as retornavam da escola quando foram atropeladas Morreu no Hospital Universit\u00e1rio (HU), por volta das 22 horas desta quinta-feira (14), a quarta crian\u00e7a v\u00edtima de atropelamento por uma VW Kombi, no distrito de S\u00e3o Luiz, em\u00a0Londrina\u00a0no norte do Paran\u00e1. As crian\u00e7as mortas na trag\u00e9dia s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-518","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/518\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}