{"id":4972,"date":"2024-11-07T14:37:31","date_gmt":"2024-11-07T14:37:31","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=4972"},"modified":"2024-11-07T14:37:32","modified_gmt":"2024-11-07T14:37:32","slug":"apucarana-disponibiliza-vacina-gratuita-contra-a-dengue-a-criancas-e-adolescentes","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/11\/07\/apucarana-disponibiliza-vacina-gratuita-contra-a-dengue-a-criancas-e-adolescentes\/","title":{"rendered":"Apucarana disponibiliza vacina gratuita contra a dengue a crian\u00e7as e adolescentes"},"content":{"rendered":"\n<p>Com apenas 63 doses aplicadas nos \u00faltimos 15 dias, o prefeito de Apucarana, J\u00fanior da Femac, voltou a refor\u00e7ar nesta quarta-feira (06\/11) apelo para que pais ou demais respons\u00e1veis levem as crian\u00e7as e adolescentes, com idades entre 10 e 14 anos, para tomar as doses da vacina contra a dengue.<\/p>\n\n\n\n<p>No final de novembro, com a confirma\u00e7\u00e3o da primeira morte no Paran\u00e1 ocasionada pela doen\u00e7a dentro do atual ciclo epidemiol\u00f3gico, J\u00fanior da Femac j\u00e1 havia alertado sobre a disponibilidade gratuita do imunizante na rede p\u00fablica e a import\u00e2ncia da vacina\u00e7\u00e3o. \u201cO cen\u00e1rio atual \u00e9 alarmante, pois temos um panorama bastante semelhante ao enfrentado no \u00faltimo ciclo da doen\u00e7a, com cidades vizinha registrando crescente n\u00famero de novos casos, e temos que agir de forma preventiva e coordenada para impedir que a doen\u00e7a avance. Dengue mata e todos, poder p\u00fablico e sociedade, precisamos fazer a nossa parte para evitarmos passar novamente por uma epidemia\u201d, justificou o prefeito.<\/p>\n\n\n\n<p>Segundo a Autarquia Municipal de Sa\u00fade (AMS), apesar da disponibilidade de doses suficientes para atender ao p\u00fablico de 10 a 14 anos, a procura tem sido baixa, com apenas 63 doses aplicadas nos \u00faltimos 15 dias. \u201cReiteramos aos pais e demais respons\u00e1veis que a vacina contra a dengue \u00e9 segura, gratuita e est\u00e1 \u00e0 disposi\u00e7\u00e3o em todas as 27 Unidades B\u00e1sicas de Sa\u00fade de Apucarana (UBS\u2019s) com sala de vacina\u00e7\u00e3o\u201d, diz Em\u00eddio Bachiega, secret\u00e1rio municipal de Sa\u00fade.<\/p>\n\n\n\n<p>O esquema vacinal \u00e9 composto por duas doses com intervalo de tr\u00eas meses entre elas. \u201cO imunizante, que na rede privada de sa\u00fade tem custo entre R$350 e R$490, \u00e9 disponibilizado gratuitamente na rede p\u00fablica para crian\u00e7as e adolescentes na faixa entre os 10 e 14 anos\u201d, refor\u00e7a Bachiega, pontuando que a lista das unidades b\u00e1sicas de sa\u00fade com sala de vacina\u00e7\u00e3o est\u00e1 dispon\u00edvel do portal da prefeitura na internet, no endere\u00e7o:&nbsp;<a href=\"https:\/\/www.apucarana.pr.gov.br\/site\/unidades-basicas-de-saude-ubs\">https:\/\/www.apucarana.pr.gov.br\/site\/unidades-basicas-de-saude-ubs.<\/a>&nbsp;O p\u00fablico alvo (10 a 14 anos) foi definido pelo Minist\u00e9rio da Sa\u00fade.<\/p>\n\n\n\n<p><strong>Atendimento&nbsp;<\/strong>\u2013 A procura de atendimento m\u00e9dico nos primeiros sintomas da dengue \u00e9 fator importante. \u201cEm caso de sintomas da dengue, a pessoa deve procurar a UBS Bolivar Pav\u00e3o, no Jardim Am\u00e9rica, que \u00e9 especializada no atendimento da doen\u00e7a\u201d, orienta Em\u00eddio Bachiega, secret\u00e1rio Municipal da Sa\u00fade. O pronto atendimento est\u00e1 aberto de domingo a domingo. De segunda-feira a sexta-feira funciona entre 7 e 22 horas e, s\u00e1bados, domingos e feriados das 8 \u00e0s 22 horas.<\/p>\n\n\n\n<p><strong>Sintomas&nbsp;<\/strong>\u2013 Normalmente, a primeira manifesta\u00e7\u00e3o da dengue \u00e9 a febre alta (39\u00b0 a 40\u00b0C) de in\u00edcio abrupto e que, geralmente, dura de 2 a 7 dias, acompanhada de dor de cabe\u00e7a, dores no corpo e articula\u00e7\u00f5es, al\u00e9m de prostra\u00e7\u00e3o, fraqueza, dor atr\u00e1s dos olhos, erup\u00e7\u00e3o e coceira na pele. Perda de peso, n\u00e1useas e v\u00f4mitos s\u00e3o comuns. Em alguns casos, o paciente tamb\u00e9m apresenta manchas vermelhas na pele.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com apenas 63 doses aplicadas nos \u00faltimos 15 dias, o prefeito de Apucarana, J\u00fanior da Femac, voltou a refor\u00e7ar nesta quarta-feira (06\/11) apelo para que pais ou demais respons\u00e1veis levem as crian\u00e7as e adolescentes, com idades entre 10 e 14 anos, para tomar as doses da vacina contra a dengue. No final de novembro, com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina.jpg",1024,683,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-150x150.jpg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-768x512.jpg",768,512,true],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina.jpg",860,574,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina.jpg",1024,683,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina.jpg",1024,683,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-400x300.jpg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-400x600.jpg",400,600,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-400x400.jpg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-400x267.jpg",400,267,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-700x500.jpg",700,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-700x683.jpg",700,683,true],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-700x467.jpg",700,467,true],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-1000x600.jpg",1000,600,true],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-1024x600.jpg",1024,600,true],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/11\/dengue-vacina-100x100.jpg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=4972"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/4973"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=4972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=4972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=4972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}