{"id":4661,"date":"2024-10-09T12:34:35","date_gmt":"2024-10-09T12:34:35","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=4661"},"modified":"2024-10-09T12:45:07","modified_gmt":"2024-10-09T12:45:07","slug":"coisas-de-apucarana-idade-que-nao-define-indole-nem-carater-moral-idoso-flagrado-cometendo-crime","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/10\/09\/coisas-de-apucarana-idade-que-nao-define-indole-nem-carater-moral-idoso-flagrado-cometendo-crime\/","title":{"rendered":"Idade que n\u00e3o define \u00edndole nem car\u00e1ter moral, idoso flagrado cometendo crime no centro de  Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"457\" height=\"597\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-2.jpeg\" alt=\"\" class=\"wp-image-4665\" style=\"width:330px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-2.jpeg 457w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-2-230x300.jpeg 230w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-2-400x523.jpeg 400w\" sizes=\"(max-width: 457px) 100vw, 457px\" \/><\/figure>\n\n\n\n<p>O circuito de monitoramento de um im\u00f3vel flagrou o furto de um aparelho celular em Apucarana. <\/p>\n\n\n\n<p>O que chama a aten\u00e7\u00e3o \u00e9 quem cometeu o crime: um idoso.<\/p>\n\n\n\n<p>O idoso tirou proveito de um jovem em estado de vulnerabilidade, dormindo na rua,  e roubou o celular  dele sem que o mesmo notasse.<br><\/p>\n\n\n\n<p>A pol\u00edcia pede ajuda para identific\u00e1-lo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O circuito de monitoramento de um im\u00f3vel flagrou o furto de um aparelho celular em Apucarana. O que chama a aten\u00e7\u00e3o \u00e9 quem cometeu o crime: um idoso. O idoso tirou proveito de um jovem em estado de vulnerabilidade, dormindo na rua, e roubou o celular dele sem que o mesmo notasse. A pol\u00edcia pede [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"featured_image_urls":{"full":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-150x150.jpeg",150,150,true],"medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-300x289.jpeg",300,289,true],"medium_large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"1536x1536":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"2048x2048":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"rivax-small":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-400x300.jpeg",400,300,true],"rivax-small-tall":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-400x587.jpeg",400,587,true],"rivax-small-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-400x400.jpeg",400,400,true],"rivax-small-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-400x386.jpeg",400,386,true],"rivax-medium":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-609x500.jpeg",609,500,true],"rivax-medium-square":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"rivax-medium-masonry":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"rivax-large":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"rivax-large-wide":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao.jpeg",609,587,false],"woocommerce_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-300x300.jpeg",300,300,true],"woocommerce_single":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-600x578.jpeg",600,578,true],"woocommerce_gallery_thumbnail":["https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/10\/veio-ladrao-100x100.jpeg",100,100,true]},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=4661"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media\/4662"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=4661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=4661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=4661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}