{"id":457,"date":"2023-09-13T14:58:54","date_gmt":"2023-09-13T14:58:54","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=457"},"modified":"2023-09-13T14:58:54","modified_gmt":"2023-09-13T14:58:54","slug":"policia-dos-eua-captura-brasileiro-condenado-a-prisao-perpetua","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/13\/policia-dos-eua-captura-brasileiro-condenado-a-prisao-perpetua\/","title":{"rendered":"Pol\u00edcia dos EUA captura brasileiro condenado \u00e0 pris\u00e3o perp\u00e9tua"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O brasileiro, condenado \u00e0 pris\u00e3o perp\u00e9tua por matar a ex-namorada, escalou as paredes da pris\u00e3o para conseguir fugir<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"533\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Cavalcante-foi-preso-pouco-depois-das-08h-no-horar-00792130-0-202309131141-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-458\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Cavalcante-foi-preso-pouco-depois-das-08h-no-horar-00792130-0-202309131141-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Cavalcante-foi-preso-pouco-depois-das-08h-no-horar-00792130-0-202309131141-ScaleDownProportional-600x359.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Cavalcante-foi-preso-pouco-depois-das-08h-no-horar-00792130-0-202309131141-ScaleDownProportional-300x179.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Cavalcante-foi-preso-pouco-depois-das-08h-no-horar-00792130-0-202309131141-ScaleDownProportional-768x459.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>Depois de 14 dias foragido, o brasileiro Danilo Cavalcante foi capturado pela pol\u00edcia da Pensilv\u00e2nia, nos\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/estados-unidos?d=1\">Estados Unidos<\/a>, nesta quarta-feira (13). O homem conseguiu fugir da cadeia onde cumpria uma senten\u00e7a de pris\u00e3o perp\u00e9tua por matar a ex-namorada.<\/p>\n\n\n\n<p>A partir da\u00ed, uma megaopera\u00e7\u00e3o com 500 policiais, participa\u00e7\u00e3o do FBI e fechamento de escolas e parques foi realizada para que Cavalcante fosse encontrado. A regi\u00e3o do condado de Chester se viu em terror, porque a pol\u00edcia local afirmou nas redes sociais que se tratava de um indiv\u00edduo perigoso. Autoridades pediram que os moradores ficassem em casa.<\/p>\n\n\n\n<p>O brasileiro saiu da pris\u00e3o escalando as paredes. Durante a fuga, ele caminhou cerca de 38 quil\u00f4metros, roubou uma van e um rifle e trocou tiros com um morador.<\/p>\n\n\n\n<p>As autoridades contaram com a ajuda de c\u00e2meras t\u00e9rmicas e c\u00e3es farejadores para encontrar o homem. Com o aux\u00edlio de tais equipamentos, Danilo foi localizado sob uma pilha de madeira dentro do per\u00edmetro de buscas. Segundo a pol\u00edcia, ele n\u00e3o apresentava ferimentos graves, e nenhum tiro foi disparado.<\/p>\n\n\n\n<p><em>&#8220;A captura de Cavalcante d\u00e1 fim ao pesadelo das duas \u00faltimas semanas, e agradecemos a cada um dos policiais regionais, estatuais e federais que sa\u00edram \u00e0s ruas em todas as condi\u00e7\u00f5es, dia e noite&#8221;<\/em>, declarou a pol\u00edcia do condado de Chester, na Pensilv\u00e2nia, em comunicado.<\/p>\n\n\n\n<p>Cavalcante foi preso pouco depois das 08h no hor\u00e1rio local (09h no hor\u00e1rio de Bras\u00edlia).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O brasileiro, condenado \u00e0 pris\u00e3o perp\u00e9tua por matar a ex-namorada, escalou as paredes da pris\u00e3o para conseguir fugir Depois de 14 dias foragido, o brasileiro Danilo Cavalcante foi capturado pela pol\u00edcia da Pensilv\u00e2nia, nos\u00a0Estados Unidos, nesta quarta-feira (13). O homem conseguiu fugir da cadeia onde cumpria uma senten\u00e7a de pris\u00e3o perp\u00e9tua por matar a ex-namorada. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-457","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/457\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}