{"id":436,"date":"2023-09-12T12:36:25","date_gmt":"2023-09-12T12:36:25","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=436"},"modified":"2023-09-12T12:36:25","modified_gmt":"2023-09-12T12:36:25","slug":"jovem-de-17-anos-e-agredida-pelo-companheiro-em-cambira","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/12\/jovem-de-17-anos-e-agredida-pelo-companheiro-em-cambira\/","title":{"rendered":"Jovem de 17 anos \u00e9 agredida pelo companheiro em Cambira"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">V\u00edtima foi agredida com chutes e apert\u00f5es no pesco\u00e7o pelo companheiro de 19 anos ap\u00f3s uma discuss\u00e3o<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"626\" height=\"417\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Segundo-PM-mulher-afirmou-que-estava-com-dores-apo-00791708-0-202309120914-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-437\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Segundo-PM-mulher-afirmou-que-estava-com-dores-apo-00791708-0-202309120914-ScaleDownProportional.webp 626w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Segundo-PM-mulher-afirmou-que-estava-com-dores-apo-00791708-0-202309120914-ScaleDownProportional-600x400.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Segundo-PM-mulher-afirmou-que-estava-com-dores-apo-00791708-0-202309120914-ScaleDownProportional-300x200.webp 300w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/figure>\n\n\n\n<p>Uma jovem de 17 anos foi\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/agressao?d=1\" target=\"_blank\">agredida<\/a>\u00a0com chutes na perna e apert\u00f5es no pesco\u00e7o pelo companheiro, de 19, na noite desta segunda-feira (11) em\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/tags\/cambira?d=1\" target=\"_blank\">Cambia<\/a>, no Vale do Iva\u00ed. O fato aconteceu em uma casa localizada no centro da cidade.<\/p>\n\n\n\n<p>A v\u00edtima chamou a Pol\u00edcia Militar (PM) e relatou que ap\u00f3s uma discuss\u00e3o com o companheiro, o homem empurrou ela na cama e ficou insistindo que queria conversar. No entanto, por diversas vezes a jovem pediu para o homem deixar ela em paz, mas o agressor continuou falando que queria conversar.<\/p>\n\n\n\n<p>Ap\u00f3s isso, o rapaz deu tr\u00eas chutes na perna da v\u00edtima e apertou o pesco\u00e7o dela. Depois da agress\u00e3o o homem pulou a janela e saiu correndo da casa.<\/p>\n\n\n\n<p>Segundo os policiais, quando os agentes chegaram, o suspeito estava na frente da resid\u00eancia. Ele recebeu voz de pris\u00e3o e foi encaminhado para a Delegacia de Pol\u00edcia Civil para que as medidas sejam tomadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtima foi agredida com chutes e apert\u00f5es no pesco\u00e7o pelo companheiro de 19 anos ap\u00f3s uma discuss\u00e3o Uma jovem de 17 anos foi\u00a0agredida\u00a0com chutes na perna e apert\u00f5es no pesco\u00e7o pelo companheiro, de 19, na noite desta segunda-feira (11) em\u00a0Cambia, no Vale do Iva\u00ed. O fato aconteceu em uma casa localizada no centro da cidade. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-436","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=436"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/436\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}